{"id":100854,"date":"2024-12-31T00:44:30","date_gmt":"2024-12-31T00:44:30","guid":{"rendered":"https:\/\/www.scoan.org\/examine-se\/"},"modified":"2025-01-03T00:45:34","modified_gmt":"2025-01-03T00:45:34","slug":"examine-se","status":"publish","type":"post","link":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/","title":{"rendered":"EXAMINE-SE"},"content":{"rendered":"\n<p>\u00c0 medida que o ano chega ao fim, voc\u00ea percebe que \u00e9 crucial examinar a si mesmo? Para aqueles na SCOAN durante o \u00faltimo culto de domingo de 2024, foi um momento de verificar sua posi\u00e7\u00e3o com Deus e com os outros humanos. Essa busca pela alma come\u00e7ou com uma sess\u00e3o de adora\u00e7\u00e3o, durante a qual as pessoas glorificaram a Deus com muitas can\u00e7\u00f5es por Sua miseric\u00f3rdia e gra\u00e7a duradouras. \u201cN\u00f3s Te Damos Gl\u00f3ria e Honra\/Voc\u00ea \u00c9 o Senhor\/Que Seu Nome Seja Glorificado!\u201d eles proclamaram. Reconhecendo o dom\u00ednio de Deus, os congregantes saudaram Yahweh de muitas maneiras e tiveram sucesso em preparar a atmosfera para o Esp\u00edrito Santo.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-683x1024.jpg\" alt=\"O Coral da Scoan cantando louvores e adora&#xE7;&#xE3;o no Culto Dominical da Scoan em 29 de dezembro de 2024\" class=\"wp-image-100576\" style=\"width:678px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-683x1024.jpg 683w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-200x300.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-768x1152.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-1024x1536.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-500x750.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-800x1200.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3.jpg 1080w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-736x1024.jpg\" alt=\"O Coral da Scoan cantando louvores e adora&#xE7;&#xE3;o no Culto Dominical da Scoan em 29 de dezembro de 2024\" class=\"wp-image-100580\" style=\"width:677px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-736x1024.jpg 736w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-216x300.jpg 216w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-768x1068.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-500x695.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-800x1113.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3.jpg 1080w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"418\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-1024x418.jpg\" alt=\"O Coral da Scoan cantando louvores e adora&#xE7;&#xE3;o no Culto Dominical da Scoan em 29 de dezembro de 2024\" class=\"wp-image-100584\" style=\"width:680px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-1024x418.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-300x123.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-768x314.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-500x204.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-800x327.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>Uma vida n\u00e3o examinada \u00e9 uma vida desleixada<\/strong><\/p>\n\n<p>O evangelista Ope ancorou seu serm\u00e3o principalmente em 1 Tim\u00f3teo 4:16 e parcialmente em 2 Cor\u00edntios 13:5 e 1 Cor\u00edntios 11:28. Intitulada \u201cExamine a si mesmo\u201d, a mensagem foi entregue sem rodeios a um p\u00fablico bastante receptivo. Baseando-se em 2 Cor\u00edntios 10:2, o pregador explicou que seu objetivo n\u00e3o era ver as pessoas se compararem com outras ou se medirem por si mesmas. Em vez disso, ele disse, elas deveriam examinar suas a\u00e7\u00f5es \u00e0 luz da Palavra de Deus, conforme instado em 2 Tim\u00f3teo 3:16-17 e Hebreus 4:12. \u201cExaminar a si mesmo diariamente \u00e9 uma coisa boa\u201d, ele declarou.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"745\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-745x1024.jpg\" alt=\"O evangelista pregando o serm&#xE3;o no altar no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100588\" style=\"width:691px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-745x1024.jpg 745w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-218x300.jpg 218w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-768x1056.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-500x688.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-800x1100.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1.jpg 1080w\" sizes=\"auto, (max-width: 745px) 100vw, 745px\" \/><\/figure>\n\n<p>O ministro tamb\u00e9m observou que a maioria dos fracassos tende a ser resultado de ina\u00e7\u00e3o, especialmente de n\u00e3o se controlar \u2014 uma situa\u00e7\u00e3o que frequentemente leva ao arrependimento. \u201cUma vida descontrolada \u00e9 uma vida desleixada\u201d, ele observou, acrescentando que algumas pessoas se deleitam em causar dor aos outros e semear sementes de discurso entre as pessoas. Como tal, ele pediu aos congregantes que notassem que eles podem, de fato, ser a fonte de seus pr\u00f3prios problemas. Uma maneira de ser uma pessoa melhor, ele disse, \u00e9 ser grato sempre, ser um doador e praticar o perd\u00e3o, evitando uma mentalidade de direito.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"714\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-1024x714.jpg\" alt=\"O evangelista pregando o serm&#xE3;o no altar no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100592\" style=\"width:700px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-1024x714.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-300x209.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-768x535.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-500x349.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-800x558.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-697x1024.jpg\" alt=\"O evangelista pregando o serm&#xE3;o no altar no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100596\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-697x1024.jpg 697w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-204x300.jpg 204w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-768x1128.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-1046x1536.jpg 1046w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-500x734.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-800x1175.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1.jpg 1080w\" sizes=\"auto, (max-width: 697px) 100vw, 697px\" \/><\/figure>\n\n<p>Ao concluir o serm\u00e3o, o Evangelista Ope citou 1 Cor\u00edntios 10:12 e G\u00e1latas 6:3 e disse ao povo: \u201cDeus Todo-Poderoso est\u00e1 nos chamando para mudar. Ele est\u00e1 nos chamando para olhar para dentro e corrigir nossos caminhos. Vamos verificar ou examinar a n\u00f3s mesmos para fazer uma mudan\u00e7a, porque se voc\u00ea n\u00e3o mudar, nada mudar\u00e1!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-735x1024.jpg\" alt=\"O evangelista pregando o serm&#xE3;o no altar no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100600\" style=\"width:663px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-735x1024.jpg 735w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-215x300.jpg 215w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-768x1070.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-500x697.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-800x1115.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1.jpg 1080w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"777\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-777x1024.jpg\" alt=\"O evangelista pregando o serm&#xE3;o no altar no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100608\" style=\"width:621px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-777x1024.jpg 777w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-228x300.jpg 228w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-768x1012.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-500x659.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-800x1054.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1.jpg 1080w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><\/figure>\n\n<p><strong>\u201cV\u00e1 para onde voc\u00ea \u00e9 bem-vindo\u201d<\/strong><\/p>\n\n<p>\u201c\u00c9 mais um dia glorioso em Sua presen\u00e7a e viemos dizer: \u2018Obrigado\u2019\u201d, disse a pastora Evelyn Joshua ao se juntar ao povo para a ministra\u00e7\u00e3o da Linha de Ora\u00e7\u00e3o.<\/p>\n\n<p>Dando continuidade ao serm\u00e3o, a pastora Evelyn Joshua falou \u00e0s pessoas sobre o lugar da f\u00e9 e a natureza do Esp\u00edrito Santo. Ela assegurou a eles: \u201cAquele dentro de voc\u00eas \u00e9 maior do que aquele no mundo.\u201d Ela tamb\u00e9m lembrou aos congregantes assim: \u201cSe o Esp\u00edrito Santo fizer morada dentro de voc\u00eas, voc\u00eas ir\u00e3o para um lugar onde Ele \u00e9 honrado, bem-vindo e apreciado, n\u00e3o apenas onde Ele \u00e9 necess\u00e1rio.\u201d<\/p>\n\n<p>Citando Lucas 9:1-5 e Salmo 40:2, a mulher de Deus observou: \u201cHoje, muitos de n\u00f3s nos encontramos onde somos necess\u00e1rios, mas n\u00e3o bem-vindos.\u201d Ela, portanto, encorajou o povo a tomar a decis\u00e3o certa ao abra\u00e7ar Jesus Cristo, que nos ensina o caminho a seguir.<\/p>\n\n<p><strong>Tocado de uma maneira especial<\/strong><\/p>\n\n<p>Na Linha de Ora\u00e7\u00e3o, a Pastora Evelyn Joshua olhou para o C\u00e9u: \u201cPai Senhor, n\u00f3s bendizemos o Teu Santo nome. Jesus Cristo, n\u00f3s Te honramos. Esp\u00edrito Santo, n\u00f3s Te acolhemos. Pai, viemos declarando a Tua soberania. Confessamos que Tu \u00e9s o nosso Deus, que Tu \u00e9s o nosso Criador. Viemos sabendo que Tu \u00e9s o Juiz, confiando na Tua gra\u00e7a e no Teu amor para que n\u00e3o sejamos deixados de fora. Tu \u00e9s a nossa paz; em Ti encontramos alegria e em Ti encontramos a vida eterna.<\/p>\n\n<p>Senhor Deus Todo-Poderoso, pedimos que nos toque hoje de uma forma diferente, de uma forma especial. Toque Seus filhos para que aqueles que est\u00e3o doentes digam que est\u00e3o curados, aqueles que s\u00e3o pobres digam que s\u00e3o aben\u00e7oados, aqueles que s\u00e3o fracos digam que t\u00eam for\u00e7a e aqueles que est\u00e3o perdidos declarem que foram encontrados, em nome de Jesus Cristo.\u201d<\/p>\n\n<p>Com f\u00e9 em seus cora\u00e7\u00f5es, as pessoas vinham com v\u00e1rios problemas, como dificuldade para andar, asma, barriga inchada, h\u00e9rnia, depend\u00eancia de \u00e1lcool, doen\u00e7as de pele, derrame parcial, artrite reumatoide e sangramento nasal. E o poder do Deus vivo curou todos eles!<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-1024x543.jpg\" alt=\"Pastora Evelyn Joshua orando pelo povo no poder do Esp&#xED;rito Santo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100612\" style=\"width:668px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-1024x543.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-300x159.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-768x407.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-500x265.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-800x424.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"851\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-1024x851.jpg\" alt=\"Pastora Evelyn Joshua orando pelo povo no poder do Esp&#xED;rito Santo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100616\" style=\"width:675px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-1024x851.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-300x249.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-768x639.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-500x416.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-800x665.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"483\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-1024x483.jpg\" alt=\"Pastora Evelyn Joshua orando pelo povo no poder do Esp&#xED;rito Santo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100620\" style=\"width:675px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-1024x483.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-300x141.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-768x362.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-500x236.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-800x377.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"609\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-1024x609.jpg\" alt=\"Pastora Evelyn Joshua orando pelo povo no poder do Esp&#xED;rito Santo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100624\" style=\"width:668px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-1024x609.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-300x178.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-768x457.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-500x297.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-800x476.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"631\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-1024x631.jpg\" alt=\"Pastora Evelyn Joshua orando pelo povo no poder do Esp&#xED;rito Santo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100632\" style=\"width:671px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-1024x631.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-300x185.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-768x473.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-500x308.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-800x493.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Outros casos que receberam aten\u00e7\u00e3o inclu\u00edram les\u00e3o no tornozelo, depend\u00eancia de drogas, fratura no ombro, pr\u00f3stata aumentada, transtorno mental, \u00falceras nas pernas, queimaduras de fogo, perda de mem\u00f3ria, hemorroidas, hipertens\u00e3o, dificuldade para respirar e convuls\u00f5es. Conforme as pessoas recebiam do Trono da Gra\u00e7a, elas exclamavam: \u2018Obrigado, Jesus!\u2019\u201d<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"544\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-1024x544.jpg\" alt=\"Pastora Evelyn Joshua orando pelo povo no poder do Esp&#xED;rito Santo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100636\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-1024x544.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-300x159.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-768x408.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-500x266.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-800x425.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"496\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-1024x496.jpg\" alt=\"O evangelista orando pelo povo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100640\" style=\"width:754px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-1024x496.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-300x145.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-768x372.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-500x242.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-800x387.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"466\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-1024x466.jpg\" alt=\"O evangelista orando pelo povo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100644\" style=\"width:751px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-1024x466.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-300x136.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-768x349.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-500x227.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-800x364.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"602\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-1024x602.jpg\" alt=\"O evangelista orando pelo povo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100648\" style=\"width:747px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-1024x602.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-300x176.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-768x452.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-500x294.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-800x470.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"501\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-1024x501.jpg\" alt=\"O evangelista orando pelo povo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100652\" style=\"width:738px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-1024x501.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-300x147.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-768x375.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-500x244.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-800x391.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"787\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-1024x787.jpg\" alt=\"O evangelista orando pelo povo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100656\" style=\"width:730px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-1024x787.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-300x231.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-768x590.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-500x384.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-800x615.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"602\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-1024x602.jpg\" alt=\"O evangelista orando pelo povo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100660\" style=\"width:733px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-1024x602.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-300x176.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-768x452.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-500x294.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-800x470.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-1024x570.jpg\" alt=\"O evangelista orando pelo povo durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100664\" style=\"width:731px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-1024x570.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-300x167.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-768x427.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-500x278.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-800x445.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"922\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-1024x922.jpg\" alt=\" \" class=\"wp-image-100668\" style=\"width:731px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-1024x922.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-300x270.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-768x691.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-500x450.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-800x720.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Mulheres gr\u00e1vidas tamb\u00e9m foram cobertas com o Sangue de Jesus Cristo.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"571\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-1024x571.jpg\" alt=\"Pastora Evelyn Joshua para as mulheres para o parto seguro durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100672\" style=\"width:751px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-1024x571.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-300x167.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-768x428.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-500x279.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-800x446.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-1024x529.jpg\" alt=\"Pastora Evelyn Joshua para as mulheres para o parto seguro durante a se&#xE7;&#xE3;o de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100676\" style=\"width:758px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-1024x529.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-300x155.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-768x397.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-500x258.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-800x413.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-1024x612.jpg\" alt=\"Pastora Evelyn Joshua para as mulheres para um parto seguro durante a se&#xE7;&#xE3;o de fila de ora&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100680\" style=\"width:761px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-1024x612.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-300x179.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-768x459.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-500x299.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-800x478.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Para o restante dos congregantes no audit\u00f3rio, na se\u00e7\u00e3o de excedentes, na Escola Dominical e na se\u00e7\u00e3o de m\u00e3es que amamentam, foi um toque especial de fim de ano apoiado pelo C\u00e9u, enquanto os servos de Deus ministravam com un\u00e7\u00e3o incomum.<\/p>\n\n<p>De fato, pelo fogo do Esp\u00edrito Santo, todo dem\u00f4nio teimoso foi expulso!<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-1024x574.jpg\" alt=\"Pastora Evelyn Joshua impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100684\" style=\"width:773px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-1024x574.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-300x168.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-768x430.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-500x280.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-800x448.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-790x1024.jpg\" alt=\"Pastora Evelyn Joshua impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100688\" style=\"width:774px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-790x1024.jpg 790w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-231x300.jpg 231w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-768x996.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-500x648.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-800x1037.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3.jpg 1080w\" sizes=\"auto, (max-width: 790px) 100vw, 790px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-799x1024.jpg\" alt=\"Pastora Evelyn Joshua impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100692\" style=\"width:781px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-799x1024.jpg 799w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-234x300.jpg 234w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-768x984.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-500x641.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-800x1025.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3.jpg 1080w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"862\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-862x1024.jpg\" alt=\"O evangelista impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100696\" style=\"width:785px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-862x1024.jpg 862w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-253x300.jpg 253w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-768x912.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-500x594.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-800x950.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2.jpg 1080w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-822x1024.jpg\" alt=\"O evangelista impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100700\" style=\"width:776px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-822x1024.jpg 822w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-241x300.jpg 241w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-768x956.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-500x623.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-800x996.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1.jpg 1080w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-778x1024.jpg\" alt=\"O evangelista impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100704\" style=\"width:781px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-778x1024.jpg 778w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-228x300.jpg 228w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-768x1010.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-500x658.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-800x1053.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2.jpg 1080w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"806\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-806x1024.jpg\" alt=\"O evangelista impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100708\" style=\"width:777px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-806x1024.jpg 806w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-236x300.jpg 236w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-768x976.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-500x635.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-800x1016.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2.jpg 1080w\" sizes=\"auto, (max-width: 806px) 100vw, 806px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"867\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-867x1024.jpg\" alt=\"O evangelista impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100802\" style=\"width:776px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-867x1024.jpg 867w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-254x300.jpg 254w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-768x907.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-500x590.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-800x944.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4.jpg 1080w\" sizes=\"auto, (max-width: 867px) 100vw, 867px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-1024x592.jpg\" alt=\"O evangelista impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100806\" style=\"width:780px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-1024x592.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-300x173.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-768x444.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-500x289.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-800x462.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-1024x512.jpg\" alt=\"O evangelista impondo as m&#xE3;os e orando pelas pessoas durante a ministra&#xE7;&#xE3;o no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100811\" style=\"width:780px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-1024x512.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-300x150.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-768x384.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-500x250.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-800x400.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>E o medo deles se tornou f\u00e9!<\/strong><\/p>\n\n<p>\u201cQue a paz de Deus nunca se afaste de seu lar\u201d, orou a pastora Evelyn Joshua no final da sess\u00e3o de louvor. \u201cD\u00eaem gra\u00e7as a Deus\u201d, ela pediu ao povo.<\/p>\n\n<p>Come\u00e7ando a sess\u00e3o de Ora\u00e7\u00e3o em Massa, ela orou: \u201cN\u00f3s ordenamos que toda d\u00favida em voc\u00ea se transforme em f\u00e9 forte, em nome de Jesus. N\u00f3s ordenamos que todo medo dentro e fora de voc\u00ea se transforme em confian\u00e7a tranquila, em nome de Jesus. Todo problema que entrou em sua vida pela iniquidade dos pais \u2013 seja lavado, em nome de Jesus. Esp\u00edrito de malfeitor que enredou sua vida \u2013 n\u00f3s ordenamos que seja lavado, em nome de Jesus! Que haja cura em seu corpo, esp\u00edrito, ossos, rins, espinha, f\u00edgado! Que haja cura em cada \u00f3rg\u00e3o do seu corpo! Seja curado dessa afli\u00e7\u00e3o, doen\u00e7a, enfermidade, em nome de Jesus!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"751\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-751x1024.jpg\" alt=\"Pastora Evelyn Joshua orando pela congrega&#xE7;&#xE3;o e pelos espectadores durante a ora&#xE7;&#xE3;o da massa no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100712\" style=\"width:707px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-751x1024.jpg 751w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-220x300.jpg 220w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-768x1047.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-500x682.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-800x1091.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3.jpg 1080w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/figure>\n\n<p>A mulher de Deus continuou a orar: \u201cTudo o que te causa vergonha e desgra\u00e7a \u2013 ordenamos que v\u00e1 com o ano, em nome de Jesus! Tudo o que te mant\u00e9m estagnado \u2013 ordenamos que v\u00e1, em nome de Jesus Cristo!\u201d<\/p>\n\n<p>Voltando-se para os espectadores em todo o mundo, a pastora Evelyn Joshua orou: \u201cQualquer coisa que esteja entre voc\u00ea e as promessas de Deus para sua vida \u2013 ordenamos que ceda agora mesmo, em nome de Jesus! Todo v\u00e9u maligno de destrui\u00e7\u00e3o, \u00f3dio, estagna\u00e7\u00e3o que esteja entre voc\u00ea e as promessas de Deus para sua vida \u2013 ordenamos que seja quebrado, em nome de Jesus Cristo! Vit\u00f3ria em nossas vidas, em nossas carreiras, em nosso casamento, em nome de Jesus! Avan\u00e7o em suas finan\u00e7as! Liberdade de todo grilh\u00e3o, de toda escravid\u00e3o, de toda limita\u00e7\u00e3o!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"871\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-871x1024.jpg\" alt=\"Pastora Evelyn Joshua orando pela congrega&#xE7;&#xE3;o e pelos espectadores durante a ora&#xE7;&#xE3;o da massa no culto dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100716\" style=\"width:710px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-871x1024.jpg 871w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-255x300.jpg 255w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-768x903.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-500x588.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-800x941.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2.jpg 1080w\" sizes=\"auto, (max-width: 871px) 100vw, 871px\" \/><\/figure>\n\n<p>O evangelista James incentivou o povo a orar: \u201cVoc\u00ea, dem\u00f4nio, em qualquer lugar que voc\u00ea esteja na minha vida, na minha fam\u00edlia \u2013 Fora, em nome de Jesus! Voc\u00ea, esp\u00edrito familiar, voc\u00ea, esp\u00edrito ancestral \u2013 Fora, em nome de Jesus!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-886x1024.jpg\" alt=\"Evangelista orando pela congrega&#xE7;&#xE3;o e pelos espectadores durante a Ora&#xE7;&#xE3;o da Massa no Culto Dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100720\" style=\"width:765px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-886x1024.jpg 886w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-260x300.jpg 260w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-768x887.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-500x578.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-800x924.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/figure>\n\n<p>Em seguida, o evangelista Ope orou: \u201cTodo \u00eddolo familiar operando em sua vida \u2013 Fora!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"923\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-923x1024.jpg\" alt=\"Evangelista orando pela congrega&#xE7;&#xE3;o e pelos espectadores durante a Ora&#xE7;&#xE3;o da Massa no Culto Dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100724\" style=\"width:753px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-923x1024.jpg 923w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-270x300.jpg 270w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-768x852.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-500x555.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-800x887.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 923px) 100vw, 923px\" \/><\/figure>\n\n<p>Assumindo o comando, o Evangelista Joseph orou: \u201cEsses esp\u00edritos que est\u00e3o lhe causando afli\u00e7\u00e3o, causando dor, causando doen\u00e7a em seus \u00f3rg\u00e3os \u2013 Fora, em nome de Jesus! Voc\u00eas envenenam meu cora\u00e7\u00e3o, pulm\u00f5es, rins, ossos \u2013 onde quer que estejam, ou\u00e7am a voz de Deus: Eu ordeno que saiam!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-820x1024.jpg\" alt=\"Evangelista orando pela congrega&#xE7;&#xE3;o e pelos espectadores durante a Ora&#xE7;&#xE3;o da Massa no Culto Dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100728\" style=\"width:763px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-820x1024.jpg 820w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-240x300.jpg 240w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-768x959.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-500x624.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-800x999.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n<p>O evangelista Chisom orou: \u201cVoc\u00ea, dem\u00f4nio, n\u00e3o tem escolha; voc\u00ea deve se submeter! Onde quer que esteja, me segurando em cativeiro, limita\u00e7\u00e3o, decep\u00e7\u00e3o \u2013 eu te ordeno em nome de Jesus: Fora!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"867\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-867x1024.jpg\" alt=\"Evangelista orando pela congrega&#xE7;&#xE3;o e pelos espectadores durante a Ora&#xE7;&#xE3;o da Massa no Culto Dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100732\" style=\"width:761px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-867x1024.jpg 867w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-254x300.jpg 254w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-768x907.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-500x590.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-800x944.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 867px) 100vw, 867px\" \/><\/figure>\n\n<p>Em um v\u00eddeo de ora\u00e7\u00e3o em massa, o profeta TB Joshua declarou: \u201cEu venho contra todo esp\u00edrito que se op\u00f5e a voc\u00eas! Todo esp\u00edrito que questiona seus neg\u00f3cios, carreira, vis\u00e3o, destino \u2013 comece a ceder, em nome de Jesus! Todo esp\u00edrito familiar \u2013 n\u00f3s ordenamos sua exist\u00eancia: Fora! Voc\u00eas, afli\u00e7\u00e3o no sangue, fluidos, rins, f\u00edgado, ossos \u2013 voc\u00eas devem ir, em nome de Jesus!\u201d O homem de Deus instou o povo a decretar: \u201cMinhas finan\u00e7as, meus neg\u00f3cios, minha carreira \u2013 sejam liberados, em nome de Jesus!\u201d<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-1024x683.jpg\" alt=\"Profeta TB Joshua orando pela congrega&#xE7;&#xE3;o e espectadores durante a Ora&#xE7;&#xE3;o em Massa no Culto Dominical de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100736\" style=\"width:726px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-1024x683.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-300x200.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-768x512.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-500x333.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-800x533.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>Testemunhos<\/strong><\/p>\n\n<p><strong>Curado de um derrame paralisante<\/strong><\/p>\n\n<p>Em algum momento de 2002, Blessing sofreu um ataque espiritual que eventualmente levou a um derrame. Ela foi levada a v\u00e1rios lugares para obter ajuda. \u201cEm um ponto, fui transferida para o estado de Ondo\u201d, ela disse em 29 de dezembro de 2024. Sem muita melhora sendo registrada, Blessing retornou a Lagos. \u201cEm 23 de outubro de 2022, meu marido me levou para a SCOAN para orar\u201d, ela lembrou. Mais tarde naquela noite, Blessing teve um encontro em sonho com uma imagem do profeta TB Joshua. \u201cO homem de Deus levantou minha m\u00e3o doente e me declarou curada\u201d, ela disse. Hoje, a boca de Blessing n\u00e3o est\u00e1 mais torcida pelo derrame nem sua m\u00e3o paralisada. \u201cCorra para Deus para sua cura e liberta\u00e7\u00e3o\u201d, ela aconselhou outros.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"596\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-1024x596.jpg\" alt=\"Testemunho 1 Compartilhado no Culto de Domingo de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100780\" style=\"width:764px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-1024x596.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-300x175.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-768x447.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-500x291.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-800x466.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>N\u00e3o mais escravo da dor demon\u00edaca!<\/strong><\/p>\n\n<p>Certa manh\u00e3, cinco anos atr\u00e1s, Helen acordou com uma dor excruciante por todo o corpo. \u201cEu derramei l\u00e1grimas e a dor desapareceu misteriosamente\u201d, ela lembrou em 29 de dezembro de 2024. Dois anos depois, no entanto, a dor voltou com for\u00e7a total. \u201cFui a hospitais diferentes\u201d, ela continuou, \u201ce fiz sess\u00f5es de fisioterapia\u201d. Mais tarde, ela tamb\u00e9m ganhou um espartilho lombar. No entanto, todos esses aux\u00edlios n\u00e3o conseguiram ajud\u00e1-la.<\/p>\n\n<p>\u201c\u00c0s 4 da manh\u00e3 de cada dia eu acordava por causa da dor\u201d, Helen continuou. Mas havia uma dimens\u00e3o espiritual no problema. \u201cEu costumava ver um homem vir at\u00e9 mim no sonho e eu sofria abortos espont\u00e2neos\u201d, ela se abriu. Ao receber a ora\u00e7\u00e3o em 22 de dezembro, Helen viu o poder do Deus vivo surgir atrav\u00e9s dela. \u201cAgora eu posso fazer tudo o que eu n\u00e3o conseguia fazer antes\u201d, ela disse enquanto demonstrava sua liberdade. Ela aconselhou outros a buscarem a ajuda de Deus.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"586\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-1024x586.jpg\" alt=\"Testemunho 2 Compartilhado no Culto de Domingo de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100776\" style=\"width:734px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-1024x586.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-300x172.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-768x439.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-500x286.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-800x458.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>Um artes\u00e3o recupera sua for\u00e7a<\/strong><\/p>\n\n<p>Joseph, um ladrilhador gan\u00eas radicado na Nig\u00e9ria, sentiu de repente uma dor aguda nas costas. &#8220;Eu n\u00e3o conseguia mais me mover, ent\u00e3o um dos meus trabalhadores teve que encontrar um \u00f4nibus para me mover&#8221;, disse ele em 29 de dezembro de 2024. Com seu trabalho suspenso e os medicamentos n\u00e3o fazendo muita diferen\u00e7a, Joseph n\u00e3o teve outra escolha a n\u00e3o ser buscar a interven\u00e7\u00e3o divina. Primeiro, ele ministrou a \u00c1gua Viva em si mesmo, ap\u00f3s o que recuperou as for\u00e7as para andar. Segundo, ele foi at\u00e9 a SCOAN para orar. Ap\u00f3s um toque de um dos evangelistas, a dor nas costas de Joseph desapareceu instantaneamente. Agora ele voltou ao trabalho! &#8220;Se voc\u00ea pudesse acreditar, Deus faria isso por voc\u00ea&#8221;, ele aconselhou.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"541\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-1024x541.jpg\" alt=\"Testemunho 3 Compartilhado no Culto de Domingo de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100748\" style=\"width:765px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-1024x541.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-300x159.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-768x406.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-500x264.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-800x423.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>\u201cSinto uma sensa\u00e7\u00e3o de alegria\u201d, diz homem liberto de esp\u00edritos malignos<\/strong><\/p>\n\n<p>Knowledge, um zimbabuense, nasceu em uma fam\u00edlia de adoradores de \u00eddolos. \u201cMeus pais herdaram os \u00eddolos de seus pr\u00f3prios pais e me disseram que os \u00eddolos eram para nos proteger\u201d, ele disse \u00e0 igreja em 29 de dezembro de 2024. No entanto, os \u00eddolos n\u00e3o trouxeram nada al\u00e9m de infort\u00fanio para toda a fam\u00edlia, trazendo atrasos em todas as \u00e1reas da vida. Ao descobrir a Emmanuel TV, Knowledge decidiu que tinha que ir para a SCOAN. Em 15 de dezembro de 2024, ele recebeu um toque apoiado pelo C\u00e9u. \u201cSenti algo sair do meu corpo e agora sinto uma sensa\u00e7\u00e3o de alegria\u201d, disse ele. Como conselho, ele disse aos congregantes: \u201cJesus Cristo \u00e9 a \u00fanica solu\u00e7\u00e3o para os nossos problemas\u201d.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"646\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-1024x646.jpg\" alt=\"Testemunho 4 Compartilhado no Culto de Domingo de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100752\" style=\"width:740px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-1024x646.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-300x189.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-768x484.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-500x315.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-800x504.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>Elisa se liberta da dor!<\/strong><\/p>\n\n<p>Em 22 de dezembro de 2024, Elisa de Angola estava na SCOAN para ora\u00e7\u00e3o. No instante em que a ora\u00e7\u00e3o penetrou, o corpo de Elisa come\u00e7ou a vibrar incontrolavelmente, fazendo com que ela acabasse no ch\u00e3o enquanto a pastora Evelyn Joshua se posicionava na autoridade do crente. \u201cPor 15 anos, sofri dores severas de osteoporose\u201d, ela disse, \u201ce fui a diferentes m\u00e9dicos para obter ajuda\u201d. Com a condi\u00e7\u00e3o afetando sua capacidade de andar, Elisa quase aceitou o veredito dos m\u00e9dicos de que ela n\u00e3o poderia ser curada permanentemente. No entanto, ela deu o passo da f\u00e9 e buscou ajuda divina. \u201cAp\u00f3s a ora\u00e7\u00e3o, recebi minha cura e pude me mover livremente e dormir em paz novamente\u201d, ela disse. \u201cBusque a ajuda de Deus, ela aconselhou os outros.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"927\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-1024x927.jpg\" alt=\"Testemunho 5 Compartilhado no Culto de Domingo de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100756\" style=\"width:770px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-1024x927.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-300x272.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-768x695.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-500x453.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-800x724.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><strong>O fim de 16 anos de enurese noturna!<\/strong><\/p>\n\n<p>\u201cEu fazia xixi na cama at\u00e9 os 16 anos\u201d, confessou Gifty, de 18 anos, em 29 de dezembro de 2024. Por causa desse problema, ela n\u00e3o conseguia frequentar o internato nem se misturar com colegas em seus dias de escola prim\u00e1ria. Quando seu \u201csegredinho\u201d finalmente vazou no ensino m\u00e9dio, Gifty se tornou alvo de piadas. \u201cAt\u00e9 em casa, meus irm\u00e3os \u00e0s vezes zombavam de mim\u201d, disse ela. Como solu\u00e7\u00e3o, Gifty come\u00e7ou a usar fraldas para adultos. \u201cEu me escondia dos meus colegas de dormit\u00f3rio no ensino m\u00e9dio quando usava ou descartava as fraldas.<\/p>\n\n<p>Para a gl\u00f3ria de Deus, a m\u00e3e de Gifty visitou a SCOAN e ganhou de presente o Adesivo de Un\u00e7\u00e3o e a \u00c1gua de Un\u00e7\u00e3o. \u201cMinistrei a \u00e1gua antes de ir para a cama e descobri que n\u00e3o tinha molhado minha cama naquela noite\u201d, ela testemunhou. Gifty repetiu a a\u00e7\u00e3o. \u201cLiguei para minha m\u00e3e de manh\u00e3 porque agora tinha certeza do milagre\u201d, ela disse com um sorriso c\u00famplice. Por mais de dois anos, os len\u00e7\u00f3is de Gifty permaneceram secos! Ela e sua m\u00e3e glorificaram o Senhor pela liberta\u00e7\u00e3o, incitando outros a confiarem no Todo-Poderoso.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"773\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-773x1024.jpg\" alt=\"Testemunho 6 Compartilhado no Culto de Domingo de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100768\" style=\"width:738px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-773x1024.jpg 773w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-227x300.jpg 227w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-768x1017.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-500x662.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-800x1059.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6.jpg 1090w\" sizes=\"auto, (max-width: 773px) 100vw, 773px\" \/><\/figure>\n\n<p><strong>O v\u00edcio em arrancar cabelos acaba em elogio!<\/strong><\/p>\n\n<p>Em 28 de julho de 2023, Hope estava no The SCOAN Living Water Service. Ela estava sofrendo com o v\u00edcio de arrancar os cabelos da parte de tr\u00e1s da cabe\u00e7a. &#8220;Eu simplesmente n\u00e3o conseguia parar e as pessoas podiam facilmente me identificar por causa disso&#8221;, disse Hope em 29 de dezembro de 2024. Os pais de Hope fizeram muitas coisas para ajud\u00e1-la a parar com o h\u00e1bito, mas falharam espetacularmente. No entanto, no Culto da \u00c1gua Viva, Hope orou fervorosamente e o Senhor ouviu seu clamor.<\/p>\n\n<p>\u201cJ\u00e1 se passaram duas semanas depois de orar no Altar da SCOAN que percebi que n\u00e3o puxava mais meu cabelo\u201d, Hope lembrou, seu rosto brilhando com um sorriso cheio de dentes. Ela aconselhou outros a buscarem a ajuda do Senhor. \u201cO que quer que voc\u00ea esteja buscando hoje, o Senhor far\u00e1 por voc\u00ea\u201d, ela assegurou a eles. Sua m\u00e3e, Stella, disse: \u201cOro para que o milagre seja permanente em sua vida, em nome de Jesus\u201d.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-1024x826.jpg\" alt=\"Testemunho 8 Compartilhado no Culto de Domingo de Scoan em 29 de dezembro de 2024\" class=\"wp-image-100764\" style=\"width:728px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-1024x826.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-300x242.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-768x619.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-500x403.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-800x645.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 medida que o ano chega ao fim, voc\u00ea percebe que \u00e9 crucial examinar a si mesmo? Para aqueles na SCOAN durante o \u00faltimo culto de domingo de 2024, foi um momento de verificar sua posi\u00e7\u00e3o com Deus e com os outros humanos. Essa busca pela alma come\u00e7ou com uma sess\u00e3o de adora\u00e7\u00e3o, durante a [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":100800,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[1971],"tags":[1974,1965,1963,1966,1964,2052,1969,1975,1967,2053,1970],"class_list":["post-100854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culto-dominical-da-scoan","tag-coral","tag-cura","tag-emmanuel-tv-pt-pt","tag-libertacao","tag-pastora-evelyn-joshua","tag-scoan-pt-pt","tag-sermao","tag-sinagoga-igreja-de-todas-as-nacoes-pt-pt","tag-sinagoga-igreja-de-todas-as-nacoes","tag-tb-joshua-pt-pt","tag-testemunho"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXAMINE-SE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua<\/title>\n<meta name=\"description\" content=\"EXAMINE-SE: Ao longo dos anos, convidamos os membros da nossa fam\u00edlia da igreja a refletir sobre t\u00f3picos como o que Deus est\u00e1 ensinando...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scoan.org\/pt-pt\/examine-se\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXAMINE-SE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"og:description\" content=\"EXAMINE-SE: Ao longo dos anos, convidamos os membros da nossa fam\u00edlia da igreja a refletir sobre t\u00f3picos como o que Deus est\u00e1 ensinando...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scoan.org\/pt-pt\/examine-se\/\" \/>\n<meta property=\"og:site_name\" content=\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tbjministries\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-31T00:44:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-03T00:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"v3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:site\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"v3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/\"},\"author\":{\"name\":\"v3\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/9407e2a1d1e2a15ac63326fe09b7d3b6\"},\"headline\":\"EXAMINE-SE\",\"datePublished\":\"2024-12-31T00:44:30+00:00\",\"dateModified\":\"2025-01-03T00:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/\"},\"wordCount\":2536,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"keywords\":[\"Coral\",\"Cura\",\"Emmanuel TV\",\"Liberta\u00e7\u00e3o\",\"Pastora Evelyn Joshua\",\"SCOAN\",\"Serm\u00e3o\",\"sinagoga igreja de todas as na\u00e7\u00f5es\",\"Sinagoga Igreja de Todas as Na\u00e7\u00f5es\",\"TB Joshua\",\"Testemunho\"],\"articleSection\":[\"Culto Dominical da SCOAN\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/\",\"name\":\"EXAMINE-SE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"datePublished\":\"2024-12-31T00:44:30+00:00\",\"dateModified\":\"2025-01-03T00:45:34+00:00\",\"description\":\"EXAMINE-SE: Ao longo dos anos, convidamos os membros da nossa fam\u00edlia da igreja a refletir sobre t\u00f3picos como o que Deus est\u00e1 ensinando...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"width\":1080,\"height\":704,\"caption\":\"Prophet TB Joshua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/examine-se\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXAMINE-SE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"description\":\"Founded by Prophet TB Joshua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#organization\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"width\":186,\"height\":85,\"caption\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tbjministries\",\"https:\\\/\\\/x.com\\\/SCOANTBJoshua\",\"https:\\\/\\\/www.instagram.com\\\/tbjoshua\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/9407e2a1d1e2a15ac63326fe09b7d3b6\",\"name\":\"v3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g\",\"caption\":\"v3\"},\"url\":\"https:\\\/\\\/www.scoan.org\\\/pt-pt\\\/author\\\/v3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXAMINE-SE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"EXAMINE-SE: Ao longo dos anos, convidamos os membros da nossa fam\u00edlia da igreja a refletir sobre t\u00f3picos como o que Deus est\u00e1 ensinando...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/","og_locale":"pt_PT","og_type":"article","og_title":"EXAMINE-SE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","og_description":"EXAMINE-SE: Ao longo dos anos, convidamos os membros da nossa fam\u00edlia da igreja a refletir sobre t\u00f3picos como o que Deus est\u00e1 ensinando...","og_url":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/","og_site_name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","article_publisher":"https:\/\/www.facebook.com\/tbjministries","article_published_time":"2024-12-31T00:44:30+00:00","article_modified_time":"2025-01-03T00:45:34+00:00","og_image":[{"width":1080,"height":704,"url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","type":"image\/jpeg"}],"author":"v3","twitter_card":"summary_large_image","twitter_creator":"@SCOANTBJoshua","twitter_site":"@SCOANTBJoshua","twitter_misc":{"Escrito por":"v3","Tempo estimado de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/#article","isPartOf":{"@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/"},"author":{"name":"v3","@id":"https:\/\/www.scoan.org\/pt-pt\/#\/schema\/person\/9407e2a1d1e2a15ac63326fe09b7d3b6"},"headline":"EXAMINE-SE","datePublished":"2024-12-31T00:44:30+00:00","dateModified":"2025-01-03T00:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/"},"wordCount":2536,"commentCount":0,"publisher":{"@id":"https:\/\/www.scoan.org\/pt-pt\/#organization"},"image":{"@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","keywords":["Coral","Cura","Emmanuel TV","Liberta\u00e7\u00e3o","Pastora Evelyn Joshua","SCOAN","Serm\u00e3o","sinagoga igreja de todas as na\u00e7\u00f5es","Sinagoga Igreja de Todas as Na\u00e7\u00f5es","TB Joshua","Testemunho"],"articleSection":["Culto Dominical da SCOAN"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scoan.org\/pt-pt\/examine-se\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/","url":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/","name":"EXAMINE-SE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","isPartOf":{"@id":"https:\/\/www.scoan.org\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/#primaryimage"},"image":{"@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","datePublished":"2024-12-31T00:44:30+00:00","dateModified":"2025-01-03T00:45:34+00:00","description":"EXAMINE-SE: Ao longo dos anos, convidamos os membros da nossa fam\u00edlia da igreja a refletir sobre t\u00f3picos como o que Deus est\u00e1 ensinando...","breadcrumb":{"@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scoan.org\/pt-pt\/examine-se\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/#primaryimage","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","width":1080,"height":704,"caption":"Prophet TB Joshua"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scoan.org\/pt-pt\/examine-se\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scoan.org\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"EXAMINE-SE"}]},{"@type":"WebSite","@id":"https:\/\/www.scoan.org\/pt-pt\/#website","url":"https:\/\/www.scoan.org\/pt-pt\/","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"Founded by Prophet TB Joshua","publisher":{"@id":"https:\/\/www.scoan.org\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scoan.org\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.scoan.org\/pt-pt\/#organization","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","url":"https:\/\/www.scoan.org\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.scoan.org\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","width":186,"height":85,"caption":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua"},"image":{"@id":"https:\/\/www.scoan.org\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tbjministries","https:\/\/x.com\/SCOANTBJoshua","https:\/\/www.instagram.com\/tbjoshua"]},{"@type":"Person","@id":"https:\/\/www.scoan.org\/pt-pt\/#\/schema\/person\/9407e2a1d1e2a15ac63326fe09b7d3b6","name":"v3","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g","caption":"v3"},"url":"https:\/\/www.scoan.org\/pt-pt\/author\/v3\/"}]}},"_links":{"self":[{"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/posts\/100854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=100854"}],"version-history":[{"count":1,"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/posts\/100854\/revisions"}],"predecessor-version":[{"id":100855,"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/posts\/100854\/revisions\/100855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/media\/100800"}],"wp:attachment":[{"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=100854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=100854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scoan.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=100854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}