{"id":3197,"date":"2016-11-05T12:25:31","date_gmt":"2016-11-05T12:25:31","guid":{"rendered":"https:\/\/tbjoshuaes.wordpress.com\/?p=3197"},"modified":"2016-11-05T12:25:31","modified_gmt":"2016-11-05T12:25:31","slug":"una-cita-con-dios","status":"publish","type":"post","link":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/","title":{"rendered":"UNA CITA CON DIOS"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_3221\" aria-describedby=\"caption-attachment-3221\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3221\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji1.jpg\" alt=\"EVANGELISTA BOLAJI\" width=\"300\" height=\"205\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji1.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji1-200x137.jpg 200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-3221\" class=\"wp-caption-text\">EVANGELISTA BOLAJI<\/figcaption><\/figure>\n<p>Su mensaje se centr\u00f3 en la vida de los cristianos, que desde los tiempos de Abraham, nunca ha sido un camino de rosas. La evangelista explic\u00f3 que, a pesar de que como cristianos nuestras expectativas son siempre muy elevadas, no debemos perder la fe ni el valor cuando nos tropezamos con el muro de la incertidumbre, o con la pruebas y tentaciones que la vida pone en nuestro camino: <em>\u00ab<strong>Incluso el plan de futuro m\u00e1s cuidadosamente trazado puede tropezarse con alg\u00fan problema que lo haga parecer inexistente<\/strong>\u00bb.<\/em><\/p>\n<p style=\"text-align:left\">Advirti\u00f3 de la necesidad de no entrar en un estado de negaci\u00f3n del amor de Dios cuando tengamos que enfrentarnos a una prueba que ponga en jaque nuestra fe: <em>\u00ab<strong>Dios siempre est\u00e1 dispuesto a responder a nuestras oraciones; \u00c9l siempre nos responde, pero no somos capaces de escuchar sus palabras por nuestras limitaciones en el \u00e1mbito de la fe<\/strong>\u00bb. <\/em>Tras hacer varias analog\u00edas b\u00edblicas, la evangelista record\u00f3 que Dios no comete errores en Su gesti\u00f3n del tiempo porque lo sabe todo, y Su tiempo tiene una medida distinta a la nuestra. Utilizando como ejemplo la historia de Pedro y su fracaso en la pesca, explic\u00f3 a la congregaci\u00f3n que un encuentro con Jes\u00fas transformar\u00e1 su desilusi\u00f3n en ilusi\u00f3n, igual que le ocurri\u00f3 a Pedro: un encuentro con el Maestro y sus redes se llenaron de peces primero y de hombres, despu\u00e9s.<\/p>\n<p style=\"text-align:center\"><strong><u>TESTIMONIOS<\/u><\/strong><\/p>\n<p style=\"text-align:center\"><strong>ALCOHOLISMO Y TABAQUISMO ABOLIDOS GRACIAS AL AGUA<\/strong><\/p>\n<p>Titilola Labode hab\u00eda sido enviada a Inglaterra para terminar su educaci\u00f3n universitaria, pero algo la desvi\u00f3 de su prop\u00f3sito, y ese algo fue el tabaquismo y el alcohol. Cada d\u00eda consum\u00eda al menos veinte cigarrillos y una generosa cantidad de vino, lo que pronto empez\u00f3 a apurar sus reservas de dinero. Para subsanarlo acept\u00f3 un trabajo a tiempo parcial, algo que iba contra los deseos de sus padres, y precisamente como un gesto de amor paternal, su padre decidi\u00f3 darle una tarjeta de cr\u00e9dito, creyendo que su hija se lo merec\u00eda y sin imaginarse que su dinero acabar\u00eda yendo al pozo de sus adicciones. Pero para Titola no hab\u00eda marcha atr\u00e1s, adem\u00e1s teniendo en cuenta que ten\u00eda amigos que pensaban como ella y con los que compart\u00eda el mismo estilo de vida destructivo.<\/p>\n<figure id=\"attachment_3199\" aria-describedby=\"caption-attachment-3199\" style=\"width: 333px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/25.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3199\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/25.jpg\" alt=\"2\" width=\"333\" height=\"270\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/25.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/25-200x161.jpg 200w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/><\/a><figcaption id=\"caption-attachment-3199\" class=\"wp-caption-text\">LA SRITA. TITILOLA LABOED, LIBRE DEL TABAQUISMO Y ALCOHOLISMO<\/figcaption><\/figure>\n<p>Una vez terminados sus estudios en Inglaterra, sus padres le pidieron que volviera a Zimbabwe, pero ni de vuelta en su tierra dej\u00f3 de beber. A veces llegaba incluso a emborracharse y a vomitar despu\u00e9s delante de todo el mundo. En una ocasi\u00f3n, lleg\u00f3 a gatas a casa de sus padres, acompa\u00f1ada de varios perros. Seg\u00fan relat\u00f3 ella misma, aquella \u00e9poca en la que esos h\u00e1bitos dominaban su vida, sol\u00eda tener muchas pesadillas: so\u00f1aba con serpientes, escorpiones y toda clase de animales venenosos. Tambi\u00e9n so\u00f1aba que manten\u00eda relaciones sexuales con personas desconocidas, pero sobre todo su salud estaba quedando destrozada por el abuso del alcohol y del tabaco.<\/p>\n<p>Su madre, una prominente parlamentaria de Zimbabwe, ten\u00eda grandes planes para su hija y no estaba dispuesta a cruzarse de brazos mientras los enga\u00f1osos deseos del mundo segu\u00edan creciendo como la mala hierba en la vida de Titiola, y lleg\u00f3 a la conclusi\u00f3n de que lo mejor que pod\u00eda hacer por ella era llevarla a La SCOAN para que la liberaran, consciente de que detener esos perniciosos h\u00e1bitos escapaba a la capacidad humana.<\/p>\n<p>De modo que llev\u00f3 a su hija a La SCOAN, donde el profeta T.B. Joshua or\u00f3 por ella y donde fue liberada de un modo inmediato y casi sin esfuerzo, una prueba m\u00e1s del ilimitado poder de Dios.<\/p>\n<p>Titiola describi\u00f3 m\u00e1s tarde la experiencia vivida, y la record\u00f3 como una especie de corriente el\u00e9ctrica que le recorri\u00f3 el cuerpo cuando el hombre de Dios la se\u00f1al\u00f3: <em>\u00abAun sin haberme tocado, ca\u00ed al suelo, convencida de que alguien me hab\u00eda empujado desde atr\u00e1s, pero cuando vi el v\u00eddeo, comprob\u00e9 que no hab\u00eda nadie\u00bb.<\/em><\/p>\n<p>De nuevo en La SCOAN para compartir su testimonios, acompa\u00f1ada por su madre, Titiola refiri\u00f3 a la congregaci\u00f3n c\u00f3mo hab\u00eda mejorado su vida tras ser liberada. Al parecer, poco despu\u00e9s, so\u00f1\u00f3 con que quer\u00eda fumar un cigarrillo, pero el Profeta T.B. Joshua se lo quitaba y lo destru\u00eda; al despertar, el deseo de fumar y beber la hab\u00eda abandonado. Su madre recalc\u00f3 a los padres que prestasen m\u00e1s atenci\u00f3n a las necesidades espirituales de sus hijos y no solo a sus necesidades materiales, y Titiola aconsej\u00f3 a la juventud que se rodeara de personas creyentes en Dios, que estudiasen la Biblia y que escucharan a sus padres.<\/p>\n<p style=\"text-align:center\"><strong>C\u00d3MO ESCAPAR A UNA HUMILLACI\u00d3N DE ALCANCE INTERNACIONAL Y C\u00d3MO CONSEGUIR UN VISADO GRACIAS A UNA PROFEC\u00cdA<\/strong><\/p>\n<figure id=\"attachment_3200\" aria-describedby=\"caption-attachment-3200\" style=\"width: 337px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/35-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3200\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/35-1.jpg\" alt=\"3\" width=\"337\" height=\"213\" \/><\/a><figcaption id=\"caption-attachment-3200\" class=\"wp-caption-text\">EL SE\u00d1OR Y LA SE\u00d1ORA CON SUS VISADOS<\/figcaption><\/figure>\n<p>Joseph Imarhiagbe estaba intentando obtener el permiso de residencia en el Reino Unido, y fue en ese transcurso cuando comenz\u00f3 a relacionarse con mala gente, empujado por la ambici\u00f3n malsana de hacerse rico r\u00e1pidamente y a toda costa, pero se llev\u00f3 una grand\u00edsima desilusi\u00f3n cuando acab\u00f3 siendo detenido y deportado por estar en el pa\u00eds sin el necesario permiso. Enfrentado de nuevo con la dura realidad de la vida en Nigeria, Joseph se dio cuenta de que tendr\u00edan que pasar al menos diez a\u00f1os para poder volver a solicitar el visado de entrada en el pa\u00eds. La esperanza de lograr una vida mejor para su familia en el Reino Unido se hab\u00eda desvanecido\u2026 pero solo hasta que se tropez\u00f3 con <em>Emmanuel TV<\/em> v\u00eda YouTube.<\/p>\n<p>Un amigo de la familia que viv\u00eda en Francia lo anim\u00f3 a visita la <em>Arena de la Libertad<\/em>, donde la palabra de Dios se manifiesta con m\u00e1s fuerza que las palabras. Estuvo all\u00ed en abril de 2016, y fue all\u00ed donde se encontr\u00f3 consigo mismo a trav\u00e9s de la mirada prof\u00e9tica de Dios encarnada en el profeta T.B. Joshua. El hombre de Dios revel\u00f3 muchas cosas sobre \u00e9l, incluyendo la cita inminente que ten\u00eda en la embajada del Reino Unido. Bast\u00f3 el roce de la mano del Profeta bendecida por Dios para que la fuerza del cielo lo arrojase al suelo.<\/p>\n<p>La profec\u00eda se confirm\u00f3 dos semanas despu\u00e9s de haber estado en La SCOAN: a Joseph le fue concedido un Permiso Europeo de Residencia Familiar que le permitir\u00eda volver al Reino Unido.<\/p>\n<p>Volv\u00eda de viaje a Inglaterra cuando fue detenido por equivocaci\u00f3n en el aeropuerto de Heathrow, en Londres, acusado de viajar con un pasaporte que no era el suyo. Mientras le interrogaba uno de los agentes de Fronteras, Joseph ministr\u00f3 el <em>Agua de la Ma\u00f1ana<\/em> para pedir la intervenci\u00f3n de Dios, y diez minutos m\u00e1s tarde, los oficiales de fronteras se disculpaban con \u00e9l y le permit\u00edan entrar en el pa\u00eds.<\/p>\n<p>Joseph Imarhiagbe quiso compartir su experiencia con la congregaci\u00f3n en compa\u00f1\u00eda de su mujer y declar\u00f3 que Jes\u00fas hab\u00eda tomado las riendas de su vida. Seg\u00fan \u00e9l, la tranquilidad de esp\u00edritu y el progreso que ha experimentado su vida no se parecen en nada a la angustia y la frustraci\u00f3n que sinti\u00f3 con la deportaci\u00f3n.<\/p>\n<p>\u00ab<em>No acudan a los amigos, sino a Jes\u00fas\u00bb<\/em>, aconsejo a los congregantes y a todos los televidentes del mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Su mensaje se centr\u00f3 en la vida de los cristianos, que desde los tiempos de Abraham, nunca ha sido un camino de rosas. La evangelista explic\u00f3 que, a pesar de que como cristianos nuestras expectativas son siempre muy elevadas, no debemos perder la fe ni el valor cuando nos tropezamos con el muro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[3,1],"tags":[1567,1568,1569,1418,1511,1570,1571,825,1572,987,1573,1154,1067,1236,1574,1575],"class_list":["post-3197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","category-uncategorized","tag-alcoholismo-y-tabaquismo","tag-ambito-de-la-fe","tag-deportacion","tag-dios","tag-el-agua-de-la-manana","tag-escorpiones","tag-humillacion","tag-jesus","tag-la-pruebas-y-tentaciones","tag-la-scoan","tag-permiso-europeo","tag-profecia","tag-profeta-t-b-joshua","tag-reino-unido","tag-sonaba-con-serpientes","tag-visado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNA CITA CON DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNA CITA CON DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Su mensaje se centr\u00f3 en la vida de los cristianos, que desde los tiempos de Abraham, nunca ha sido un camino de rosas. La evangelista explic\u00f3 que, a pesar de que como cristianos nuestras expectativas son siempre muy elevadas, no debemos perder la fe ni el valor cuando nos tropezamos con el muro de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tbjministries\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-05T12:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"205\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SCOAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:site\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SCOAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/\"},\"author\":{\"name\":\"SCOAN\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/60e4166936306ab3c7ff663fa3ce7658\"},\"headline\":\"UNA CITA CON DIOS\",\"datePublished\":\"2016-11-05T12:25:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/\"},\"wordCount\":1311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/11\\\/evangelist-bolaji.jpg\",\"keywords\":[\"ALCOHOLISMO Y TABAQUISMO\",\"\u00e1mbito de la fe\",\"deportaci\u00f3n\",\"dios\",\"el Agua de la Ma\u00f1ana\",\"escorpiones\",\"HUMILLACI\u00d3N\",\"Jesus\",\"la pruebas y tentaciones\",\"La SCOAN\",\"Permiso Europeo\",\"profecia\",\"PROFETA T.B. JOSHUA\",\"REINO UNIDO\",\"so\u00f1aba con serpientes\",\"VISADO\"],\"articleSection\":[\"Sin categorizar\",\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/\",\"name\":\"UNA CITA CON DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/11\\\/evangelist-bolaji.jpg\",\"datePublished\":\"2016-11-05T12:25:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/11\\\/evangelist-bolaji.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/11\\\/evangelist-bolaji.jpg\",\"width\":300,\"height\":205},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/una-cita-con-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNA CITA CON DIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"description\":\"Founded by Prophet TB Joshua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"width\":186,\"height\":85,\"caption\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tbjministries\",\"https:\\\/\\\/x.com\\\/SCOANTBJoshua\",\"https:\\\/\\\/www.instagram.com\\\/tbjoshua\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/60e4166936306ab3c7ff663fa3ce7658\",\"name\":\"SCOAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"caption\":\"SCOAN\"},\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/author\\\/ilyap51\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNA CITA CON DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/","og_locale":"es_ES","og_type":"article","og_title":"UNA CITA CON DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","og_description":"&nbsp; Su mensaje se centr\u00f3 en la vida de los cristianos, que desde los tiempos de Abraham, nunca ha sido un camino de rosas. La evangelista explic\u00f3 que, a pesar de que como cristianos nuestras expectativas son siempre muy elevadas, no debemos perder la fe ni el valor cuando nos tropezamos con el muro de [&hellip;]","og_url":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/","og_site_name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","article_publisher":"https:\/\/www.facebook.com\/tbjministries","article_published_time":"2016-11-05T12:25:31+00:00","og_image":[{"width":300,"height":205,"url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji.jpg","type":"image\/jpeg"}],"author":"SCOAN","twitter_card":"summary_large_image","twitter_creator":"@SCOANTBJoshua","twitter_site":"@SCOANTBJoshua","twitter_misc":{"Escrito por":"SCOAN","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#article","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/"},"author":{"name":"SCOAN","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/60e4166936306ab3c7ff663fa3ce7658"},"headline":"UNA CITA CON DIOS","datePublished":"2016-11-05T12:25:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/"},"wordCount":1311,"commentCount":0,"publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"image":{"@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji.jpg","keywords":["ALCOHOLISMO Y TABAQUISMO","\u00e1mbito de la fe","deportaci\u00f3n","dios","el Agua de la Ma\u00f1ana","escorpiones","HUMILLACI\u00d3N","Jesus","la pruebas y tentaciones","La SCOAN","Permiso Europeo","profecia","PROFETA T.B. JOSHUA","REINO UNIDO","so\u00f1aba con serpientes","VISADO"],"articleSection":["Sin categorizar","Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/","url":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/","name":"UNA CITA CON DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#primaryimage"},"image":{"@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji.jpg","datePublished":"2016-11-05T12:25:31+00:00","breadcrumb":{"@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scoan.org\/es\/una-cita-con-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#primaryimage","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji.jpg","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/11\/evangelist-bolaji.jpg","width":300,"height":205},{"@type":"BreadcrumbList","@id":"https:\/\/www.scoan.org\/es\/una-cita-con-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scoan.org\/es\/"},{"@type":"ListItem","position":2,"name":"UNA CITA CON DIOS"}]},{"@type":"WebSite","@id":"https:\/\/www.scoan.org\/es\/#website","url":"https:\/\/www.scoan.org\/es\/","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"Founded by Prophet TB Joshua","publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scoan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scoan.org\/es\/#organization","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","url":"https:\/\/www.scoan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","width":186,"height":85,"caption":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua"},"image":{"@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tbjministries","https:\/\/x.com\/SCOANTBJoshua","https:\/\/www.instagram.com\/tbjoshua"]},{"@type":"Person","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/60e4166936306ab3c7ff663fa3ce7658","name":"SCOAN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","caption":"SCOAN"},"url":"https:\/\/www.scoan.org\/es\/author\/ilyap51\/"}]}},"_links":{"self":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/3197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/comments?post=3197"}],"version-history":[{"count":0,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/3197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media\/3198"}],"wp:attachment":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media?parent=3197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/categories?post=3197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/tags?post=3197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}