{"id":2586,"date":"2016-06-21T13:36:07","date_gmt":"2016-06-21T13:36:07","guid":{"rendered":"https:\/\/tbjoshuaes.wordpress.com\/?p=2586"},"modified":"2018-09-28T14:50:52","modified_gmt":"2018-09-28T14:50:52","slug":"un-cumpleanos-dedicado-a-bendecir-a-los-enfermos","status":"publish","type":"post","link":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/","title":{"rendered":"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_2587\" aria-describedby=\"caption-attachment-2587\" style=\"width: 502px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2587\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg?w=300\" alt=\"EL PROFETA T.B. JOSHUA\" width=\"502\" height=\"303\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1-300x180.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1-200x120.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1-400x240.jpg 400w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/a><figcaption id=\"caption-attachment-2587\" class=\"wp-caption-text\">EL PROFETA T.B. JOSHUA<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El Profeta T.B. Joshua celebr\u00f3 su cincuenta y tres cumplea\u00f1os con un explosivo Servicio Dominical en el que un aut\u00e9ntico aluvi\u00f3n de testimonios y maravillas llenaron la pantalla de <em>Emmanuel TV<\/em>. El d\u00eda anterior, s\u00e1bado, Dios hab\u00eda manifestado su poder con los enfermos que abarrotaban las instalaciones de La SCOAN, y que aguardaban su sanidad como regalo especial del cielo para el cumplea\u00f1os del Profeta. Ante la mirada atenta del mundo a trav\u00e9s de <em>Emmanuel TV<\/em>, las cadenas de la esclavitud quedaron rotas y los cautivos fueron liberados de distintas aflicciones.<\/p>\n<p style=\"text-align: justify;\">Aquellos que hab\u00edan recibido su sanidad prestaron testimonio durante el Servicio Dominical en vivo del 12 de junio de 2016, pero el hombre de Dios no se conform\u00f3 con eso, sino que continu\u00f3 con la ceremonia de la Oraci\u00f3n en la que muchos oprimidos quedaron libres cuando se manifestaron en ellos presencias malignas que expulsaron de su cuerpo en forma de v\u00f3mitos de sustancias venenosas. Quienes lo estaban viendo y oraban al lado del hombre de Dios desde sus hogares, tambi\u00e9n recibieron parte de las bendiciones y la gracia de Dios. Ni siquiera los pa\u00edses quedaron fuera de esta alegr\u00eda, ya que sus asuntos fueron puestos en manos de Dios a trav\u00e9s del Profeta T.B. Joshua.<\/p>\n<p style=\"text-align: justify;\">Dirigi\u00e9ndose a la congregaci\u00f3n en el Servicio especial del d\u00eda de su cumplea\u00f1os, el hombre de Dios dijo: <strong><em>el cumplea\u00f1os debe dedicarse a bendecir a los enfermos, a liberar a aquellos que lo necesitan. <\/em><\/strong>Un poco m\u00e1s adelante, el hombre de Dios se identific\u00f3 con los presentes y los telespectadores del mundo entero en el \u00e1mbito de la realidad socio econ\u00f3mica y la necesidad de perseverar en la oraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Hay pobreza y enfermedad en el mundo entero. Dios prometi\u00f3 enviarnos una poderosa bendici\u00f3n con la que se ocupar\u00eda de todo ello. Mi pueblo necesita ser libre y gozar de buena salud, y para disfrutar de ambas cosas hace falta una poderosa bendici\u00f3n que separe el trigo de la paja en cada situaci\u00f3n que te aqueja. Llevamos desde esta ma\u00f1ana oyendo testimonios y as\u00ed seguiremos. Ahora te toca a ti.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Para concluir, el profeta T.B. Joshua invoc\u00f3 la presencia del Esp\u00edritu Santo en aquel servicio: <strong><em>D\u00e9mosle la bienvenida al Esp\u00edritu Santo. Toma m\u00e1s de nosotros, Se\u00f1or, y danos m\u00e1s de ti: m\u00e1s pureza, m\u00e1s integridad, m\u00e1s lealtad, m\u00e1s amabilidad. Queremos tu declaraci\u00f3n. Queremos tu confirmaci\u00f3n. \u00a1Gracias, Se\u00f1or!<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>TESTIMONIOS<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>LA DEPRESI\u00d3N ESTABA ALL\u00cd PARA MATAR, ROBAR Y DESTRUIR, PERO JES\u00daS DIJO \u00a1BASTA!<\/strong><\/p>\n<p style=\"text-align: justify;\">Desbordada por la infinidad de desaf\u00edos que la vida hab\u00eda puesto en su camino, la joven Evelyn, de Malasia, acab\u00f3 harta de su existencia y a punto estuvo de tirar la toalla de la batalla por la supervivencia. La depresi\u00f3n se apoder\u00f3 de su esp\u00edritu y teji\u00f3 su destructiva tela de ara\u00f1a en ella. Lleg\u00f3 incluso a desarrollar tendencias suicidas, convencida como estaba de que el sol nunca volver\u00eda a brillar para ella. Desde luego no era culpa suya todo cuanto acontec\u00eda en su vida, ya que se hab\u00eda criado en un entorno familiar de adoradores de \u00eddolos, lo que sin duda bloqueaba cualquier posibilidad de comuni\u00f3n con el Alt\u00edsimo.<\/p>\n<p style=\"text-align: justify;\">Creciendo bajo la tutela de sus padres, se uni\u00f3 a ellos en el servicio y la obediencia a extra\u00f1os dioses, lo cual la hundi\u00f3 a\u00fan m\u00e1s en el oscurantismo y en la adoraci\u00f3n de esp\u00edritus ancestrales, a los que se les ofrec\u00eda incienso y libaciones para la <em>liberaci\u00f3n<\/em> de la familia. La joven Evelyn, envuelta en las fantas\u00edas de la juventud, disfrutaba con la naturaleza ritual de todo aquello sin tener ni idea de los graves peligros que corr\u00eda su desarrollo espiritual. Su romance con la adoraci\u00f3n id\u00f3latra era muy intenso.<\/p>\n<figure id=\"attachment_2588\" aria-describedby=\"caption-attachment-2588\" style=\"width: 302px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/02-miss-evelyn-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2588\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/02-miss-evelyn-1.jpg?w=300\" alt=\"LA SE\u00d1ORITA EVELYN\" width=\"302\" height=\"253\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/02-miss-evelyn-1.jpg 720w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/02-miss-evelyn-1-300x250.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/02-miss-evelyn-1-200x167.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/02-miss-evelyn-1-400x334.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/02-miss-evelyn-1-600x501.jpg 600w\" sizes=\"auto, (max-width: 302px) 100vw, 302px\" \/><\/a><figcaption id=\"caption-attachment-2588\" class=\"wp-caption-text\">LA SE\u00d1ORITA EVELYN<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Al madurar se dio cuenta de que sus aspiraciones en la vida quedaban a kil\u00f3metros de distancia de la verdad implacable de la vida, y ese descubrimiento, como no pod\u00eda ser de otro modo, acarre\u00f3 frustraci\u00f3n, p\u00e9rdida de esperanza y depresi\u00f3n, que a su vez desencadenaron sus tendencias suicidas. Pensaba que a nadie le ca\u00eda bien, se sent\u00eda rechazada socialmente y todo ello le llev\u00f3 a la conclusi\u00f3n de que no hab\u00eda nada por lo que valiera la pena vivir. Carg\u00f3 con esta disposici\u00f3n de \u00e1nimo durante bastante tiempo y, en una ocasi\u00f3n, estuvo a punto de saltar de un edificio de veinte pisos. Estaba convencida de que no val\u00eda para nada, de que era una persona sin valor, y esta clase de pensamientos se apoderaron de ella como la mala hierba inunda un campo.<\/p>\n<p style=\"text-align: justify;\">Iba cambiando de trabajo por una inexplicable insatisfacci\u00f3n continua, con lo que su carrera qued\u00f3 en un estado comatoso. Sus relaciones interpersonales eran tambi\u00e9n un desastre. Cuando lleg\u00f3 a la conclusi\u00f3n de que no hab\u00eda modo de escapar a aquel dilema y que sus in\u00fatiles dioses no pod\u00edan ayudarla, decidi\u00f3 explorar otras opciones superiores. Por casualidad hab\u00eda conocido La SCOAN bastante tiempo atr\u00e1s, e incluso hab\u00eda so\u00f1ado con que el Profeta T.B. Joshua le hac\u00eda una profec\u00eda y la liberaba. Contra viento y marea, Evelyn encontr\u00f3 el modo de llegar a Nigeria y pudo visitar la Sinagoga.<\/p>\n<p style=\"text-align: justify;\">El pen\u00faltimo domingo acudi\u00f3 al servicio y tuvo un encuentro muy interesante con el Profeta:<\/p>\n<p style=\"text-align: justify;\"><strong><em>Llevas contigo el esp\u00edritu del suicidio. Quieres suicidarte. Tienes una depresi\u00f3n grave. Tres veces lo has intentado. Tu familia sirve a dioses poderosos.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Evelyn confirm\u00f3 la profec\u00eda y fue liberada en el todopoderoso nombre de Jes\u00fas.<\/p>\n<p style=\"text-align: justify;\">Durante su testimonio, refiri\u00f3 al mundo c\u00f3mo la depresi\u00f3n hab\u00eda estado a punto de arrebatarle la vida. Lamentaba sus actos, pero dijo que, desde que el esp\u00edritu de Dios reinaba en su coraz\u00f3n, ya no albergaba ese pensamiento sino que se sent\u00eda llena de satisfacci\u00f3n y de paz.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Acost\u00fambrense a los desaf\u00edos. Dios no nos prometi\u00f3 borrarlos de nuestro camino, sino ayudarnos a superarlos.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em>\u00a0<\/em><\/strong><strong>EN NOMBRE DE JES\u00daS, \u00a1LEV\u00c1NTATE Y ANDA!<\/strong><\/p>\n<p style=\"text-align: justify;\">Las garras de la espondilitis se hab\u00edan clavado en varias partes del cuerpo de Felicia Nwachi, dej\u00e1ndola inv\u00e1lida.<\/p>\n<figure id=\"attachment_2589\" aria-describedby=\"caption-attachment-2589\" style=\"width: 319px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2589\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-1-1.jpg?w=300\" alt=\"LA SE\u00d1ORA FELICIA Y SU FAMILIA\" width=\"319\" height=\"257\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-1-1.jpg 720w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-1-1-177x142.jpg 177w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-1-1-200x160.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-1-1-400x321.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-1-1-600x481.jpg 600w\" sizes=\"auto, (max-width: 319px) 100vw, 319px\" \/><\/a><figcaption id=\"caption-attachment-2589\" class=\"wp-caption-text\">LA SE\u00d1ORA FELICIA Y SU FAMILIA<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">De la cabeza a los pies pasando por la espalda, un dolor intenso llevaba quince a\u00f1os tortur\u00e1ndola. Iban a ser los a\u00f1os m\u00e1s dif\u00edciles de su vida, ya que el dolor no cesaba y era incapaz de caminar por s\u00ed misma, con la consiguiente angustia que eso generaba.<\/p>\n<p style=\"text-align: justify;\">Cuantos esfuerzos hab\u00edan hecho tanto la medicina occidental como la tradicional hab\u00edan resultado in\u00fatiles, hasta que un d\u00eda su hija decidi\u00f3 llevarla a La SCOAN al calor de la decisi\u00f3n tomada por el Profeta T.B. Joshua de orar por los enfermos y atribulados como parte de las celebraciones por su onom\u00e1stica.<\/p>\n<figure id=\"attachment_2590\" aria-describedby=\"caption-attachment-2590\" style=\"width: 330px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2590\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-2-1.jpg?w=300\" alt=\"LA SE\u00d1ORA FELICIA \" width=\"330\" height=\"280\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-2-1.jpg 720w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-2-1-300x254.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-2-1-200x169.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-2-1-400x339.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/03-mrs-felicia-family-2-1-600x508.jpg 600w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/a><figcaption id=\"caption-attachment-2590\" class=\"wp-caption-text\">LA SE\u00d1ORA FELICIA<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La llevaron hasta all\u00ed en autom\u00f3vil, ya que no pod\u00eda desplazarse de otro modo, y el hombre de Dios sali\u00f3 fuera para orar por ella y demostrar as\u00ed el poder de Dios.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n, le pidi\u00f3 a su hija que orase por ella tambi\u00e9n. En cuanto su hija la toc\u00f3, la madre sinti\u00f3 que algo sal\u00eda de sus ojos. En un instante, una mujer que llevaba quince a\u00f1os en silla de ruedas, se levant\u00f3 y comenz\u00f3 a caminar, maravill\u00e1ndose del poder del Alt\u00edsimo.<\/p>\n<p style=\"text-align: justify;\">Cuando prest\u00f3 su testimonio ante la congregaci\u00f3n, se levant\u00f3 de la silla que ocupaba y camin\u00f3 por el auditorio dando las gracias a Dios por permit\u00edrselo. Ahora puede dormir tranquilamente, algo que antes no pod\u00eda hacer por los incesantes dolores que padec\u00eda en todo el cuerpo.<\/p>\n<p style=\"text-align: justify;\">Nunca se separar\u00eda de Jesucristo.<\/p>\n<p style=\"text-align: center;\"><strong>RECONCILIADO CON DIOS Y CON LA FAMILIA DESPU\u00c9S DE VEINTICINCO A\u00d1OS SIENDO FUMADOR<\/strong><\/p>\n<p style=\"text-align: justify;\">El se\u00f1or Konstantinos estaba hundido en el pecado. Se dejaba llevar por la lujuria, beb\u00eda alcohol y fumaba tres paquetes al d\u00eda, todo esto desde hac\u00eda veinticinco a\u00f1os. Se pasaba la vida en clubes y disfrutando de <em>las cosas buenas de la vida<\/em>. Lleg\u00f3 a un extremo tal que empez\u00f3 a preguntarse por su propia existencia. Intent\u00f3 buscar ayuda en muchas iglesias, pero cuanto m\u00e1s lo hac\u00eda, mayores eran sus pecados. Todo lleg\u00f3 ya a un extremo insoportable cuando su irresponsabilidad condujo en la familia a discusiones frecuentes y a la puesta en peligro de su matrimonio. Fue entonces cuando comenz\u00f3 a dirigirse a Dios en busca de ayuda para corregir sus malos h\u00e1bitos, intentando encontrar una oportunidad de redenci\u00f3n, de abrazar a Dios y de hallar un lugar donde de verdad pudieran ayudarle.<\/p>\n<figure id=\"attachment_2591\" aria-describedby=\"caption-attachment-2591\" style=\"width: 321px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/04-mr-konstantinos-son-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2591\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/04-mr-konstantinos-son-1.jpg?w=300\" alt=\"EL SE\u00d1OR KONSTANTINOS Y SU HIJO\" width=\"321\" height=\"281\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/04-mr-konstantinos-son-1.jpg 720w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/04-mr-konstantinos-son-1-300x262.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/04-mr-konstantinos-son-1-200x174.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/04-mr-konstantinos-son-1-400x349.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/04-mr-konstantinos-son-1-600x523.jpg 600w\" sizes=\"auto, (max-width: 321px) 100vw, 321px\" \/><\/a><figcaption id=\"caption-attachment-2591\" class=\"wp-caption-text\">EL SE\u00d1OR KONSTANTINOS Y SU HIJO<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Un amigo le habl\u00f3 de <em>Emmanuel TV<\/em>, y a medida que ve\u00eda las emisiones de la cadena y comenzaba a orar con el Profeta T.B. Joshua, not\u00f3 c\u00f3mo su vida comenzaba a cambiar. Poco despu\u00e9s, empez\u00f3 a vomitar sustancias venenosas, y la paz volvi\u00f3 gradualmente a su familia. En dos ocasiones lleg\u00f3 incluso a burlar a la muerte: en una de ellas estuvo a punto de perder la vida por salvar a un perro que hab\u00eda ca\u00eddo en una m\u00e1quina, y varias personas acudieron en su ayuda mientras el recordaba las oraciones del Profeta T.B. Joshua en <em>Emmanuel TV<\/em>. <strong><em>Las oraciones del profeta T.B. Joshua me han influido much\u00edsimo. Bast\u00f3 con que tocara la pantalla para que las cosas que estaban ocurriendo all\u00ed me ocurriesen a m\u00ed tambi\u00e9n.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Tras agradecer a Dios su liberaci\u00f3n, el se\u00f1or Konstantinos refiri\u00f3 que hab\u00eda logrado reconciliarse con su familia y que est\u00e1 en paz consigo mismo, ya que su necesidad compulsiva de fumar y de los dem\u00e1s vicios han desaparecido.<\/p>\n<p style=\"text-align: justify;\">Su consejo es que hagamos nuestra la frase de <em>la distancia no es barrera<\/em>.<\/p>\n<p style=\"text-align: center;\"><strong>HUESOS ROTOS COMO NUEVOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Chinwe Amandi result\u00f3 atropellada por un cami\u00f3n que se dio posteriormente a la fuga, y a resultas de ese atropello qued\u00f3 con varios huesos fracturados.<\/p>\n<figure id=\"attachment_2592\" aria-describedby=\"caption-attachment-2592\" style=\"width: 234px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/05-mrs-amandi-husband-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2592\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/05-mrs-amandi-husband-1-1.jpg?w=191\" alt=\"LA SE\u00d1ORA AMANDI Y SU ESPOSO\" width=\"234\" height=\"364\" \/><\/a><figcaption id=\"caption-attachment-2592\" class=\"wp-caption-text\">LA SE\u00d1ORA AMANDI Y SU ESPOSO<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Los m\u00e9dicos le dijeron que ten\u00edan que operarla, pero ella no quiso ni o\u00edr hablar de cirug\u00eda, pues sab\u00eda que Dios puede lograrlo todo. Estaba completamente incapacitada y no pod\u00eda realizar las tareas de su casa sin asistirse con muletas o contar con la ayuda de su marido, un popular actor de Nollywood, que tuvo que abandonar su participaci\u00f3n en una pel\u00edcula para atenderla.<\/p>\n<p style=\"text-align: justify;\">Chinwe sigui\u00f3 adelante con su vida a duras penas hasta que Dios se le mostr\u00f3 a trav\u00e9s del Profeta T.B. Joshua.<\/p>\n<p style=\"text-align: justify;\">El hombre de Dios hab\u00eda hecho saber que, por mandato divino, pretend\u00eda celebrar su 53 cumplea\u00f1os con una <em>L\u00ednea de Oraci\u00f3n <\/em>el s\u00e1bado 11 de junio de 2016, y el se\u00f1or y la se\u00f1ora Amandi aprovecharon la oportunidad de registrarse para esa fecha. Estando en la <em>L\u00ednea de Oraci\u00f3n<\/em>, el hombre de Dios le impuso las manos y el poder de Dios la arroj\u00f3 al suelo. Al levantarse, comenz\u00f3 a caminar sin ayuda por primera vez desde hac\u00eda meses.<\/p>\n<figure id=\"attachment_2593\" aria-describedby=\"caption-attachment-2593\" style=\"width: 356px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/05-mrs-amandi-husband-2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2593\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/05-mrs-amandi-husband-2-1.jpg?w=300\" alt=\"LA SE\u00d1ORA AMANDI\" width=\"356\" height=\"234\" \/><\/a><figcaption id=\"caption-attachment-2593\" class=\"wp-caption-text\">LA SE\u00d1ORA AMANDI<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Su esposo tambi\u00e9n cay\u00f3 al suelo por la fuerza del poder del Se\u00f1or cuando le toc\u00f3 el hombre de Dios.<\/p>\n<p style=\"text-align: justify;\">Se levant\u00f3 del suelo para celebrar con su esposa aquella gran alegr\u00eda y dijo: <strong><em>el hombre de Dios or\u00f3 por mi esposa y por m\u00ed, y yo sent\u00ed que la alegr\u00eda me desbordaba.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">La se\u00f1ora Amandi demostr\u00f3 a la congregaci\u00f3n c\u00f3mo ha recuperado su buena forma f\u00edsica, y c\u00f3mo ha vuelto a ser capaz de caminar y de correr incluso. Dirigi\u00e9ndose a todos, declar\u00f3: <strong><em>Conv\u00e9nzanse de que Dios puede sanarlos. En cuanto tengan fe, su problema quedar\u00e1 resuelto.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>TODO ME VA BIEN DESDE QUE CONOC\u00cd A CRISTO EN <em>EMMANUEL TV<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Dancho Hadzhieu se hab\u00eda convertido en una espina clavada en la carne de muchos por culpa de sus decisiones. Hab\u00eda nacido en una familia adinerada y nunca careci\u00f3 de nada. Este joven b\u00falgaro que vive en Grecia, se aficion\u00f3 a propinar palizas a la gente para quitarles lo que llevaran, ya que no tem\u00eda a nada ni a nadie por las influencias que ten\u00edan sus padres en aquella comunidad. Mientras estaba en el instituto, form\u00f3 una banda que se especializaba en acosar a personas indefensas. Sab\u00eda que no obraba bien, pero era incapaz de poner punto final. Se sent\u00eda como un Dios.<\/p>\n<figure id=\"attachment_2594\" aria-describedby=\"caption-attachment-2594\" style=\"width: 250px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/06-mr-danchio-hadzhieu-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2594\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/06-mr-danchio-hadzhieu-1.jpg?w=200\" alt=\"EL SE\u00d1OR DANCHIO HADZHIEU\" width=\"250\" height=\"372\" \/><\/a><figcaption id=\"caption-attachment-2594\" class=\"wp-caption-text\">EL SE\u00d1OR DANCHIO HADZHIEU<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Acab\u00f3 entrando en el cuerpo de polic\u00eda, pero no por ello cesaron sus nefastas actividades. M\u00e1s bien al contrario, al ampararse en la impunidad de oficial de polic\u00eda, en el uniforme y su arma, de modo que continu\u00f3 hostigando a la gente, propinando palizas sin remordimiento alguno. Sus superiores terminaron enter\u00e1ndose de todo y lo amenazaron con echarle del cuerpo, pero a \u00e9l le dio igual. Incluso lleg\u00f3 a decirles a sus jefes que ten\u00eda dinero de sobra y que le daba igual lo que le hicieran porque para \u00e9l no significaba nada. La conciencia le enviaba d\u00e9biles mensajes de vez en cuando, pero \u00e9l no la escuchaba.<\/p>\n<p style=\"text-align: justify;\">Un tiempo despu\u00e9s fue despedido y \u00e9l, furioso, sigui\u00f3 con su vida de irresponsabilidad, saliendo por las noches con un grupo mafioso, bebiendo y fumando, sin importarle nada las consecuencias de sus actos porque manten\u00eda amigos en la polic\u00eda. Pero la mano de Dios lo alcanz\u00f3 al fin cuando un amigo le habl\u00f3 de la salvaci\u00f3n y del profeta T.B. Joshua, y le mostr\u00f3 <em>Emmanuel TV<\/em>. A pesar de sus recistencias iniciales, logr\u00f3 convencerle para que viera el canal<em>.<\/em><\/p>\n<p style=\"text-align: justify;\">Mientras ve\u00eda orar al Profeta T.B. Joshua en la televisi\u00f3n, el se\u00f1or Hadzhieu se aclam\u00f3 a Dios rog\u00e1ndole que tuviera compasi\u00f3n de \u00e9l y le ayudara a cambiar de vida. Desde aquel momento, su vida se transform\u00f3: dej\u00f3 de jugar, de beber, de fumar, y todos los problemas que llevaba cargando sobre los hombros desaparecieron. Las denuncias que la gente hab\u00eda interpuesto contra \u00e9l quedaron archivadas, e incluso llegaron a readmitirlo en la polic\u00eda en un puesto de mayor rango.<\/p>\n<p style=\"text-align: justify;\">El pasado domingo acudi\u00f3 a La SCOAN para dar testimonio sobre c\u00f3mo la bondad de Dios hab\u00eda transformado su vida, la alegr\u00eda que hab\u00eda supuesto para \u00e9l descubrir a Cristo a trav\u00e9s de <em>Emmanuel TV <\/em>y c\u00f3mo se hab\u00eda arrepentido de tanto mal como hab\u00eda causado. <strong><em>Si alguna vez ha hablado mal de T.B. Joshua, pida perd\u00f3n a Dios por haberlo hecho<\/em><\/strong>, fue su consejo, recordando las escrituras en <strong><em>Mateo 10:41 <\/em><\/strong>en donde se dice que, si se honra a un profeta de Dios, recibiremos la recompensa de un profeta, en el nombre de Dios.<\/p>\n<p style=\"text-align: center;\"><strong>\u00a1HE VUELTO A CAMINAR! \u00a1GRACIAS, JES\u00daS!<\/strong><\/p>\n<p style=\"text-align: justify;\">Diane Ebele Okeke llevaba a\u00f1os confinada en una silla de ruedas. Desde 2009 ven\u00eda padeciendo serios problemas de artritis reumatoide, que le imped\u00edan desarrollar sus funciones de madre y esposa.<\/p>\n<figure id=\"attachment_2595\" aria-describedby=\"caption-attachment-2595\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2595\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-1-1.jpg?w=300\" alt=\"LA SE\u00d1ORA DIANE Y SU FAMILIA\" width=\"360\" height=\"261\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-1-1.jpg 720w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-1-1-200x144.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-1-1-600x433.jpg 600w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/a><figcaption id=\"caption-attachment-2595\" class=\"wp-caption-text\">LA SE\u00d1ORA DIANE Y SU FAMILIA<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">En un principio temieron incluso que su afecci\u00f3n le impidiera concebir, ya que la enfermedad hab\u00eda afectado a otras zonas de su cuerpo, entre ellas la zona lumbar.<\/p>\n<p style=\"text-align: justify;\">Llevaba a\u00f1os viviendo con el apoyo de su familia, y sus consultas en distintos hospitales no hab\u00edan aportado soluci\u00f3n al problema. Incluso cuando consigui\u00f3 concebir y dar a luz a su hijo, tras un parto largo y dif\u00edcil, el problema empeor\u00f3. Es f\u00e1cil imaginar las dificultades de una mujer prisionera de una silla de ruedas y del dolor para amamantar a su hijo.<\/p>\n<p style=\"text-align: justify;\">Sus siete a\u00f1os de angustia llegaron a su fin el s\u00e1bado 11 de junio de 2016, cuando el profeta T.B. Joshua, inspirado por el Esp\u00edritu Santo, convoc\u00f3 una <em>L\u00ednea de Oraci\u00f3n <\/em>\u00a0en conmemoraci\u00f3n de su 53 cumplea\u00f1os.<\/p>\n<figure id=\"attachment_2596\" aria-describedby=\"caption-attachment-2596\" style=\"width: 385px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2596\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-2-1.jpg?w=300\" alt=\"LA SE\u00d1ORA DIANE\" width=\"385\" height=\"244\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-2-1-320x202.jpg 320w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-2-1-700x441.jpg 700w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/07-mrs-diane-ebere-family-2-1-200x126.jpg 200w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/a><figcaption id=\"caption-attachment-2596\" class=\"wp-caption-text\">LA SE\u00d1ORA DIANE<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Diane fue trasladada a La SCOAN desde Abuja con su silla de ruedas, y cuando el hombre de Dios estaba ministrando sanidad fuera del auditorio, ella llam\u00f3 su atenci\u00f3n. El profeta T.B. Joshua le impuso las manos bendecidas en el todopoderoso nombre de Jes\u00fas, y Diane se levant\u00f3 de la silla y camin\u00f3 sin ayuda por primera vez en siete a\u00f1os, gritando <strong><em>\u00a1Estoy sanada\u2026 gracias, Jes\u00fas!<\/em><\/strong> Su hermana, que la hab\u00eda acompa\u00f1ado, estall\u00f3 en muestras de j\u00fabilo, lo mismo que aquellos que hab\u00edan presenciado el poder de Dios a trav\u00e9s de su profeta.<\/p>\n<p style=\"text-align: justify;\">Acompa\u00f1ada por su hermana, Diane comparti\u00f3 su testimonio y dio las gracias a Dios por su sanidad, que le ha permitido cuidar de s\u00ed misma. Todo el dolor que hab\u00eda hecho de su vida un valle de l\u00e1grimas ha desaparecido.<\/p>\n<p style=\"text-align: center;\"><strong>DINERO ROBADO RECUPERADO<\/strong><\/p>\n<p style=\"text-align: justify;\">La se\u00f1ora Okechukwu estaba cuadrando la caja despu\u00e9s de un d\u00eda de trabajo cuando descubri\u00f3 que le faltaban doscientas cincuenta mil nairas. Por m\u00e1s que lo intent\u00f3, no logr\u00f3 descubrir qu\u00e9 hab\u00eda pasado. Ni siquiera una revisi\u00f3n exhaustiva de lo que hab\u00eda grabado el circuito cerrado de c\u00e1maras pudo darle idea de d\u00f3nde hab\u00eda ido a parar ese dinero, lo cual acarrear\u00eda sin duda su despido. Pero la cajera del banco no iba a rendirse ante satan\u00e1s: decidi\u00f3 llamar de inmediato a los n\u00fameros de las <em>L\u00edneas de Oraci\u00f3n y Consejo <\/em>de <em>Emmanuel TV<\/em> y or\u00f3 con los <em>Guerreros de Oraci\u00f3n<\/em>. Luego, corri\u00f3 a su casa en busca de su <em>Agua de la Ma\u00f1ana<\/em>, y volvi\u00f3 con ella a la oficina, donde or\u00f3 con fervor para pedirle a Dios que localizara ese dinero, sin importarle qui\u00e9n lo tuviera o d\u00f3nde se hab\u00eda escondido. Tras la oraci\u00f3n, ministr\u00f3 el <em>Agua de la Ma\u00f1ana <\/em>en su sitio de trabajo.<\/p>\n<figure id=\"attachment_2597\" aria-describedby=\"caption-attachment-2597\" style=\"width: 311px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/08-mrmrs-okechukwu-davies-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2597\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/08-mrmrs-okechukwu-davies-1.jpg?w=300\" alt=\"EL SE\u00d1OR Y LA SE\u00d1ORA OKECHUKWU\" width=\"311\" height=\"260\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/08-mrmrs-okechukwu-davies-1.jpg 720w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/08-mrmrs-okechukwu-davies-1-300x250.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/08-mrmrs-okechukwu-davies-1-200x167.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/08-mrmrs-okechukwu-davies-1-400x334.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/08-mrmrs-okechukwu-davies-1-600x501.jpg 600w\" sizes=\"auto, (max-width: 311px) 100vw, 311px\" \/><\/a><figcaption id=\"caption-attachment-2597\" class=\"wp-caption-text\">EL SE\u00d1OR Y LA SE\u00d1ORA OKECHUKWU<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Aquella misma noche so\u00f1\u00f3 que se encontraba con el Profeta T.B. Joshua, y que \u00e9l le preguntaba: <strong><em>\u00bfQui\u00e9n soy yo?<\/em><\/strong>\u00a0 tres veces, a lo que ella respond\u00eda <strong><em>Eres el profeta. <\/em><\/strong>A continuaci\u00f3n, \u00e9l le ped\u00eda que se sentara y ella se despert\u00f3.<\/p>\n<p style=\"text-align: justify;\">Al volver al trabajo el lunes, se encontr\u00f3 con una recepci\u00f3n dura: le dijeron que abandonara su puesto mientras se llevaba a cabo la investigaci\u00f3n pertinente sobre el paradero del dinero. A aquellas alturas, las insinuaciones de que fuera ella la responsable del robo de la cantidad eran cada vez m\u00e1s fuertes.<\/p>\n<p style=\"text-align: justify;\">Al d\u00eda siguiente, estando en casa, recibi\u00f3 una llamada en la que le ped\u00edan que volviera urgentemente a la oficina: \u00a1el dinero hab\u00eda sido encontrado! De camino hacia all\u00e1, iba derramando l\u00e1grimas de alegr\u00eda, ya que el dinero se hab\u00eda encontrado en un lugar que ya hab\u00eda sido registrado a conciencia varias veces. En el fondo de su coraz\u00f3n sab\u00eda que alguien lo hab\u00eda robado, pero que gracias a la intensidad de sus oraciones y del <em>Agua de la Ma\u00f1ana <\/em>\u00a0lo hab\u00eda devuelto.<\/p>\n<p style=\"text-align: justify;\">Dando gracias a Dios junto a su esposo, su consejo para todos los que la escuchaban fue que confiaran en Dios porque para \u00e9l no hay nada demasiado dif\u00edcil.<\/p>\n<p style=\"text-align: center;\"><strong>A PESAR DE TODAS LAS DIFICULTADES , DIOS LE HIZO EL MEJOR<\/strong><\/p>\n<p style=\"text-align: justify;\">Trevor Phillips hab\u00eda abandonado sus estudios de Producci\u00f3n Musical e Ingenier\u00eda de Sonido para dedicarse a otras disciplinas. Un d\u00eda, mientras oraba, sinti\u00f3 que Dios le ped\u00eda que volviera a sus estudios y completase la licenciatura que hab\u00eda empezado. Originario del Reino Unido y residente en Australia, volvi\u00f3\u00a0 a la universidad y se traslad\u00f3 de Adelaide a Melbourne para completra los aspectos pr\u00e1cticos del curso. En Melburne su familia y \u00e9l descubrieron <em>Emmanuel TV, <\/em>y desarrollaron gran inter\u00e9s por alimentar su fe en Dios.<\/p>\n<figure id=\"attachment_2598\" aria-describedby=\"caption-attachment-2598\" style=\"width: 329px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/09-mrmrs-trevor-baby-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2598\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/09-mrmrs-trevor-baby-1.jpg?w=300\" alt=\"EL SE\u00d1OR Y LA SE\u00d1ORA TREVOR Y SU BEBE\" width=\"329\" height=\"236\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/09-mrmrs-trevor-baby-1-300x214.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/09-mrmrs-trevor-baby-1-200x142.jpg 200w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/><\/a><figcaption id=\"caption-attachment-2598\" class=\"wp-caption-text\">EL SE\u00d1OR Y LA SE\u00d1ORA TREVOR Y SU BEBE<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em>Emmanuel TV <\/em>mejoraba su vida espiritual y se sent\u00edan animados y bendecidos por los testimonios as\u00ed como por los mensajes del profeta T.B. Joshua. Un tiempo despu\u00e9s, su esposa consigui\u00f3 un trabajo que les proporcion\u00f3 los fondos suficientes para que \u00e9l pudiera continuar con los estudios. En mayo de 2015 obtuvo su t\u00edtulo para mayor gloria de Dios.<\/p>\n<p style=\"text-align: justify;\">La direcci\u00f3n de su universidad le envi\u00f3 una invitaci\u00f3n especial para asistir a la ceremonia de graduaci\u00f3n como el estudiante con las mejores notas de toda Australia, que le fue reconocido con un premio, adem\u00e1s de con el privilegio de dirigir unas palabras al resto de graduados.<\/p>\n<p style=\"text-align: justify;\">Trevor Phillips, acompa\u00f1ado por su esposa y su hija, dio las gracias a Dios por haberle llevado de la mano hasta la cima de su vida acad\u00e9mica, y aconsej\u00f3 a quienes le escuchaban, y en particular a los estudiantes, a centrarse en Dios y a perseguir sus sue\u00f1os por inalcanzables que puedan parecer, en la confianza de que Dios les acompa\u00f1ar\u00e1 a cada paso del camino.<\/p>\n<p style=\"text-align: center;\"><strong>ADI\u00d3S AL DEVORADOR<\/strong><\/p>\n<p style=\"text-align: justify;\">Anastasia Mavridoy hab\u00eda empezado a trabajar a los veinte a\u00f1os, y aunque estaba ganando bastante dinero, no alcanzaba a comprender de qu\u00e9 manera se le escapaba de las manos. Compraba y vend\u00eda productos por todo el mundo, pero su esfuerzo aparentemente no ten\u00eda recompensa. Ganaba entre trescientos y quinientos mil euros mensuales, pero segu\u00eda sin poder dar cuenta de ellos. La depresi\u00f3n comenz\u00f3 a hacer mella en ella, y cada noche, cuando se iba a su habitaci\u00f3n, ped\u00eda a Dios que la ayudase con su problema.<\/p>\n<p style=\"text-align: justify;\">En esa \u00e9poca comenz\u00f3 a ver <em>Emmanuel TV,<\/em> y enseguida quiso conocer La SCOAN. Era extra\u00f1o que una mujer como ella, que ganaba tanto dinero, no pudiera dar cuenta de \u00e9l; desde luego algo ten\u00eda que estar pasando.<\/p>\n<figure id=\"attachment_2599\" aria-describedby=\"caption-attachment-2599\" style=\"width: 301px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/10-mrs-anastasia-mavridoy-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2599\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/10-mrs-anastasia-mavridoy-1.jpg?w=271\" alt=\"LA SE\u00d1ORA ANASTASIA MAVRIDO\" width=\"301\" height=\"333\" \/><\/a><figcaption id=\"caption-attachment-2599\" class=\"wp-caption-text\">LA SE\u00d1ORA ANASTASIA MAVRIDO<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Por fin sus oraciones fueron escuchadas y pudo visitar La SCOAN, y una vez all\u00ed recibi\u00f3 el <em>Agua de la Ma\u00f1ana<\/em> y un mensaje prof\u00e9tico del hombre de Dios respecto a su negocio hort\u00edcola, en el que le dec\u00eda que iba a florecer. En cuanto volvi\u00f3 a Grecia, ministr\u00f3 el <em>Agua de la Ma\u00f1ana<\/em> mientras pensaba con absoluto convencimiento que su negocio iba a florecer como hab\u00eda declarado el hombre de Dios.<\/p>\n<p style=\"text-align: justify;\">Por la gracia de Dios, as\u00ed fue exactamente como ocurri\u00f3: la gente comenz\u00f3 a hacer de su negocio un \u00e9xito rotundo, y sus cifras ascendieron como no se habr\u00eda atrevido a so\u00f1ar. Al ver crecer as\u00ed sus ingresos, se anim\u00f3 a abrir otra empresa llamada <em>TEMITOPE Company,<\/em> en honor del hombre de Dios, la mano que el Se\u00f1or escogi\u00f3 para hacer que sus negocios florecieran.<\/p>\n<p style=\"text-align: justify;\">Tras dar las gracias a Dios por bendecirla y devolverle la sonrisa, la se\u00f1ora Mavridoy record\u00f3 a quienes la escuchaban que siempre hay un esp\u00edritu detr\u00e1s de cada problema, y que lo mejor que se puede hacer es llevarle a Dios nuestras pesadumbres.<\/p>\n<p style=\"text-align: center;\"><strong>JES\u00daS REVIVI\u00d3 SU CORAZ\u00d3N<\/strong><\/p>\n<p style=\"text-align: justify;\">Hac\u00eda doce a\u00f1os que el pastor Ely Blunk hab\u00eda notado los primeros s\u00edntomas de una enfermedad cardiaca y, en una intervenci\u00f3n quir\u00fargica, le instalaron un marcapasos para ayudar a su coraz\u00f3n.<\/p>\n<figure id=\"attachment_2601\" aria-describedby=\"caption-attachment-2601\" style=\"width: 283px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/peacemaker-man1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2601\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/peacemaker-man1-1.jpg?w=259\" alt=\"PASTOR ELLY BLUNCK\" width=\"283\" height=\"327\" \/><\/a><figcaption id=\"caption-attachment-2601\" class=\"wp-caption-text\">PASTOR ELLY BLUNCK<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Este pastor brasile\u00f1o llevaba muchos a\u00f1os viviendo con el marcapasos hasta que el poder de Dios lo encontr\u00f3 durante un Servicio Dominial de La SCOAN.<\/p>\n<p style=\"text-align: justify;\">El Profeta T.B. Joshua se mov\u00eda entre la congregaci\u00f3n cuando se detuvo ante \u00e9l y le puso la mano en el pecho para orar.<\/p>\n<figure id=\"attachment_2602\" aria-describedby=\"caption-attachment-2602\" style=\"width: 375px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/peacemaker-man2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2602\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/peacemaker-man2-1.jpg?w=300\" alt=\"PASTOR ELLY BLINCK Y SU MARCA PASOS\" width=\"375\" height=\"252\" \/><\/a><figcaption id=\"caption-attachment-2602\" class=\"wp-caption-text\">PASTOR ELLY BLINCK Y SU MARCA PASOS<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La bendici\u00f3n de Dios impregn\u00f3 la atm\u00f3sfera del servicio y el pastor Blunck sinti\u00f3 que su coraz\u00f3n comenzaba a latir por s\u00ed mismo. Inmediatamente se adelant\u00f3 y dio las gracias a Dios por su milagrosa sanidad.<\/p>\n<p style=\"text-align: justify;\">Sobrecogido, llorando de emoci\u00f3n y alegr\u00eda, oy\u00f3 como otros latinoamericanos que hab\u00edan acudido para la celebraci\u00f3n del cumplea\u00f1os del Profeta daban las gracias a Dios por haber revivido su coraz\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Mientras expresaban su gratitud, se desplegaron las banderas de Brasil, Paraguay, Argentina, Per\u00fa, Cuba, M\u00e9xico, Rusia y Grecia, y sus portadores declararon que hab\u00edan ido hasta La SCOAN para invitar formalmente al Profeta T.b. Joshua a visitar sus pa\u00edses.<\/p>\n<figure id=\"attachment_2603\" aria-describedby=\"caption-attachment-2603\" style=\"width: 424px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/tbjoshuaes.files.wordpress.com\/2016\/06\/2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2603\" src=\"https:\/\/tbjoshuaes.files.wordpress.com\/2016\/06\/2.jpg?w=300\" alt=\"DELEGACI\u00d3N DE BRASIL\" width=\"424\" height=\"290\" \/><\/a><figcaption id=\"caption-attachment-2603\" class=\"wp-caption-text\">DELEGACI\u00d3N DE BRASIL<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2604\" aria-describedby=\"caption-attachment-2604\" style=\"width: 434px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/51.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2604\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/51.jpg?w=300\" alt=\"DELAGACI\u00d3N DE PARAGUAY\" width=\"434\" height=\"265\" \/><\/a><figcaption id=\"caption-attachment-2604\" class=\"wp-caption-text\">DELAGACI\u00d3N DE PARAGUAY<\/figcaption><\/figure>\n<figure id=\"attachment_2605\" aria-describedby=\"caption-attachment-2605\" style=\"width: 418px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/3-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2605\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/3-1.jpg?w=300\" alt=\"DELEGACI\u00d3N DE ARGENTINA\" width=\"418\" height=\"303\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/3-1-300x216.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/3-1-768x554.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/3-1-200x144.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/3-1-600x433.jpg 600w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/a><figcaption id=\"caption-attachment-2605\" class=\"wp-caption-text\">DELEGACI\u00d3N DE ARGENTINA<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2606\" aria-describedby=\"caption-attachment-2606\" style=\"width: 414px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2606\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/4-1.jpg?w=300\" alt=\"DELEGACI\u00d3N DE CUBA\" width=\"414\" height=\"325\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/4-1.jpg 716w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/4-1-300x235.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/4-1-200x157.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/4-1-400x314.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/4-1-600x471.jpg 600w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\" \/><\/a><figcaption id=\"caption-attachment-2606\" class=\"wp-caption-text\">DELEGACI\u00d3N DE CUBA<\/figcaption><\/figure>\n<figure id=\"attachment_2607\" aria-describedby=\"caption-attachment-2607\" style=\"width: 430px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2607\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/1-1.jpg?w=300\" alt=\"DELEGACION DE RUSIA\" width=\"430\" height=\"238\" \/><\/a><figcaption id=\"caption-attachment-2607\" class=\"wp-caption-text\">DELEGACI\u00d3N DE RUSIA<\/figcaption><\/figure>\n<figure id=\"attachment_2608\" aria-describedby=\"caption-attachment-2608\" style=\"width: 393px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/6-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2608\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/6-1.jpg?w=300\" alt=\"DELEGACI\u00d3N DE GRECIA\" width=\"393\" height=\"236\" \/><\/a><figcaption id=\"caption-attachment-2608\" class=\"wp-caption-text\">DELEGACI\u00d3N DE GRECIA<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El serm\u00f3n fue toda una celebraci\u00f3n del amor de Dios y de su gracia a trav\u00e9s de la vida y el ministerio del Profeta T.B. Joshua, que celebraba su cincuenta y tres cumplea\u00f1os para mayor gloria de Dios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El Profeta T.B. Joshua celebr\u00f3 su cincuenta y tres cumplea\u00f1os con un explosivo Servicio Dominical en el que un aut\u00e9ntico aluvi\u00f3n de testimonios y maravillas llenaron la pantalla de Emmanuel TV. El d\u00eda anterior, s\u00e1bado, Dios hab\u00eda manifestado su poder con los enfermos que abarrotaban las instalaciones de La SCOAN, y que aguardaban su [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[1436,1],"tags":[1458,1297,1459,1187,1460,1461,1462,1463,1147,1464,1465,1211,1466,1467,1468,1469,1470,1471,1472,1473,1474,1475,1069,1156,1184,1476,371],"class_list":["post-2586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emmanuel-tv-2","category-uncategorized","tag-actor","tag-agricultura","tag-argentina","tag-australia","tag-brasil","tag-cajera","tag-chile","tag-cumpleanos","tag-depresion","tag-dificultad-para-caminar","tag-dioses-familiares","tag-embarazo","tag-enfermos","tag-grecia","tag-latinoamerica","tag-marca-pasos","tag-mexico","tag-negocios","tag-nollywood","tag-paraguay","tag-peru","tag-policia","tag-robo","tag-rusia","tag-silla-de-ruedas","tag-suicio","tag-temitope"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"og:description\" content=\"&nbsp; El Profeta T.B. Joshua celebr\u00f3 su cincuenta y tres cumplea\u00f1os con un explosivo Servicio Dominical en el que un aut\u00e9ntico aluvi\u00f3n de testimonios y maravillas llenaron la pantalla de Emmanuel TV. El d\u00eda anterior, s\u00e1bado, Dios hab\u00eda manifestado su poder con los enfermos que abarrotaban las instalaciones de La SCOAN, y que aguardaban su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/\" \/>\n<meta property=\"og:site_name\" content=\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tbjministries\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-21T13:36:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-28T14:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SCOAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:site\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SCOAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/\"},\"author\":{\"name\":\"SCOAN\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/60e4166936306ab3c7ff663fa3ce7658\"},\"headline\":\"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS\",\"datePublished\":\"2016-06-21T13:36:07+00:00\",\"dateModified\":\"2018-09-28T14:50:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/\"},\"wordCount\":4448,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/06\\\/01-prophet-t-b-joshua-1.jpg\",\"keywords\":[\"actor\",\"Agricultura\",\"argentina\",\"AUSTRALIA\",\"brasil\",\"cajera\",\"chile\",\"cumplea\u00f1os\",\"Depresi\u00f3n\",\"dificultad para caminar\",\"dioses familiares\",\"embarazo\",\"enfermos\",\"grecia\",\"latinoamerica\",\"marca pasos\",\"mexico\",\"negocios\",\"nollywood\",\"paraguay\",\"peru\",\"policia\",\"Robo\",\"Rusia\",\"silla de ruedas\",\"suicio\",\"Temitope\"],\"articleSection\":[\"EMMANUEL TV\",\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/\",\"name\":\"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/06\\\/01-prophet-t-b-joshua-1.jpg\",\"datePublished\":\"2016-06-21T13:36:07+00:00\",\"dateModified\":\"2018-09-28T14:50:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/06\\\/01-prophet-t-b-joshua-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/06\\\/01-prophet-t-b-joshua-1.jpg\",\"width\":720,\"height\":432,\"caption\":\"EL PROFETA T.B. JOSHUA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"description\":\"Founded by Prophet TB Joshua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"width\":186,\"height\":85,\"caption\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tbjministries\",\"https:\\\/\\\/x.com\\\/SCOANTBJoshua\",\"https:\\\/\\\/www.instagram.com\\\/tbjoshua\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/60e4166936306ab3c7ff663fa3ce7658\",\"name\":\"SCOAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"caption\":\"SCOAN\"},\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/author\\\/ilyap51\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/","og_locale":"es_ES","og_type":"article","og_title":"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","og_description":"&nbsp; El Profeta T.B. Joshua celebr\u00f3 su cincuenta y tres cumplea\u00f1os con un explosivo Servicio Dominical en el que un aut\u00e9ntico aluvi\u00f3n de testimonios y maravillas llenaron la pantalla de Emmanuel TV. El d\u00eda anterior, s\u00e1bado, Dios hab\u00eda manifestado su poder con los enfermos que abarrotaban las instalaciones de La SCOAN, y que aguardaban su [&hellip;]","og_url":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/","og_site_name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","article_publisher":"https:\/\/www.facebook.com\/tbjministries","article_published_time":"2016-06-21T13:36:07+00:00","article_modified_time":"2018-09-28T14:50:52+00:00","og_image":[{"width":720,"height":432,"url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg","type":"image\/jpeg"}],"author":"SCOAN","twitter_card":"summary_large_image","twitter_creator":"@SCOANTBJoshua","twitter_site":"@SCOANTBJoshua","twitter_misc":{"Escrito por":"SCOAN","Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#article","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/"},"author":{"name":"SCOAN","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/60e4166936306ab3c7ff663fa3ce7658"},"headline":"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS","datePublished":"2016-06-21T13:36:07+00:00","dateModified":"2018-09-28T14:50:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/"},"wordCount":4448,"commentCount":1,"publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"image":{"@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg","keywords":["actor","Agricultura","argentina","AUSTRALIA","brasil","cajera","chile","cumplea\u00f1os","Depresi\u00f3n","dificultad para caminar","dioses familiares","embarazo","enfermos","grecia","latinoamerica","marca pasos","mexico","negocios","nollywood","paraguay","peru","policia","Robo","Rusia","silla de ruedas","suicio","Temitope"],"articleSection":["EMMANUEL TV","Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/","url":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/","name":"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#primaryimage"},"image":{"@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg","datePublished":"2016-06-21T13:36:07+00:00","dateModified":"2018-09-28T14:50:52+00:00","breadcrumb":{"@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#primaryimage","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/06\/01-prophet-t-b-joshua-1.jpg","width":720,"height":432,"caption":"EL PROFETA T.B. JOSHUA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scoan.org\/es\/un-cumpleanos-dedicado-a-bendecir-a-los-enfermos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scoan.org\/es\/"},{"@type":"ListItem","position":2,"name":"UN CUMPLEA\u00d1OS DEDICADO A BENDECIR A LOS ENFERMOS"}]},{"@type":"WebSite","@id":"https:\/\/www.scoan.org\/es\/#website","url":"https:\/\/www.scoan.org\/es\/","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"Founded by Prophet TB Joshua","publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scoan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scoan.org\/es\/#organization","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","url":"https:\/\/www.scoan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","width":186,"height":85,"caption":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua"},"image":{"@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tbjministries","https:\/\/x.com\/SCOANTBJoshua","https:\/\/www.instagram.com\/tbjoshua"]},{"@type":"Person","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/60e4166936306ab3c7ff663fa3ce7658","name":"SCOAN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","caption":"SCOAN"},"url":"https:\/\/www.scoan.org\/es\/author\/ilyap51\/"}]}},"_links":{"self":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/2586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/comments?post=2586"}],"version-history":[{"count":1,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/2586\/revisions"}],"predecessor-version":[{"id":22609,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/2586\/revisions\/22609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media\/2587"}],"wp:attachment":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media?parent=2586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/categories?post=2586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/tags?post=2586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}