{"id":2235,"date":"2016-03-01T16:00:34","date_gmt":"2016-03-01T16:00:34","guid":{"rendered":"https:\/\/tbjoshuaes.wordpress.com\/?p=2235"},"modified":"2016-03-01T16:00:34","modified_gmt":"2016-03-01T16:00:34","slug":"el-cristianismo-reside-en-el-corazon","status":"publish","type":"post","link":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/","title":{"rendered":"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N"},"content":{"rendered":"<figure id=\"attachment_2236\" aria-describedby=\"caption-attachment-2236\" style=\"width: 401px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg\" rel=\"attachment wp-att-2236\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2236\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg?w=300\" alt=\"EL PROFETA T.B. JOSHUA\" width=\"401\" height=\"309\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1-300x230.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1-260x200.jpg 260w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1-200x153.jpg 200w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/a><figcaption id=\"caption-attachment-2236\" class=\"wp-caption-text\">EL PROFETA T.B. JOSHUA<\/figcaption><\/figure>\n<p><strong>\u00a0<\/strong>El profeta T.B. Joshua revel\u00f3 el secreto que se esconde tras la aplicaci\u00f3n de la fe en la vida de un verdadero cristiano con el mensaje titulado <em>\u00abLa Cristiandad\u00a0<\/em><em>reside en el coraz\u00f3n\u00bb, <\/em>durante el servicio dominical del 21 de febrero de 2016, acompa\u00f1ado por las canciones de adoraci\u00f3n que, interpretadas por el coro, acondicionaron la atm\u00f3sfera del auditorio. Profec\u00edas, testimonios y liberaciones reafirmaron el hecho de que con fe, el poder de Dios est\u00e1 siempre al alcance de los creyentes. En palabras del hombre de Dios:<\/p>\n<p><strong>\u00ab<em>La fe es la moneda del cielo. La fe surge de nosotros de modo natural, y es necesario conocer la fidelidad y la fiabilidad de Dios. Si prestas atenci\u00f3n a Su palabra, descubrir\u00e1s que la fe llega de un modo espont\u00e1neo, que es algo natural\u00bb.<\/em><\/strong><\/p>\n<p>En otras palabras: que no hay modo de que un cristiano pueda tener fe, si antes no ha alimentado su mente con la Palabra de Dios. Cuanto m\u00e1s se alimente de Su palabra, con m\u00e1s facilidad crecer\u00e1 en \u00e9l o en ella, de modo natural, su fe.<\/p>\n<p>El hombre de Dios explic\u00f3 que hagamos lo que hagamos, si nuestros actos no brotan del coraz\u00f3n, no obtendremos recompensa alguna de Dios, dado que equivaldr\u00eda a vivir una mentira.<\/p>\n<p><strong>\u00ab<\/strong><strong><em>La fe proviene del coraz\u00f3n, y sin fe no podemos complacer a Dios. Dios es quien nos recompensa. Cuando lo que haces no te nace del coraz\u00f3n, Dios no te recompensa\u00bb.<\/em><\/strong><\/p>\n<p>Para concluir, el hombre de Dios dirigi\u00f3 la oraci\u00f3n de la congregaci\u00f3n pidiendo que se denunciara y se renunciara a cualquier forma de forma de vida falsa, y se declaraba el deseo de dedicar el coraz\u00f3n a Dios, a quien no podemos complacer si no tenemos fe.<\/p>\n<p style=\"text-align:center\"><strong>TESTIMONIOS<\/strong><\/p>\n<p style=\"text-align:center\"><strong>\u00a0LIBERADA DEL ESP\u00cdRITU QUE LE HAC\u00cdA MOJAR LA CAMA<\/strong><\/p>\n<p><strong>\u00a0<\/strong>Onyinye Anyanwu, una hermosa joven nacida en Imo State y graduada en la North American University de la Rep\u00fablica de Benin, llevaba atormentada desde la ni\u00f1ez por un esp\u00edritu que le hac\u00eda mojar la cama, y su asedio fue a\u00fan peor durante los a\u00f1os de instituto y universidad.<\/p>\n<figure id=\"attachment_2237\" aria-describedby=\"caption-attachment-2237\" style=\"width: 197px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/miss-onyinye-anyanwu.jpg\" rel=\"attachment wp-att-2237\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2237\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/miss-onyinye-anyanwu.jpg\" alt=\"LA SE\u00d1ORITA ONYINYE ANYANWU\" width=\"197\" height=\"274\" \/><\/a><figcaption id=\"caption-attachment-2237\" class=\"wp-caption-text\">LA SE\u00d1ORITA ONYINYE ANYANWU<\/figcaption><\/figure>\n<p>En cuanto cerraba los ojos por la noche, mojaba la cama. Era algo que se sent\u00eda incapaz de controlar. Treinta a\u00f1os duraba ya aquel estigma.<\/p>\n<p>Hab\u00eda perdido varios novios por este problema. Algunos de los hombres que se acercaban a ella decid\u00edan cortar su relaci\u00f3n porque no pod\u00edan comprender cu\u00e1l era la raz\u00f3n que empujaba a una hermosa mujer a mojar la cama. Todos los esfuerzos de su difunta madre por solventar su incontinencia hab\u00edan resultado en vano. Tremendamente preocupada, la se\u00f1orita Anyanwu decidi\u00f3 acudir a La SCOAN en busca de intervenci\u00f3n divina. El esp\u00edritu de Dios la localiz\u00f3 entre los asistentes y el profeta T.B. Joshua percibi\u00f3 su presencia, dirigi\u00e9ndose a ella con palabras prof\u00e9ticas:<\/p>\n<p style=\"text-align:center\">\u00ab<em>Hay hoy aqu\u00ed una mujer que tiene una incontinencia incontrolable.\u00bb<\/em><\/p>\n<p>Sorprendida porque hubiera podido dejar expuesto un problema que ella ocultaba con celo, dio un paso al frente y confirm\u00f3 las palabras del profeta.<\/p>\n<p>En el nombre de Jes\u00fas fue liberada, mientras el esp\u00edritu arrojaba a la joven al suelo resisti\u00e9ndose a salir de ella. Una vez hubo sido liberada, so\u00f1\u00f3 con una mujer que avanzaba hacia ella, y por primera vez se vio capaz de vencerla. \u00a1Y con una sonrisa deslumbrante nos refiri\u00f3 que no hab\u00eda vuelto a mojar la cama desde entonces! Dando gracias a Dios por su liberaci\u00f3n, Onyinye anim\u00f3 a la gente del mundo entero a poner su esperanza siempre en Dios y a depender de \u00c9l para todo.<\/p>\n<p style=\"text-align:center\"><strong>\u00a0EL AGUA DE LA MA\u00d1ANA INSPIR\u00d3 EL AVANCE EN SU CARRERA<\/strong><\/p>\n<p>Kofi Enoch Awayiwu, de Ghana, era guardia de seguridad. Hab\u00eda empezado su carrera en 1999, momento en el que la vida le mostraba su cara m\u00e1s amarga, ya que se las ven\u00eda y se las deseaba para sacar adelante a su familia. En un momento dado, una mujer le habl\u00f3 de <em>Emmanuel TV<\/em> y le hizo entrega del <em>Agua de la Ma\u00f1ana<\/em>, que \u00e9l comenz\u00f3 a ministrarse con fe.<\/p>\n<figure id=\"attachment_2238\" aria-describedby=\"caption-attachment-2238\" style=\"width: 285px\" class=\"wp-caption alignright\"><a href=\"https:\/\/tbjoshuaes.files.wordpress.com\/2016\/03\/mr-kofi-enoch-awayiwu.jpg\" rel=\"attachment wp-att-2238\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2238\" src=\"https:\/\/tbjoshuaes.files.wordpress.com\/2016\/03\/mr-kofi-enoch-awayiwu.jpg?w=300\" alt=\"EL SE\u00d1OR KOFI ENOCH AWAYIWU\" width=\"285\" height=\"191\" \/><\/a><figcaption id=\"caption-attachment-2238\" class=\"wp-caption-text\">EL SE\u00d1OR KOFI ENOCH AWAYIWU<\/figcaption><\/figure>\n<p>Tras un tiempo, fue ascendido a Supervisor de Seguridad. Sigui\u00f3 ministr\u00e1ndose el <em>Agua de la Ma\u00f1ana<\/em>, y se le present\u00f3 otra oportunidad en otra empresa, que le ofreci\u00f3 el puesto de Director de Operaciones y Marketing, puesto que ven\u00eda acompa\u00f1ado de una mayor remuneraci\u00f3n.<\/p>\n<p>Su fe en Dios sigui\u00f3 creciendo mientras continu\u00f3 orando con el profeta T.B. Joshua a trav\u00e9s de <em>Emmanuel TV<\/em>. Fue la inspiraci\u00f3n del <em>Agua de la Ma\u00f1ana<\/em> la que lo anim\u00f3 a crear su propia empresa de seguridad. Aunque no pose\u00eda en aquel momento el t\u00edtulo requerido por el Ministerio del Interior, consigui\u00f3 firmar un contrato con una importante franquicia de \u00e1mbito internacional. R\u00e1pidamente solicit\u00f3 el pertinente permiso ministr\u00e1ndose el <em>Agua de la Ma\u00f1ana<\/em>, aunque los funcionarios le dec\u00edan que iba a ser pr\u00e1cticamente imposible que lo consiguiera el mismo d\u00eda que lo hab\u00eda solicitado. Pero su fe obtuvo recompensa cuando el Ministro del Interior se present\u00f3 inesperadamente y firm\u00f3 el permiso que le permiti\u00f3 crear su empresa de seguridad. En la actualidad, es due\u00f1o de su propia compa\u00f1\u00eda y da empleo a otras personas. Est\u00e1 muy agradecido a Dios por haberle ayudado a trav\u00e9s de La SCOAN, y aconseja a la congregaci\u00f3n que siga con fidelidad <em>Emmanuel TV <\/em>para orar con el hombre de Dios.<\/p>\n<p style=\"text-align:center\"><strong>UN AUTOM\u00d3VIL REGALO DEL CIELO<\/strong><\/p>\n<p>La vida de Abiola Ogunade, humilde electricista de Nigeria, dio un giro inesperado cuando entr\u00f3 en contacto con el <em>Agua de la Ma\u00f1ana<\/em> y las <em>Calcoman\u00edas de la Unci\u00f3n<\/em> del ministerio de T.B. Joshua. Para \u00e9l, el d\u00eda a d\u00eda era una dura lucha, cargando a la espalda con su pesada bolsa de herramientas y utilizando para deslazase el transporte p\u00fablico de Lagos.<\/p>\n<figure id=\"attachment_2239\" aria-describedby=\"caption-attachment-2239\" style=\"width: 287px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-abiola-ogunade.jpg\" rel=\"attachment wp-att-2239\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2239\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-abiola-ogunade.jpg?w=300\" alt=\"EL SE\u00d1OR ABIOLA OGUNADE\" width=\"287\" height=\"206\" \/><\/a><figcaption id=\"caption-attachment-2239\" class=\"wp-caption-text\">EL SE\u00d1OR ABIOLA OGUNADE<\/figcaption><\/figure>\n<p>Como electricista ten\u00eda que desplazarse entre los domicilios de sus clientes, y necesitaba con urgencia mejorar su movilidad. Contemplaba a quienes viajaban en su autom\u00f3vil y so\u00f1aba con c\u00f3mo ser\u00eda tener el suyo propio. Algo relegado al dominio de los sue\u00f1os se hizo realidad cuando acudi\u00f3 a La SCOAN y recibi\u00f3 <em>El agua de la Ma\u00f1ana <\/em>y las <em>Calcoman\u00edas de la Unci\u00f3n.<\/em> Se ministr\u00f3 el <em>Agua de la Ma\u00f1ana<\/em> en nombre de Jes\u00fas y or\u00f3 con las <em>Calcoman\u00edas de la Unci\u00f3n<\/em>, confiado en que las personas con fe ven la gloria de Dios en sus vidas. El Se\u00f1or respondi\u00f3 a sus plegarias antes de lo que se esperaba, ya que, a la ma\u00f1ana siguiente, un pariente suyo que viv\u00eda en EE.UU. le envi\u00f3 una foto de un autom\u00f3vil nuevo, dici\u00e9ndole: \u00ab<em>\u00bfTe gusta? \u00a1Pues es tuyo!\u00bb <\/em>Un mes despu\u00e9s, el autom\u00f3vil llegaba a Nigeria.<\/p>\n<p>El se\u00f1or Ogunade mostr\u00f3 orgulloso las llaves y la documentaci\u00f3n de su auto ante la congregaci\u00f3n, y aconsej\u00f3 a los j\u00f3venes que se centren en Dios y que tengan fe en \u00c9l, para que puedan recibir sus bendiciones.<\/p>\n<p style=\"text-align:center\"><strong>\u00a0TARJETA ROJA A LA ESPONDILITIS CERVICAL<\/strong><\/p>\n<p>Cletus Eze, oriundo de Enugu, Nigieria, padec\u00eda de rigidez cervical y par\u00e1lisis parcial como resultado de un accidente que sufri\u00f3 a\u00f1os atr\u00e1s y que afect\u00f3 a su espina dorsal.<\/p>\n<figure id=\"attachment_2240\" aria-describedby=\"caption-attachment-2240\" style=\"width: 214px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-cletus-eze-1.jpg\" rel=\"attachment wp-att-2240\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2240\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-cletus-eze-1.jpg?w=214\" alt=\"EL SE\u00d1OR CLETUS EZE\" width=\"214\" height=\"300\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-cletus-eze-1.jpg 342w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-cletus-eze-1-214x300.jpg 214w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-cletus-eze-1-200x280.jpg 200w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><figcaption id=\"caption-attachment-2240\" class=\"wp-caption-text\">EL SE\u00d1OR CLETUS EZE<\/figcaption><\/figure>\n<p>Poco despu\u00e9s le diagnosticaron espondilitis cervical y qued\u00f3 condenado a ser una carga para su familia.<\/p>\n<p>Viaj\u00f3 a la India para someterse a una operaci\u00f3n, pero el resultado fue nefasto porque empeor\u00f3, y tras convencerse de que no pod\u00eda recibir ayuda m\u00e9dica, decidi\u00f3 visitar La SCOAN. Para \u00e9l fue una cita concertada por el Se\u00f1or, ya que pudo orar con el hombre de Dios.<\/p>\n<p>Dios le someti\u00f3 a una operaci\u00f3n espiritual que le liber\u00f3 de un estado que lo hab\u00eda condenado a la inutilidad durante un a\u00f1o y medio. Describir\u00eda m\u00e1s tarde as\u00ed el modo en que recibi\u00f3 la sanidad: \u00ab<em>Cuando el hombre de Dios or\u00f3 por m\u00ed, experiment\u00e9 una sensaci\u00f3n diferente y me di cuenta de que pod\u00eda mover el cuello libremente\u00bb<\/em>. Las cargas, el dolor, el collar\u00edn\u2026 pudo deshacerse de todo ello.<\/p>\n<p>Con su agilidad recuperada, el se\u00f1or Eze anima a todo el mundo a tener fe en Dios, por dura que sea la situaci\u00f3n en que se halle inmersos.<\/p>\n<p style=\"text-align:center\"><strong>BENDICIONES MARITALES Y AFECTO RESTAURADOS<\/strong><\/p>\n<p>El se\u00f1or y la se\u00f1ora Bashumika de Tanzania llevaban casados doce a\u00f1os, pero no hab\u00eda cari\u00f1o entre ellos, hasta el punto de que llevaban separados ya cinco a\u00f1os por no hallar el modo de solucionar sus diferencias. La se\u00f1ora Bashumika, una mujer hermosa, se ve\u00eda pr\u00e1cticamente confinada en su casa porque donde quiera que fuese, se le acusaba de querer robarle el marido a otras mujeres.<\/p>\n<figure id=\"attachment_2241\" aria-describedby=\"caption-attachment-2241\" style=\"width: 305px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-mrs-loenard-david-bashumika.jpg\" rel=\"attachment wp-att-2241\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2241\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-mrs-loenard-david-bashumika.jpg?w=300\" alt=\"EL SE\u00d1OR Y LA SE\u00d1ORA LEONARD DAVID BASHUMIKA\" width=\"305\" height=\"219\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-mrs-loenard-david-bashumika.jpg 471w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-mrs-loenard-david-bashumika-300x214.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/mr-mrs-loenard-david-bashumika-200x143.jpg 200w\" sizes=\"auto, (max-width: 305px) 100vw, 305px\" \/><\/a><figcaption id=\"caption-attachment-2241\" class=\"wp-caption-text\">EL SE\u00d1OR Y LA SE\u00d1ORA LEONARD DAVID BASHUMIKA<\/figcaption><\/figure>\n<p>Los problemas la condujeron a La SCOAN, donde recibi\u00f3 el <em>Agua de la Ma\u00f1ana <\/em> y con ella volvi\u00f3 a su pa\u00eds de origen, Tanzania, pidi\u00e9ndole a Dios que la ayudara a reparar su matrimonio. Tras un tiempo, la pareja volvi\u00f3 a unirse durante unos meses, pero sus discusiones empezaron de nuevo. El se\u00f1or Bashumika empez\u00f3 a sospechar que deb\u00eda haber algo m\u00e1s, y se vio ratificado en su opini\u00f3n cuando su esposa lo llam\u00f3 desde China para decirle que, cada vez que se acostaba para dormir, so\u00f1aba con que hab\u00eda una enorme serpiente tumbada a su lado.<\/p>\n<p>Ese sue\u00f1o, junto con otras desagradables experiencias, convenci\u00f3 a la pareja de que deb\u00edan acudir a La SCOAN. Durante un servicio dominical, el hombre de Dios pronunci\u00f3 unas palabras prof\u00e9ticas sobre su problema, y les pidi\u00f3 que se mostraran ante la comunidad. Cuando la se\u00f1ora Bashumika se acercaba, inesperadamente ech\u00f3 a correr para alejarse del profeta. Tras la liberaci\u00f3n confes\u00f3 que hab\u00eda huido del hombre de Dios porque le hab\u00eda visto conduciendo un cami\u00f3n enorme hacia ella, una confirmaci\u00f3n de la naturaleza arrasadora de las bendiciones de Dios a trav\u00e9s del Profeta T.B. Joshua. En la actualidad, la pareja est\u00e1 disfrutando de su matrimonio y ha vuelto a encender el fuego del amor que los uni\u00f3 como marido y mujer.<\/p>\n<p><strong><em>\u00abHermanos, no hay l\u00edmites para lo que nosotros como cristianos podemos lograr cuando creemos en Dios con todo nuestro coraz\u00f3n. vivir una mentira es lo que nos ha privado de la fruta madura de la que disfrutar\u00edamos estando en el lugar que Dios nos tiene reservado. y ese lugar, el lugar donde Dios quiere que estemos, es donde est\u00e1 nuestro coraz\u00f3n.<\/em><\/strong><\/p>\n<p style=\"text-align:center\"><strong><em>\u00a1Emmanuel!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0El profeta T.B. Joshua revel\u00f3 el secreto que se esconde tras la aplicaci\u00f3n de la fe en la vida de un verdadero cristiano con el mensaje titulado \u00abLa Cristiandad\u00a0reside en el coraz\u00f3n\u00bb, durante el servicio dominical del 21 de febrero de 2016, acompa\u00f1ado por las canciones de adoraci\u00f3n que, interpretadas por el coro, acondicionaron la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[3,1],"tags":[1196,1197,1198,1049,1199,1057,1200,1201,1202,1203],"class_list":["post-2235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","category-uncategorized","tag-automovil","tag-bendiciones","tag-cielo","tag-corazon","tag-cristianismo","tag-espiritu","tag-espondilitis-cervical","tag-regalo","tag-tarjeta-roja","tag-testimonios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"og:description\" content=\"\u00a0El profeta T.B. Joshua revel\u00f3 el secreto que se esconde tras la aplicaci\u00f3n de la fe en la vida de un verdadero cristiano con el mensaje titulado \u00abLa Cristiandad\u00a0reside en el coraz\u00f3n\u00bb, durante el servicio dominical del 21 de febrero de 2016, acompa\u00f1ado por las canciones de adoraci\u00f3n que, interpretadas por el coro, acondicionaron la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/\" \/>\n<meta property=\"og:site_name\" content=\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tbjministries\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-01T16:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"383\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SCOAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:site\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SCOAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/\"},\"author\":{\"name\":\"SCOAN\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/60e4166936306ab3c7ff663fa3ce7658\"},\"headline\":\"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N\",\"datePublished\":\"2016-03-01T16:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/\"},\"wordCount\":1911,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/03\\\/daddy1.jpg\",\"keywords\":[\"autom\u00f3vil\",\"bendiciones\",\"CIELO\",\"CORAZON\",\"cristianismo\",\"espiritu\",\"ESPONDILITIS CERVICAL\",\"REGALO\",\"TARJETA ROJA\",\"testimonios\"],\"articleSection\":[\"Sin categorizar\",\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/\",\"name\":\"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/03\\\/daddy1.jpg\",\"datePublished\":\"2016-03-01T16:00:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/03\\\/daddy1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/03\\\/daddy1.jpg\",\"width\":500,\"height\":383,\"caption\":\"EL PROFETA T.B. JOSHUA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/el-cristianismo-reside-en-el-corazon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"description\":\"Founded by Prophet TB Joshua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"width\":186,\"height\":85,\"caption\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tbjministries\",\"https:\\\/\\\/x.com\\\/SCOANTBJoshua\",\"https:\\\/\\\/www.instagram.com\\\/tbjoshua\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/60e4166936306ab3c7ff663fa3ce7658\",\"name\":\"SCOAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g\",\"caption\":\"SCOAN\"},\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/author\\\/ilyap51\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/","og_locale":"es_ES","og_type":"article","og_title":"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","og_description":"\u00a0El profeta T.B. Joshua revel\u00f3 el secreto que se esconde tras la aplicaci\u00f3n de la fe en la vida de un verdadero cristiano con el mensaje titulado \u00abLa Cristiandad\u00a0reside en el coraz\u00f3n\u00bb, durante el servicio dominical del 21 de febrero de 2016, acompa\u00f1ado por las canciones de adoraci\u00f3n que, interpretadas por el coro, acondicionaron la [&hellip;]","og_url":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/","og_site_name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","article_publisher":"https:\/\/www.facebook.com\/tbjministries","article_published_time":"2016-03-01T16:00:34+00:00","og_image":[{"width":500,"height":383,"url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg","type":"image\/jpeg"}],"author":"SCOAN","twitter_card":"summary_large_image","twitter_creator":"@SCOANTBJoshua","twitter_site":"@SCOANTBJoshua","twitter_misc":{"Escrito por":"SCOAN","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#article","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/"},"author":{"name":"SCOAN","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/60e4166936306ab3c7ff663fa3ce7658"},"headline":"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N","datePublished":"2016-03-01T16:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/"},"wordCount":1911,"commentCount":0,"publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"image":{"@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg","keywords":["autom\u00f3vil","bendiciones","CIELO","CORAZON","cristianismo","espiritu","ESPONDILITIS CERVICAL","REGALO","TARJETA ROJA","testimonios"],"articleSection":["Sin categorizar","Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/","url":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/","name":"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#primaryimage"},"image":{"@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg","datePublished":"2016-03-01T16:00:34+00:00","breadcrumb":{"@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#primaryimage","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/03\/daddy1.jpg","width":500,"height":383,"caption":"EL PROFETA T.B. JOSHUA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scoan.org\/es\/el-cristianismo-reside-en-el-corazon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scoan.org\/es\/"},{"@type":"ListItem","position":2,"name":"LA CRISTIANDAD RESIDE EN EL CORAZ\u00d3N"}]},{"@type":"WebSite","@id":"https:\/\/www.scoan.org\/es\/#website","url":"https:\/\/www.scoan.org\/es\/","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"Founded by Prophet TB Joshua","publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scoan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scoan.org\/es\/#organization","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","url":"https:\/\/www.scoan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","width":186,"height":85,"caption":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua"},"image":{"@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tbjministries","https:\/\/x.com\/SCOANTBJoshua","https:\/\/www.instagram.com\/tbjoshua"]},{"@type":"Person","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/60e4166936306ab3c7ff663fa3ce7658","name":"SCOAN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55b13ce8d7680014f28ada0249959b684098657f914e4d4cd0efc2297b1953b5?s=96&d=mm&r=g","caption":"SCOAN"},"url":"https:\/\/www.scoan.org\/es\/author\/ilyap51\/"}]}},"_links":{"self":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/2235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/comments?post=2235"}],"version-history":[{"count":0,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/2235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media\/2236"}],"wp:attachment":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media?parent=2235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/categories?post=2235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/tags?post=2235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}