{"id":15496,"date":"2017-07-20T10:35:32","date_gmt":"2017-07-20T10:35:32","guid":{"rendered":"https:\/\/www.scoan.org\/?p=15496\/"},"modified":"2017-07-20T10:43:34","modified_gmt":"2017-07-20T10:43:34","slug":"se-un-imitador-de-dios","status":"publish","type":"post","link":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/","title":{"rendered":"S\u00c9 UN IMITADOR DE DIOS"},"content":{"rendered":"<p>La atm\u00f3sfera vibraba con la espectacular y vivificante interpretaci\u00f3n del coro de La SCOAN, que animaba a una congregaci\u00f3n que expres\u00f3 su deferencia a Dios mediante hermosas canciones de alabanza y adoraci\u00f3n uni\u00e9ndose a sus voces. Los testimonios que se compartieron despu\u00e9s iluminaron el d\u00eda, recordando a los hijos de Dios que \u00c9l a\u00fan est\u00e1 diciendo algo, no importa la situaci\u00f3n que est\u00e9n atravesando.<\/p>\n<p>El Profeta T.B. Joshua comprometi\u00f3 el pensamiento de los congregados exhort\u00e1ndoles a permitir que la Palabra de Dios eche ra\u00edces profundas en su coraz\u00f3n. En su opini\u00f3n, el \u00fanico modo en que los Cristianos puedan tener un ininterrumpido acercamiento a Dios es permitiendo que Su Palabra more en sus corazones: <strong><em>\u00abCuando la Palabra mora en ti, te gobierna y vive en ti, produce fruto de oraci\u00f3n. La Palabra dominando en ti, se convierte en el Se\u00f1or\u00edo de Cristo en ti. Debes dejar que la Palabra tenga derecho de paso en tu vida. Dejar que la Palabra tenga derecho de paso en tu vida es dejar que Cristo mismo tenga derecho de paso en tu vida\u00bb.<\/em><\/strong><\/p>\n<p>Descontento con la desesperada negativa de los hombres a esperar al Se\u00f1or, el hombre de Dios observ\u00f3 que las personas se copian unas a otras s\u00f3lo porque quieren ser importantes. Advirti\u00f3 que la prosperidad no es una evidencia de que alguien est\u00e9 ejecutando su llamado de Dios. Dijo: <strong><em>\u00ab<\/em><\/strong><strong><em>La prosperidad no es la evidencia de est\u00e9s llamado por el Cielo para hacer ese trabajo. Puedes ser muy rico, muy pr\u00f3spero en lo que est\u00e1s haciendo, pero eso no demuestra que hayas sido llamado a hacerlo; el final probar\u00e1 que lo que est\u00e1s haciendo es tu llamado de Dios\u2026 Hoy, todo se copia porque nadie es lo suficientemente paciente para esperar por Dios\u2026 el principiante no es el due\u00f1o, sino el consumador<\/em><\/strong><strong><em>\u00bb<\/em><\/strong><strong><em>.<\/em><\/strong><\/p>\n<p>Para concluir, el hombre de Dios inst\u00f3 a los Cristianos a unirse y a vivir en amor, a amar a sus enemigos y a sus semejantes. Explic\u00f3 que nuestros semejantes pueden ser aquellos que no comparten nuestra misma fe. Debemos amarlos a todos. Esta es la ense\u00f1anza que Jes\u00fas nos dej\u00f3: <strong><em>\u00ab<\/em><\/strong><strong><em>Cristianos unidos por el amor, su amor ve m\u00e1s all\u00e1 de los enemigos y el ataque, pero la ley religiosa no ve m\u00e1s all\u00e1 del ataque\u2026 lo que les haces a ellos, ellos te lo hacen a ti<\/em><\/strong><strong><em>\u00bb<\/em><\/strong><strong><em>.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>TESTIMONIOS<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a1DESCOMUNAL \u00daLCERA DE EST\u00d3MAGO SANADA!<\/strong><strong>\u00a0<\/strong><\/p>\n<p>Un lunes por la ma\u00f1ana iba a de camino al trabajo cuando de pronto sinti\u00f3 que ten\u00eda fiebre y tuvo que volverse a casa, pensando que al d\u00eda siguiente ya estar\u00eda en condiciones de trabajar. Pero al llegar la noche de ese mismo d\u00eda, el Profesor Anene tuvo que ir al hospital de un amigo suyo porque no mejoraba. Al d\u00eda siguiente, martes, recibi\u00f3 tratamiento contra la malaria, pero a pesar de ello, segu\u00eda sinti\u00e9ndose mal. Era ya mi\u00e9rcoles cuando la tragedia se desencaden\u00f3. Sinti\u00f3 una persistente necesidad de vomitar, y descubri\u00f3 que hab\u00eda manchado la cama. Tard\u00f3 un momento en darse cuenta de que estaba echando sangre por el ano por culpa de una tremenda \u00falcera de est\u00f3mago.<\/p>\n<figure id=\"attachment_15240\" aria-describedby=\"caption-attachment-15240\" style=\"width: 485px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15240\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY-300x195.jpg\" alt=\"\" width=\"485\" height=\"315\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY-300x195.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY-768x499.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY-200x130.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY-400x260.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY-600x390.jpg 600w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY-800x520.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROF.-ANENE-FAMILY-MW-TESTIMONY.jpg 1013w\" sizes=\"auto, (max-width: 485px) 100vw, 485px\" \/><figcaption id=\"caption-attachment-15240\" class=\"wp-caption-text\">El Profesor Anene y su familia<\/figcaption><\/figure>\n<p>El Profesor Anene se encontr\u00f3 presa de su estado de salud y del miedo a lo desconocido. Sab\u00eda que sangrar por el ano era s\u00edntoma de un problema importante de salud que requer\u00eda atenci\u00f3n urgente. El sangrado continu\u00f3, dej\u00e1ndolo demacrado y con la tensi\u00f3n por los suelos. Estaba vivo, pero muy cerca de recibir el fr\u00edo abrazo de la muerte. Su hermano menor, m\u00e9dico de profesi\u00f3n, le sugiri\u00f3 que buscara atenci\u00f3n m\u00e9dica especializada, y por ello fue trasladado al Hospital Universitario del Estado de Anambra.<\/p>\n<p>Dos d\u00edas llevaba ingresado y hab\u00eda perdido casi toda la sangre del cuerpo, su tensi\u00f3n arterial hab\u00eda empeorado y su recuento sangu\u00edneo era muy bajo, de modo que el profesor comenz\u00f3 a perder el sentido. Hablando para <em>Emmanuel TV<\/em>, su hija Jachimma dijo que mientras su padre vomitaba y perd\u00eda sangre, no hab\u00eda comido absolutamente nada. Cuando lleg\u00f3 al hospital en el que hab\u00eda sido ingresado en Urgencias, se encontr\u00f3 con un hombre totalmente an\u00e9mico que hab\u00eda estado a punto de perder el conocimiento, y no se lo pens\u00f3; no iba a permitir que la muerte repentina le robase a su padre. Corri\u00f3 al auto, busc\u00f3 el <em>Agua de La Ma\u00f1ana<\/em> que ten\u00eda all\u00ed y volvi\u00f3 junto a \u00e9l.<\/p>\n<p>Al darle el Agua de La Ma\u00f1ana, le pidi\u00f3 que bebiera y mientras lo hac\u00eda, le pidi\u00f3 que recibiera su sanidad en nombre de Jesucristo. Poco despu\u00e9s, el Profesor Anene sinti\u00f3 necesidad de ir al ba\u00f1o y se encontr\u00f3 con que su orina y sus heces, antes de color rojo, hab\u00edan cambiado de pronto, se\u00f1al de que una rehabilitaci\u00f3n espiritual estaba ocurriendo. Horas despu\u00e9s, el color de sus emisiones hab\u00eda vuelto a su estado normal.<\/p>\n<p>Su hija mayor tambi\u00e9n contribuy\u00f3 en el testimonio refiriendo a los espectadores de todo el mundo que escribi\u00f3 el nombre de su padre en la <em>Tarjeta de Felicitaci\u00f3n<\/em> que se hab\u00eda llevado de La SCOAN e hizo que su hermano menor le leyese el contenido de la tarjeta a su padre quien, aun estando en el hospital, llevaba puesto su <em>Brazalete de la Fe <\/em>que Jachima le hab\u00eda prestado. Todo ello culmin\u00f3 con la r\u00e1pida recuperaci\u00f3n y sanidad del Profesor Chukwunonye Anene, para la gloria del Dios Hacedor de milagros.<\/p>\n<p>El consejo que el Profesor Anene, distinguido acad\u00e9mico y tiempo atr\u00e1s administrador universitario, quiso dejar para todos fue sencillo: <strong><em>\u00ab<\/em><\/strong><strong><em>Cree y ver\u00e1s que los milagros y el progreso te seguir\u00e1n; tan s\u00f3lo cree<\/em><\/strong><strong><em>\u00bb<\/em><\/strong><strong><em>.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15243\" aria-describedby=\"caption-attachment-15243\" style=\"width: 469px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15243\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-300x210.jpg\" alt=\"\" width=\"469\" height=\"328\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-300x210.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-768x537.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-1024x716.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-200x140.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-400x280.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-600x419.jpg 600w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY-800x559.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/HON.-TOVIE-MW-TESTIMONY.jpg 1080w\" sizes=\"auto, (max-width: 469px) 100vw, 469px\" \/><figcaption id=\"caption-attachment-15243\" class=\"wp-caption-text\">El se\u00f1or Tovie<\/figcaption><\/figure>\n<p><strong>UN GLORIOSO CAMBIO DE RUMBO\u00a0<\/strong><br \/>\nTovie estaba siempre en lo mismo. Para \u00e9l, la belleza de la vida se encontraba en la diversi\u00f3n y el placer que obten\u00eda de salir con los amigos a clubes, de beber y de retozar con distintas mujeres. Como ingeniero naval, la mayor\u00eda de sus ingresos se iban en esta clase de vida fr\u00edvola. Sigui\u00f3 arranc\u00e1ndole brillo a la ciudad con su ostentaci\u00f3n y su glamour hasta que lo peor lo alcanz\u00f3 como una bala, sin que \u00e9l se lo esperara; su estimada fuente de ingresos desapareci\u00f3. Quiz\u00e1s nunca se hab\u00eda parado a pensar que todas las cosas buenas terminan alg\u00fan d\u00eda. Perder el trabajo fue un golpe tan duro que lo dej\u00f3 tambale\u00e1ndose, deambulando en distintas direcciones en busca de una soluci\u00f3n.<\/p>\n<p>Este joven nigeriano comenz\u00f3 a visitar doctores nativos, pensando que semejante infortunio podr\u00eda ser revertido con su intervenci\u00f3n, y se gast\u00f3 una fortuna procur\u00e1ndose toda clase de amuletos que supuestamente ten\u00edan la capacidad de hacerle encontrar un trabajo a\u00fan mejor que el que ten\u00eda. Uno de esos doctores le entreg\u00f3 un amuleto con el que deb\u00eda ba\u00f1arse a medianoche, utilizando para ello una determinada clase de esponja local. Despu\u00e9s de haber sido estafado por estos doctores nativos cuyos amuletos no eran m\u00e1s que enga\u00f1os fetichistas, Tovie volvi\u00f3 a la casa familiar en lo que podr\u00eda ser descrito como una ca\u00edda auto infligida de la gracia al suelo.<\/p>\n<p>Con una esposa y cuatro hijos viviendo en una \u00fanica habitaci\u00f3n que ya ni siquiera pod\u00edan pagar, mudarse a casa de su padre fue una p\u00edldora muy amarga, pero no ten\u00eda otra elecci\u00f3n. No le quedaba m\u00e1s remedio que dar la cara y acarrear con las consecuencias de sus actos pasados, en la esperanza de que Dios proveer\u00eda una segunda oportunidad para \u00e9l con la que enmendar sus errores. Aunque ten\u00eda acceso a <em>Emmanuel TV<\/em>, sus sentidos estaban completamente abotagados por fuerzas que escapaban a su control. Hab\u00eda sido manipulado por los que se llaman a s\u00ed mismos doctores nativos, llegando incluso a vender un coche que ten\u00eda un valor de quinientas mil nairas por la rid\u00edcula y risible suma de treinta mil, solo para disponer del dinero necesario para un amuleto especial que uno de ellos iba a prepararle expresamente.<\/p>\n<p>Cuando el amuleto demostr\u00f3 ser un fracaso monumental, el enga\u00f1o le explot\u00f3 en la cara y se dio cuenta de que hab\u00eda sido estafado por un tipo m\u00e1s listo que \u00e9l que se otorgaba el t\u00edtulo de doctor nativo. Tambi\u00e9n fue aquel el momento en que, aconsejado por su esposa, la idea de ver <em>Emmanuel TV<\/em> comenz\u00f3 a arraigar en su cabeza. El consejo de su esposa result\u00f3 ser certero y dio sus frutos. Despu\u00e9s de ver la poderosa demostraci\u00f3n del poder de Dios a trav\u00e9s de <em>Emmanuel TV<\/em>, visit\u00f3 La SCOAN y recibi\u00f3 <em>Agua de La Ma\u00f1ana<\/em>. Tras cuatro d\u00edas de ministr\u00e1rsela y orar con el <em>Agua de La Ma\u00f1ana<\/em> lleg\u00f3 el tan esperado avance; el trabajo que llevaba buscando desde hac\u00eda cuatro a\u00f1os y por el que hab\u00eda andado de ac\u00e1 para all\u00e1, corriendo de un doctor nativo al otro, ba\u00f1\u00e1ndose con toda clase de pociones, por fin le lleg\u00f3 servido en la bandeja que le ofreci\u00f3 su propia fe. Tovie recuper\u00f3 su trabajo como ingeniero naval.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_15246\" aria-describedby=\"caption-attachment-15246\" style=\"width: 303px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15246\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MRS-NANSY-MW-TWSTIMONY--212x300.jpg\" alt=\"\" width=\"303\" height=\"429\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MRS-NANSY-MW-TWSTIMONY--212x300.jpg 212w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MRS-NANSY-MW-TWSTIMONY--200x284.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MRS-NANSY-MW-TWSTIMONY--400x567.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MRS-NANSY-MW-TWSTIMONY--600x851.jpg 600w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MRS-NANSY-MW-TWSTIMONY-.jpg 720w\" sizes=\"auto, (max-width: 303px) 100vw, 303px\" \/><figcaption id=\"caption-attachment-15246\" class=\"wp-caption-text\">La se\u00f1ora Nancy<\/figcaption><\/figure>\n<p><strong>\u00ab<\/strong><strong>LA LIMITACI\u00d3N DESAPARECI\u00d3 DE MI VIDA<\/strong><strong>\u00bb<\/strong><\/p>\n<p>Nancy se hab\u00eda esforzado por aprobar el examen necesario para su profesi\u00f3n conocido con el nombre de Auditor Certificado de Cuentas y Gesti\u00f3n Financiera. Aunque hab\u00eda aprobado los diecis\u00e9is ex\u00e1menes preliminares, le quedaba una prueba por salvar, que era la de competencias. Una vez aprobada, le servir\u00eda para que le dieran el correspondiente certificado. Cada vez que se presentaba a esa prueba, so\u00f1aba con que deambulaba en el cuarto de ba\u00f1o. Se hab\u00eda presentado al examen en siete ocasiones, y suspendido en todas ellas. Necesitaba un c\u00f3mputo total de veinticinco puntos para aprobar, y ella siempre se quedaba en veintid\u00f3s o veinticuatro, lo cual le resultaba ya tremendamente embarazoso a esta ghanesa, porque la mayor\u00eda de la gente a la que ella daba clases particulares aprobaba el examen, mientras que ella segu\u00eda fracasando.<\/p>\n<p>Todo sigui\u00f3 as\u00ed hasta que se person\u00f3 en La SCOAN y recibi\u00f3 el <em>Agua de La Ma\u00f1ana<\/em>, que se ministr\u00f3 mientras oraba con devoci\u00f3n. Cuando ya se acercaba de nuevo la fecha del examen, Nancy not\u00f3 algo; ya no ten\u00eda el sue\u00f1o en el que se ve\u00eda deambulando por el cuarto de ba\u00f1o. Se present\u00f3 al examen en noviembre y cuando se publicaron los resultados en diciembre, \u00a1hab\u00eda aprobado!<\/p>\n<p>Mostrando su certificado profesional durante su testimonio del pasado domingo, Nancy confirm\u00f3 que ya era Auditor Certificado de Cuentas y Gesti\u00f3n Financiera, nivel Senior, un certificado que adem\u00e1s tiene validez internacional, lo cual le permitir\u00e1 ejercer su profesi\u00f3n en el extranjero.<\/p>\n<p><strong><em>\u00ab<\/em><\/strong><strong><em>Cuando est\u00e9s afligida, como lo estaba yo, corre a Dios y cree en nuestro Se\u00f1or Jesucristo y en Su poder de liberaci\u00f3n<\/em><\/strong><strong><em>\u00bb<\/em><\/strong><strong><em>.<\/em><\/strong><\/p>\n<figure id=\"attachment_15249\" aria-describedby=\"caption-attachment-15249\" style=\"width: 446px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15249\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI-300x224.jpg\" alt=\"\" width=\"446\" height=\"333\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI-300x224.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI-768x573.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI-200x149.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI-400x298.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI-600x448.jpg 600w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI-800x597.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR-MRS-NDUBISI.jpg 1000w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><figcaption id=\"caption-attachment-15249\" class=\"wp-caption-text\">El se\u00f1or y la se\u00f1ora Ndubuisi Nwokoye<\/figcaption><\/figure>\n<p><strong>DICHA CONYUGAL RESTAURADA<\/strong><\/p>\n<p>El se\u00f1or y la se\u00f1ora Ndubuisi Nwokoye ten\u00edan dificultades en su matrimonio y estaban a punto de permitir que su uni\u00f3n se derrumbara, ya que no sab\u00edan identificar qu\u00e9 estaba pasando. Ambos hac\u00edan esfuerzos por avivar el fuego casi apagado de su amor, pero sin lograrlo. El se\u00f1or Nwokoye adquiri\u00f3 la costumbre de volver tarde a casa; se quedaba con los amigos en el bar, bebiendo y dedic\u00e1ndose a otras actividades dif\u00edciles de aceptar. Apenas pasaba tiempo con su esposa y sus hijos, y cuanto m\u00e1s tiempo permanec\u00eda alejado de ellos, peor era su estado. Su negocio comenz\u00f3 a languidecer, lo que le oblig\u00f3 a vivir completamente al d\u00eda.<\/p>\n<p>La pareja segu\u00eda junta, pero no se imaginaban que su problema ten\u00eda una faceta espiritual hasta que decidieron visitar La SCOAN y el Profeta T.B. Joshua or\u00f3 por ellos, con lo que fueron liberados en nombre de Jes\u00fas. Tras su encuentro con el hombre de Dios, sus vidas cambiaron y comenzaron a prosperar en distintos aspectos. El se\u00f1or Nwokoye se dio cuenta, a ra\u00edz de esa liberaci\u00f3n, del maravilloso regalo que Dios le hab\u00eda hecho con su esposa, y el amor que ahora siente por ella es inconmensurable. Desde que visitaron La SCOAN, la paz, el amor mutuo y la comprensi\u00f3n reinan entre ellos.<\/p>\n<p>\u00c9l agradeci\u00f3 a Dios por restaurar el amor en su matrimonio y por haberle bendecido con un progreso econ\u00f3mico y con prosperidad en su negocio: <strong><em>\u00ab<\/em><\/strong><strong><em>Todos los hombres casados deben saber que el matrimonio es algo de Dios. No des de lado a tu esposa en tiempos de dificultad<\/em><\/strong><strong><em>\u00bb.<\/em><\/strong><\/p>\n<p><strong>\u00abVEND\u00cd MI VIDA AL DIABLO\u00bb. \u00a1CONFESIONES DE UN TRAFICANTE DE SERES HUMANOS!<\/strong><\/p>\n<figure id=\"attachment_15252\" aria-describedby=\"caption-attachment-15252\" style=\"width: 528px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15252\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1-300x214.jpg\" alt=\"\" width=\"528\" height=\"377\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1-300x214.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1-768x547.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1-200x142.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1-400x285.jpg 400w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1-600x427.jpg 600w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1-800x570.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/MR.-MUYIDEEN-DELIEVRANCE-TESTIMONY1.jpg 956w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><figcaption id=\"caption-attachment-15252\" class=\"wp-caption-text\">El se\u00f1or Situ Muyideen<\/figcaption><\/figure>\n<p>Las sirenas brillaban. Los helic\u00f3pteros acechaban. Una tropa de elite formada por agentes especiales rodeaba la casa. No hab\u00eda modo de escapar y, mientras hac\u00eda desaparecer por el inodoro lo que le quedaba de coca\u00edna, Situ Muyideen se preparaba para lo inevitable. Blandiendo sin temor sus diferentes armas de fuego, amenaz\u00f3 a la polic\u00eda que esperaba abajo con saltar y matarse si se mov\u00edan. Y salt\u00f3\u2026<\/p>\n<p>Siendo a\u00fan muy joven, Situ fue iniciado en un mundo de maldad. Su padre, que pertenec\u00eda a un culto secreto, le hizo en un brazo la marca letal de un escorpi\u00f3n, un s\u00edmbolo de poder demon\u00edaco que acab\u00f3 conduci\u00e9ndolo por un camino de destrucci\u00f3n. Siendo el \u00fanico hijo var\u00f3n de su padre, que ten\u00eda diecis\u00e9is esposas y cuarenta y siete hijas, fue un luchador desde el primer d\u00eda.<\/p>\n<p>En l escuela, era capaz de enfrentarse a veinte o treinta hombres adultos en una pelea. El esp\u00edritu de violencia le condujo a viajar sin sentir temor alguno al extranjero y a meterse en una vida de criminalidad hasta extremos inenarrables. Viajando de Nigeria a Libia, cruz\u00f3 el mar en un barco improvisado para llegar sin m\u00e1s ceremonia a Italia. Fue all\u00ed donde la perversidad del plan diab\u00f3lico para su vida comenz\u00f3 a manifestarse con toda crudeza.<\/p>\n<p>Traficando con drogas y seres humanos, Muyideen, conocido como CK, se hizo amigo de los hombres m\u00e1s peligrosos y letales de Europa. <em>\u00abVend\u00eda seres humanos sin dejar rastro\u00bb, <\/em>admiti\u00f3. <em>\u00abVend\u00eda mujeres j\u00f3venes a hombres mayores\u00bb<\/em>, explicaba, a\u00f1adiendo que esas mujeres drogaban a los hombres con las que las emparejaban para robarles todas sus pertenencias, negocio del que \u00e9l se quedaba con el cincuenta por ciento.<\/p>\n<p>Fue arrestado y encarcelado posteriormente durante una de esas operaciones, pero gracias a sus conexiones con la mafia, enseguida fue puesto en libertad y reubicado en Alemania. All\u00ed lleg\u00f3 a ser un conocido \u00abbar\u00f3n\u00bb de la droga. Sus m\u00e9todos para traficar con personas comenzaron a ser m\u00e1s avanzados; acordaba matrimonios entre inocentes alemanas con hombres que se divorciaban al poco y que obten\u00edan dinero con los inevitables procedimientos legales. Tambi\u00e9n enga\u00f1aba a mujeres f\u00edsicamente discapacitadas prometi\u00e9ndolas proporcionarles marido\u2026 un marido que las dejaba poco despu\u00e9s de haberse casado.<\/p>\n<p>En Alemania volvi\u00f3 a evitar la c\u00e1rcel, y emigr\u00f3 a Estados Unidos, donde se uni\u00f3 a un conocido se\u00f1or de la droga y su banda. Con los beneficios obtenidos de sus nefandas actividades, compr\u00f3 propiedades en distintos puntos de \u00a0Estados Unidos, y se cas\u00f3 con una noruega que trabajaba en la banca y tuvo con ella dos hijos. \u00a1Y cuando ella le pregunt\u00f3 de d\u00f3nde sacaba el dinero, le dijo que su padre era un rey muy rico en \u00c1frica!<\/p>\n<p>Sin embargo, un d\u00eda su esposa abri\u00f3 un paquete que le remitieron a su domicilio y se horroriz\u00f3 al encontrarlo lleno de coca\u00edna. Aturdida, dio parte a la polic\u00eda, que r\u00e1pidamente rode\u00f3 su casa. Muyideen salt\u00f3 desde el balc\u00f3n, pero fue detenido gracias a una red que lanz\u00f3 el helic\u00f3ptero y fue puesto en custodia. Lo deportaron a Nigeria, pero ni aun as\u00ed renunci\u00f3 a sus actividades criminales. Huy\u00f3 a Ghana y comenz\u00f3 a coordinar desde all\u00ed el tr\u00e1fico de seres humanos al resto del mundo.<\/p>\n<p>Fue en medio de todo esto cuando CK descubri\u00f3 <em>Emmanuel TV<\/em>, y decidi\u00f3 visitar La SCOAN. Su encuentro all\u00ed con el Profeta T.B. Joshua fue verdaderamente memorable. El demonio en su interior qued\u00f3 expuesto con un toque del hombre de Dios, y confes\u00f3 el caos que hab\u00eda provocado en su vida y la destrucci\u00f3n que hacer todo esto le hab\u00eda causado. Tras su liberaci\u00f3n, admiti\u00f3 entre l\u00e1grimas que satan\u00e1s lo hab\u00eda utilizado para destruir multitud de vidas en el pasado y llam\u00f3 a las personas a abrazar completamente a Cristo, ya que es el \u00fanico modo de disfrutar de la vida en abundancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La atm\u00f3sfera vibraba con la espectacular y vivificante interpretaci\u00f3n del coro de La SCOAN, que animaba a una congregaci\u00f3n que expres\u00f3 su deferencia a Dios mediante hermosas canciones de alabanza y adoraci\u00f3n uni\u00e9ndose a sus voces. Los testimonios que se compartieron despu\u00e9s iluminaron el d\u00eda, recordando a los hijos de Dios que \u00c9l a\u00fan est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":103,"featured_media":15236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[1436],"tags":[1038,83,994,1785,1045,4,1028,1765,17,1786,1068,1070,567,1203,1787],"class_list":["post-15496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emmanuel-tv-2","tag-adiccion","tag-africa","tag-agua-de-la-manana","tag-atadura","tag-bendicion","tag-emmanuel-tv","tag-esterilidad","tag-la-sinagoga-iglesia-de-todas-las-naciones","tag-lagos","tag-pactos","tag-progreso","tag-sanidad","tag-t-b-joshua","tag-testimonios","tag-ulcera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00c9 UN IMITADOR DE DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00c9 UN IMITADOR DE DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"og:description\" content=\"La atm\u00f3sfera vibraba con la espectacular y vivificante interpretaci\u00f3n del coro de La SCOAN, que animaba a una congregaci\u00f3n que expres\u00f3 su deferencia a Dios mediante hermosas canciones de alabanza y adoraci\u00f3n uni\u00e9ndose a sus voces. Los testimonios que se compartieron despu\u00e9s iluminaron el d\u00eda, recordando a los hijos de Dios que \u00c9l a\u00fan est\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tbjministries\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-20T10:35:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-20T10:43:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROPHET-T.B-JOSHUA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1056\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Johana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:site\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/\"},\"author\":{\"name\":\"Johana\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/15d5d70121df962845c5d2ba3a5faf33\"},\"headline\":\"S\u00c9 UN IMITADOR DE DIOS\",\"datePublished\":\"2017-07-20T10:35:32+00:00\",\"dateModified\":\"2017-07-20T10:43:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/\"},\"wordCount\":2952,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/07\\\/PROPHET-T.B-JOSHUA.jpg\",\"keywords\":[\"adicci\u00f3n\",\"africa\",\"AGUA DE LA MA\u00d1ANA\",\"Atadura\",\"bendicion\",\"Emmanuel TV\",\"esterilidad\",\"La Sinagoga Iglesia de Todas las Naciones\",\"Lagos\",\"Pactos\",\"progreso\",\"sanidad\",\"T.B Joshua\",\"testimonios\",\"\u00daLCERA\"],\"articleSection\":[\"EMMANUEL TV\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/\",\"name\":\"S\u00c9 UN IMITADOR DE DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/07\\\/PROPHET-T.B-JOSHUA.jpg\",\"datePublished\":\"2017-07-20T10:35:32+00:00\",\"dateModified\":\"2017-07-20T10:43:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/07\\\/PROPHET-T.B-JOSHUA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/07\\\/PROPHET-T.B-JOSHUA.jpg\",\"width\":1056,\"height\":719,\"caption\":\"Profeta T.B Joshua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/se-un-imitador-de-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00c9 UN IMITADOR DE DIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"description\":\"Founded by Prophet TB Joshua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"width\":186,\"height\":85,\"caption\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tbjministries\",\"https:\\\/\\\/x.com\\\/SCOANTBJoshua\",\"https:\\\/\\\/www.instagram.com\\\/tbjoshua\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/15d5d70121df962845c5d2ba3a5faf33\",\"name\":\"Johana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g\",\"caption\":\"Johana\"},\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/author\\\/johanamyegn-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00c9 UN IMITADOR DE DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00c9 UN IMITADOR DE DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","og_description":"La atm\u00f3sfera vibraba con la espectacular y vivificante interpretaci\u00f3n del coro de La SCOAN, que animaba a una congregaci\u00f3n que expres\u00f3 su deferencia a Dios mediante hermosas canciones de alabanza y adoraci\u00f3n uni\u00e9ndose a sus voces. Los testimonios que se compartieron despu\u00e9s iluminaron el d\u00eda, recordando a los hijos de Dios que \u00c9l a\u00fan est\u00e1 [&hellip;]","og_url":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/","og_site_name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","article_publisher":"https:\/\/www.facebook.com\/tbjministries","article_published_time":"2017-07-20T10:35:32+00:00","article_modified_time":"2017-07-20T10:43:34+00:00","og_image":[{"width":1056,"height":719,"url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROPHET-T.B-JOSHUA.jpg","type":"image\/jpeg"}],"author":"Johana","twitter_card":"summary_large_image","twitter_creator":"@SCOANTBJoshua","twitter_site":"@SCOANTBJoshua","twitter_misc":{"Escrito por":"Johana","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#article","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/"},"author":{"name":"Johana","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/15d5d70121df962845c5d2ba3a5faf33"},"headline":"S\u00c9 UN IMITADOR DE DIOS","datePublished":"2017-07-20T10:35:32+00:00","dateModified":"2017-07-20T10:43:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/"},"wordCount":2952,"commentCount":0,"publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"image":{"@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROPHET-T.B-JOSHUA.jpg","keywords":["adicci\u00f3n","africa","AGUA DE LA MA\u00d1ANA","Atadura","bendicion","Emmanuel TV","esterilidad","La Sinagoga Iglesia de Todas las Naciones","Lagos","Pactos","progreso","sanidad","T.B Joshua","testimonios","\u00daLCERA"],"articleSection":["EMMANUEL TV"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/","url":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/","name":"S\u00c9 UN IMITADOR DE DIOS - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#primaryimage"},"image":{"@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROPHET-T.B-JOSHUA.jpg","datePublished":"2017-07-20T10:35:32+00:00","dateModified":"2017-07-20T10:43:34+00:00","breadcrumb":{"@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#primaryimage","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROPHET-T.B-JOSHUA.jpg","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/07\/PROPHET-T.B-JOSHUA.jpg","width":1056,"height":719,"caption":"Profeta T.B Joshua"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scoan.org\/es\/se-un-imitador-de-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scoan.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00c9 UN IMITADOR DE DIOS"}]},{"@type":"WebSite","@id":"https:\/\/www.scoan.org\/es\/#website","url":"https:\/\/www.scoan.org\/es\/","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"Founded by Prophet TB Joshua","publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scoan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scoan.org\/es\/#organization","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","url":"https:\/\/www.scoan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","width":186,"height":85,"caption":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua"},"image":{"@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tbjministries","https:\/\/x.com\/SCOANTBJoshua","https:\/\/www.instagram.com\/tbjoshua"]},{"@type":"Person","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/15d5d70121df962845c5d2ba3a5faf33","name":"Johana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g","caption":"Johana"},"url":"https:\/\/www.scoan.org\/es\/author\/johanamyegn-org\/"}]}},"_links":{"self":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/15496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/comments?post=15496"}],"version-history":[{"count":4,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/15496\/revisions"}],"predecessor-version":[{"id":15501,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/15496\/revisions\/15501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media\/15236"}],"wp:attachment":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media?parent=15496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/categories?post=15496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/tags?post=15496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}