{"id":14949,"date":"2017-06-16T17:24:40","date_gmt":"2017-06-16T17:24:40","guid":{"rendered":"https:\/\/www.scoan.org\/?p=14949\/"},"modified":"2017-06-16T17:30:32","modified_gmt":"2017-06-16T17:30:32","slug":"actuando-en-la-palabra","status":"publish","type":"post","link":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/","title":{"rendered":"ACTUANDO EN LA PALABRA"},"content":{"rendered":"<div class=\"entry-content\">\n<p>La gloriosa atm\u00f3sfera del auditorio recibi\u00f3 un poderoso impulso con el mensaje del hombre de Dios titulado <strong>ACTUANDO EN LA PALABRA<\/strong>. El Profeta T.B. Joshua inst\u00f3\u00a0 a los Cristianos a pasar tiempo de calidad con la Palabra de Dios, a fin de que pueda calar en sus corazones, de manera que puedan empoderarse y ser capaces de traer a escena al Hijo de Dios en momentos de gran necesidad: <strong><em>\u00ab<\/em><\/strong><strong><em>Debes dar tu tiempo de calidad, fuerza y amor a la Palabra de Dios<\/em><\/strong><strong><em>\u00bb<\/em><\/strong>. En su serm\u00f3n se\u00f1al\u00f3 que no importa lo buena que sea nuestra relaci\u00f3n con Dios, ya que siempre debe ser puesta a prueba por el infortunio y las tentaciones con el fin de que haya confianza mutua: <strong><em>\u00ab<\/em><\/strong><strong><em>Una relaci\u00f3n necesita ser probada. Debe pasar por buenos tiempos y tiempos de dificultad antes de que pueda ser llamada relaci\u00f3n<\/em><\/strong><strong><em>\u00bb<\/em><\/strong><strong><em>.<br \/>\n<\/em><\/strong>Continu\u00f3 explicando que todos, como Cristianos, debemos considerar que, <strong><em>\u00ab<\/em><\/strong><strong><em>las crisis o las situaciones no son nuestro enemigo, sino nuestro amigo. Est\u00e1n dise\u00f1adas para promoverte. Est\u00e1n dise\u00f1adas para nuestro beneficio espiritual, nuestro crecimiento espiritual<\/em><\/strong><strong><em>\u00bb<\/em><\/strong>. El hombre de Dios enfatiz\u00f3 que el esp\u00edritu del hombre ha de ser libre para poder atraer al Esp\u00edritu Santo, de ah\u00ed la necesidad de que los Cristianos seamos felices, aun enfrent\u00e1ndonos a las situaciones: <strong><em>\u00abLa tristeza no es permitida por el Esp\u00edritu Santo porque \u00c9l requiere un esp\u00edritu libre para operar\u00bb.<br \/>\n<\/em><\/strong>Para concluir, el Profeta T.B. Joshua record\u00f3 a los Cristianos que satan\u00e1s atacar\u00e1 a aquellos que verdaderamente est\u00e9n con Dios: <strong><em>\u00abSi dices que eres Cristiano, satan\u00e1s vendr\u00e1 a confirmar si de verdad lo eres en tu coraz\u00f3n\u00bb<\/em><\/strong>.<\/p>\n<figure id=\"attachment_12470\" aria-describedby=\"caption-attachment-12470\" style=\"width: 391px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-12470\" src=\"https:\/\/thetbjoshuafanclub.files.wordpress.com\/2017\/05\/evangelist-catherine1.jpg?w=300\" alt=\"EVANGELIST CATHERINE\" width=\"391\" height=\"287\" \/><figcaption id=\"caption-attachment-12470\" class=\"wp-caption-text\">La Evangelista Catherine.<\/figcaption><\/figure>\n<p>En un mensaje anterior, titulado <strong><em>CINCO PANES Y DOS PECES<\/em><\/strong>, la Evangelista Catherine llam\u00f3 la atenci\u00f3n de los Cristianos sobre la sobrecogedora capacidad de Dios para bendecirles m\u00e1s all\u00e1 de lo que puedan imaginarse, siempre y cuando permanezcan en Su voluntad: <strong><em>\u00abJes\u00fas es todo lo que necesitamos para alcanzar el \u00e9xito<\/em><\/strong><strong><em>\u00bb<\/em><\/strong>. Enfatiz\u00f3 el hecho de que cuanto tenemos que hacer como Cristianos es creer y actuar de acuerdo a nuestra creencia. Utiliz\u00f3 el encuentro de Pedro con Jes\u00fas como analog\u00eda: <strong><em>\u00ab<\/em><\/strong><strong><em>Tras seguir la instrucci\u00f3n\u00a0 de Jes\u00fas, las redes de Pedro comenzaron a romperse y su barca empez\u00f3 a hundirse porque la bendici\u00f3n que Dios ten\u00eda para \u00e9l era inmensa y descomunal\u00bb.<\/em><\/strong> Y resumi\u00f3 su mensaje con las siguientes palabras: <strong><em>\u00abCuanto m\u00e1s Le mires, m\u00e1s fe tendr\u00e1s en \u00c9l y m\u00e1s atraer\u00e1s Su atenci\u00f3n\u00bb.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>TESTIMONIOS<\/u><\/strong><\/p>\n<p><strong>PERDIDA PERO HALLADA POR EL ESP\u00cdRITU OMNISCIENTE DE DIOS<\/strong><\/p>\n<figure id=\"attachment_12493\" aria-describedby=\"caption-attachment-12493\" style=\"width: 480px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-12493\" src=\"https:\/\/thetbjoshuafanclub.files.wordpress.com\/2017\/05\/mr-chigozie-and-family.jpg?w=300\" alt=\"MR CHIGOZIE AND FAMILY\" width=\"480\" height=\"373\" \/><figcaption id=\"caption-attachment-12493\" class=\"wp-caption-text\">El se\u00f1or Chigozie y su familia<\/figcaption><\/figure>\n<p>El pen\u00faltimo domingo la tranquilidad de su hogar qued\u00f3 rota por la intervenci\u00f3n del diablo. Por razones inexplicables, al volver a casa se encontr\u00f3 con que su suegra hab\u00eda desaparecido. Seg\u00fan explicaba Chigozie Osinike, una desaparici\u00f3n as\u00ed era una gran carga que colgaba sobre su cuello como una espada de Damocles, debido al modo en que la sociedad nigeriana recibe la noticias de personas desaparecidas, haciendo toda clase de insinuaciones. Por eso el se\u00f1or Osinike sab\u00eda que le esperaba un calvario con la maledicencia de la gente. Todos los esfuerzos que hicieron por localizar a la anciana fueron en vano. Como una burbuja del aire a la que arrastra el viento, no hab\u00eda manera de encontrarla.<\/p>\n<p>Tanto el se\u00f1or Osinike como su hijo hab\u00edan contactado con las L\u00edneas de La SCOAN de Oraci\u00f3n y Consejer\u00eda, y les hab\u00edan asegurado que la anciana aparecer\u00eda. Hacia la medianoche de aquel fat\u00eddico s\u00e1bado, hab\u00eda prometido desencadenar el poder de Dios para solucionar aquel asunto, y dijo a quien quiso escuchar que estaba decidido a llevarlo a la <em>Arena de la Libertad.<\/em> Al d\u00eda siguiente, domingo, se present\u00f3 en La SCOAN y expuso lo ocurrido a los evangelistas, que le aconsejaron que trajera una foto de la persona desaparecida. Siguiendo su consejo, consigui\u00f3 una fotograf\u00eda y se acomod\u00f3 en el auditorio, rog\u00e1ndole a Dios en voz baja que arrancase el velo de verg\u00fcenza que lo ven\u00eda cubriendo y casi asfixiando.<\/p>\n<p>Segu\u00eda apelando a Dios, cuando el Profeta T.B. Joshua entr\u00f3 en el auditorio y comenz\u00f3 a ministrar oraci\u00f3n a la congregaci\u00f3n. El hombre de Dios iba avanzando de un asiento al siguiente, imponiendo las manos a todos los que lo buscaban. Al acercarse al se\u00f1or Osinike y dirigir sus manos hacia las personas sentadas en aquella zona, ocurri\u00f3 algo misterioso. En aquel momento, el se\u00f1or Osinike recibi\u00f3 una llamada de la zona oriental de Nigeria, donde se le informaba que su suegra hab\u00eda sido hallada en un suburbio de Lagos llamado Iyana-SARS. La llamada acert\u00f3 de pleno. Seg\u00fan el se\u00f1or Osinike, el poder del Profeta T.B. Joshua hab\u00eda desencadenado el milagro.<\/p>\n<p>Tras compartir su testimonio, en compa\u00f1\u00eda de su esposa, su hijo y la perdida y hallada suegra, el se\u00f1or Osinike expres\u00f3 la inmensa gratitud que sent\u00eda hacia Dios por haberle devuelto la paz a su coraz\u00f3n con la aparici\u00f3n de la mujer. Animando a todos a poner su confianza en Dios, declar\u00f3 que el Se\u00f1or se encuentra en todos los rincones de la <em>Arena de la Libertad<\/em>. Por su parte, su esposa dio tambi\u00e9n las gracias a Dios por aplicar sus bendiciones a trav\u00e9s de la vida del Profeta T.B. Joshua, y que as\u00ed hubiera podido encontrar a su madre.<\/p>\n<p>El se\u00f1or Osinike dej\u00f3 el siguiente mensaje para todos los que le estuvieran escuchando: <strong><em>\u00abSi est\u00e1s en Cristo, ya no est\u00e1s condenado. Cree y s\u00edrvele con todo tu coraz\u00f3n\u00bb.<\/em><\/strong><\/p>\n<p><strong>CUANDO JES\u00daS EST\u00c1 INVOLUCRADO, EL TRIUNFO SIEMPRE ES F\u00c1CIL<\/strong><\/p>\n<figure id=\"attachment_12480\" aria-describedby=\"caption-attachment-12480\" style=\"width: 279px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12480 \" src=\"https:\/\/thetbjoshuafanclub.files.wordpress.com\/2017\/05\/mrs-prsiscilla.jpg?w=189\" alt=\"MRS PRSISCILLA.\" width=\"279\" height=\"441\" \/><figcaption id=\"caption-attachment-12480\" class=\"wp-caption-text\">La se\u00f1orita Priscilla.<\/figcaption><\/figure>\n<p>Priscilla Osobase gan\u00f3 uno de los premios de la <em>American Diversity Lottery<\/em>, y decidi\u00f3 viajar a Estados Unidos desde su Nigeria natal. Priscilla es enfermera, y le parec\u00eda buena idea desarrollar su profesi\u00f3n all\u00ed, pero para lograrlo, ten\u00eda que pasar un examen de unas seis horas de duraci\u00f3n que se hac\u00eda en ordenador, lo que no era tarea f\u00e1cil. El primer intento fue un fracaso, lo que la dej\u00f3 entristecida, pero rehaci\u00e9ndose se prepar\u00f3 para un segundo intento. Estando en esa situaci\u00f3n le habl\u00f3 a su padre de sus dificultades con el examen, y aunque \u00e9l le envi\u00f3 el <em>Agua de La Ma\u00f1ana<\/em>, ella no le prest\u00f3 demasiada atenci\u00f3n.<br \/>\nPero cuando el segundo intento acab\u00f3 tambi\u00e9n en fracaso,\u00a0 se dio cuenta de que ten\u00eda que enfrentarse al problema contando con la ayuda de Dios. Una amiga la anim\u00f3 a ver <em>Emmanuel TV<\/em> y a orar con el hombre de Dios. La idea de ministrarse el <em>Agua de La Ma\u00f1ana<\/em> empez\u00f3 a cobrar intensidad.<br \/>\nCuando lleg\u00f3 el momento de presentarse por tercera vez al examen que tanto se le resist\u00eda, pidi\u00f3 a Dios su bendici\u00f3n orando, ayunando y ministr\u00e1ndose el <em>Agua de La Ma\u00f1ana<\/em>. Pocos d\u00edas antes de la fecha clave, Priscilla tuvo un sue\u00f1o en el que se le revelaba que pasar\u00eda la prueba y obtendr\u00eda una estupenda calificaci\u00f3n.<br \/>\nEl d\u00eda del prueba se ministr\u00f3 el <em>Agua de La Ma\u00f1ana<\/em> en las manos y or\u00f3 junto al Profeta T.B. Joshua antes de salir de casa. Tal y como ella hab\u00eda visto en su sue\u00f1o, aprob\u00f3 con buena nota. Tard\u00f3 solo cuarenta y cinco minutos en romper la maldici\u00f3n que la hab\u00eda venido persiguiendo. Y desde entonces, ha venido ejerciendo la enfermer\u00eda en la ciudad de Michigan, Estados Unidos.<br \/>\nDurante su testimonio del pasado domingo, se mostr\u00f3 feliz dando las gracias a Dios por haber removido la barrera que le imped\u00eda practicar su profesi\u00f3n en EE.UU, y anim\u00f3 a todos los presentes a no fiarse solo de sus propias fuerzas, sino a depositar su confianza en Dios.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>C\u00d3MO LA DISCAPACIDAD SE TORN\u00d3 EN S\u00daPER CAPACIDAD GRACIAS A JESUCRISTO<\/strong><\/p>\n<figure id=\"attachment_12504\" aria-describedby=\"caption-attachment-12504\" style=\"width: 404px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12504 \" src=\"https:\/\/thetbjoshuafanclub.files.wordpress.com\/2017\/05\/fanuel-olu1.jpg?w=300\" alt=\"FANUEL OLU\" width=\"404\" height=\"372\" \/><figcaption id=\"caption-attachment-12504\" class=\"wp-caption-text\">El se\u00f1or Fanuel Oloo<\/figcaption><\/figure>\n<p>En 2015 Fanuel Oloo se cay\u00f3 por las escaleras y se rompi\u00f3 el tend\u00f3n de una pierna, lo que le provoc\u00f3 intensos dolores e incapacidad para trabajar, por lo que este keniano recibi\u00f3 el estatus de discapacitado. Los m\u00e9dicos que evaluaron su caso le dijeron que la mejor soluci\u00f3n ser\u00eda la intervenci\u00f3n quir\u00fargica. Mientras, le indicaron el uso de una rodillera y de analg\u00e9sicos, pero todo result\u00f3 ser una p\u00e9rdida de tiempo y esfuerzo, ya que solo le aportaron un alivio temporal, y Fanuel era consultor inmobiliario, de modo que para desarrollar su trabajo necesitaba caminar mucho.<\/p>\n<p>Mientras consideraba las opciones que le quedaban, un amigo le habl\u00f3 de <em>Emmanuel TV<\/em>, y su fe fue creciendo a medida que iba viendo sus emisiones y los maravillosos milagros que Dios obraba por medio del Profeta T.B. Joshua. Fue as\u00ed como tom\u00f3 la decisi\u00f3n de visitar la <em>Arena de la Libertad<\/em>.<\/p>\n<p>Cuando por fin lleg\u00f3 a La SCOAN, ocup\u00f3 un lugar en la <em>L\u00ednea de Oraci\u00f3n<\/em>, donde tuvo un encuentro inolvidable con Dios. Seg\u00fan referir\u00eda despu\u00e9s, en cuanto el hombre de Dios lo toc\u00f3, experiment\u00f3 una especie de desvanecimiento del que solo recordaba que el hombre de Dios le hab\u00eda tocado la pierna: <em>\u00abCuando me toc\u00f3 la pierna, la sent\u00ed de pronto muy pesada. A continuaci\u00f3n me pidi\u00f3 que me pusiera en pie y caminase, y desde entonces he venido haciendo todas las cosas para las que antes estaba incapacitado\u00bb.<\/em><\/p>\n<p>Y el se\u00f1or Oloo camin\u00f3 sin ning\u00fan impedimento delante de la congregaci\u00f3n, para luego dar gracias a Dios por haberle devuelto la capacidad de caminar y por permitirle recuperar su trabajo. Sonriendo agradecido, dej\u00f3 un consejo basado en las Sagradas Escrituras: <strong><em>\u00abConf\u00eda en el Se\u00f1or tu Dios con todo tu coraz\u00f3n; no conf\u00edes en tu propio entendimiento. Es con Cristo con quien lo puedes todo, quien te presta Su fuerza\u00bb.<\/em><\/strong><\/p>\n<p><strong>VENENO DEMON\u00cdACO QUE LLEVABA A\u00d1OS EN ELLA ES EXPULSADO POR EL ESP\u00cdRITU SANTO<\/strong><\/p>\n<figure id=\"attachment_12501\" aria-describedby=\"caption-attachment-12501\" style=\"width: 323px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12501 \" src=\"https:\/\/thetbjoshuafanclub.files.wordpress.com\/2017\/05\/mrs-millicent1.jpg?w=189\" alt=\"MRS MILLICENT\" width=\"323\" height=\"511\" \/><figcaption id=\"caption-attachment-12501\" class=\"wp-caption-text\">La se\u00f1ora Millicient<\/figcaption><\/figure>\n<p>Llevaba quince a\u00f1os so\u00f1ando con que com\u00eda, y cuando se despertaba despu\u00e9s de haber tenido ese sue\u00f1o, el cuerpo entero le dol\u00eda. Hab\u00eda pensado si consultarlo en el hospital servir\u00eda de algo, pero no fue as\u00ed. Millicent Kumah hab\u00eda tomado toda clase de analg\u00e9sicos, pero segu\u00eda sin encontrar mejor\u00eda. Era incapaz de caminar largas distancias sin fatigarse mucho.<\/p>\n<p>Los m\u00e9dicos llegaron a la conclusi\u00f3n de que la \u00fanica soluci\u00f3n ser\u00eda operarla, pero esta ghanesa se neg\u00f3. Confusa y totalmente desanimada, se quej\u00f3 amargamente a una amiga, que fue quien le aconsej\u00f3 que viera <em>Emmanuel TV<\/em>. Aunque en un principio se mostr\u00f3 esc\u00e9ptica, con la persuasi\u00f3n de su amiga comenz\u00f3 a ser testigo de las incre\u00edbles y maravillosas obras que Dios lleva a cabo a trav\u00e9s de Su siervo, el Profeta T.B. Joshua.<\/p>\n<p>Cuando comprendi\u00f3 de verdad que <em>Emmanuel TV<\/em> es un medio poderoso e inspirador, lament\u00f3 no haberlo conocido antes. Se volvi\u00f3 una seguidora apasionada y oraba regularmente con el hombre de Dios. Cuando su fe hab\u00eda alcanzado ya un umbral en el que no hab\u00eda dudas, lo siguiente que pens\u00f3 fue que deb\u00eda visitar La SCOAN. El pen\u00faltimo domingo, se present\u00f3 en el auditorio. Hab\u00eda viajado desde Ghana para encontrarse all\u00ed con Dios.<\/p>\n<p>Durante la Oraci\u00f3n Masiva, cuando el hombre de Dios orden\u00f3 a todas las enfermedades y padecimientos que salieran de la vida de los all\u00ed congregados, la se\u00f1ora Kumah se puso un mano en la cabeza y otra en el est\u00f3mago. Cuando la oraci\u00f3n cobr\u00f3 intensidad, sinti\u00f3 que un objeto se le ca\u00eda de la boca y comenz\u00f3 a vomitar sangre. El Profeta T.B. Joshua explic\u00f3 a la congregaci\u00f3n que hab\u00eda ingerido veneno en sue\u00f1os, pero que gracias al poder de la unci\u00f3n que flotaba en al auditorio, el Esp\u00edritu Santo hab\u00eda intervenido y la hab\u00eda ayudado a vomitar aquel veneno fatal que ven\u00eda poniendo en peligro su bienestar desde hac\u00eda tanto tiempo.<\/p>\n<p>En cuanto termin\u00f3 de vomitar la sangre y aquel extra\u00f1o objeto, sinti\u00f3 una energ\u00eda ya olvidada en su interior. Todos los dolores cesaron de inmediato.<\/p>\n<p>Durante su testimonio del pasado domingo, la se\u00f1ora Kumah ten\u00eda un aspecto saludable, lleno de vida y sereno. Irradiaba salud, y la congregaci\u00f3n en pleno dio las gracias a Dios por su liberaci\u00f3n y porque hubiese recuperado la salud mediante un toque ungido del Profeta T.B. Joshua.<\/p>\n<p><strong>ADICCI\u00d3N AL ALCOHOL BORRADA POR LA SANGRE DE JES\u00daS<\/strong><\/p>\n<figure id=\"attachment_12474\" aria-describedby=\"caption-attachment-12474\" style=\"width: 477px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12474 \" src=\"https:\/\/thetbjoshuafanclub.files.wordpress.com\/2017\/05\/mr-and-mrs-osakwe.jpg?w=300\" alt=\"MR AND MRS OSAKWE\" width=\"477\" height=\"318\" \/><figcaption id=\"caption-attachment-12474\" class=\"wp-caption-text\">El se\u00f1or y la se\u00f1ora Osakwe<\/figcaption><\/figure>\n<p>El se\u00f1or Osakwe hab\u00eda empezado a beber cuando ten\u00eda veinte a\u00f1os. Se colaba en la habitaci\u00f3n de su padre y se llevaba toda clase de bebidas alcoh\u00f3licas que sol\u00eda compartir con amigos. A partir de aquel momento, su necesidad de beber alcohol se transform\u00f3 en una adicci\u00f3n. A veces, beb\u00eda hasta quedar inconsciente y ponerse enfermo, y volv\u00eda a hacerlo en cuanto se recuperaba. En cierto momento, se march\u00f3 de Nigeria para residir en B\u00e9lgica, y su adicci\u00f3n empeor\u00f3 a\u00fan m\u00e1s, hasta el punto de acabar en coma y tener que ser ingresado en el hospital.<\/p>\n<p>Llegaba incluso a pegar a su mujer porque ella se negaba a que malgastase el dinero en alcohol. Ni siquiera se le pas\u00f3 por la cabeza que estuviera haciendo algo mal. \u00c9l cre\u00eda estar disfrutando de la vida, pero en realidad no sab\u00eda que hab\u00eda fuerzas mal\u00e9volas que le hab\u00edan hecho esclavo de semejante pasi\u00f3n imp\u00eda. \u00bfC\u00f3mo si no se puede explicar que un hombre utilizase el dinero del alquiler de su casa para comprar alcohol sin importarle las consecuencias?<\/p>\n<p>Durante una visita a su hermana en Espa\u00f1a, ella le encontr\u00f3 marihuana y cigarrillos en el bolsillo, y le expres\u00f3 su preocupaci\u00f3n por todo ello. Aquella misma noche, volvi\u00f3 a casa borracho y drogado. Su hermana, enfadada y desilusionada, decidi\u00f3 conseguir para \u00e9l el <em>Agua de La Ma\u00f1ana<\/em>, que le traer\u00edan desde Nigeria. Tambi\u00e9n lo familiariz\u00f3 con <em>Emmanuel TV<\/em>. Cuando recibi\u00f3 el <em>Agua de La Ma\u00f1ana<\/em> pens\u00f3 que se tratar\u00eda de otro m\u00e1s de los remedios ineficaces que hab\u00eda probado con anterioridad para poder salir de la trampa del licor, pero su hermana insisti\u00f3 en que la utilizara.<\/p>\n<p>Cuando volvi\u00f3 a B\u00e9lgica, comenz\u00f3 a ver las emisiones de <em>Emmanuel TV<\/em> y a orar con el Profeta T.B. Joshua. Cuando oraba, le ped\u00eda al Esp\u00edritu Santo que arrancase de ra\u00edz lo que quiera que hubiera en \u00e9l que no hubiera sido plantado por Dios. En cuesti\u00f3n de d\u00edas se dio cuenta de que su necesidad de alcohol iba menguando. Y para mayor gloria de Dios, lleg\u00f3 un momento en el que dej\u00f3 por completo de beber y fumar.<\/p>\n<p>El domingo pasado comparti\u00f3 su testimonio con la congregaci\u00f3n, y declar\u00f3 estar ahora en paz en su casa, acompa\u00f1ado solo del favor de Dios y de la liberaci\u00f3n que le lleg\u00f3 ya tiempo atr\u00e1s. Dio las gracias al Se\u00f1or por haberlo liberado de una adicci\u00f3n que estuvo a punto de destrozar su matrimonio.<\/p>\n<p><strong>\u00a1C\u00c1NCER DE ANO SE ENCUENTRA CON JES\u00daS Y DESAPARECE!<\/strong><\/p>\n<div id=\"image-gallery\" class=\"col-4\">\n<figure class=\"gallery-thumbnail\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/mr-friday-and-mother.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-thumbnail alignleft\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/mr-friday-and-mother-150x150.jpg\" alt=\"\" width=\"205\" height=\"205\" \/><img loading=\"lazy\" decoding=\"async\" class=\"attachment-thumbnail alignleft\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/mr-friday-and-mother1-150x150.jpg\" alt=\"\" width=\"206\" height=\"206\" \/><\/a><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/mrfanuerl-oloo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-thumbnail alignleft\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/mrfanuerl-oloo-150x150.jpg\" alt=\"\" width=\"206\" height=\"206\" \/><\/a><\/figure>\n<figure class=\"gallery-thumbnail\"><\/figure>\n<figure class=\"gallery-thumbnail\"><\/figure>\n<div class=\"clear\">\u00a0Los dolores eran insoportables. Ni siquiera era capaz de caminar erguido sin tener que doblarse y apretar los dientes para soportar el dolor. El abultamiento que ten\u00eda en el ano no le permit\u00eda ni ponerse los pantalones, y era tan terrible que cre\u00eda morir. Su madre lo hab\u00eda llevado a varios hospitales, pero lo que los m\u00e9dicos suger\u00edan como tratamiento era inasumible. La \u00fanica posibilidad para \u00e9l era extirpar el abultamiento en una operaci\u00f3n.<\/div>\n<\/div>\n<p>Rechazada la opci\u00f3n propuesta por los m\u00e9dicos, madre e hijo encontraron pronto otra soluci\u00f3n; Friday acudi\u00f3 a una herborista que le dio varias cocciones a beber. Pas\u00f3 all\u00ed un par de d\u00edas, pero su estado no mejor\u00f3. M\u00e1s bien lo contrario; el dolor era m\u00e1s intenso a cada minuto que pasaba. Llevaba d\u00edas sin dormir. Se pasaba la noche levantado y languideciendo de dolor.<\/p>\n<p>Volvi\u00f3 al hospital en el que le hab\u00edan sugerido lo de la operaci\u00f3n, y all\u00ed conoci\u00f3 a un hombre que, puesto al tanto de su situaci\u00f3n, aconsej\u00f3 que lo llevaran a La SCOAN. Cuando llegaron y debido a su situaci\u00f3n, lo atendieron de inmediato. Con la protuberancia cancerosa que sal\u00eda de su ano, Friday pidi\u00f3 ayuda a gritos por el dolor. En cuanto el hombre de Dios supo de su caso, se dirigi\u00f3 sin dilaci\u00f3n fuera del auditorio y le impuso las manos: orden\u00f3 al c\u00e1ncer que desapareciera y lo toc\u00f3 dos veces en la cabeza. \u00a1No hizo falta m\u00e1s!<\/p>\n<p>El domingo pasado Friday acudi\u00f3 a compartir su testimonio acompa\u00f1ado por su madre, y refiri\u00f3 a la congregaci\u00f3n que, mientras el hombre de Dios oraba por \u00e9l, sinti\u00f3 como si su ano estuviera siendo impelido a ocupar su posici\u00f3n correcta por una fuerza que \u00e9l no pod\u00eda ver. Tras la oraci\u00f3n, recibi\u00f3 el <em>Agua de La Ma\u00f1ana<\/em> con la instrucci\u00f3n de que se la aplicase donde hab\u00eda tenido la protuberancia. Unos d\u00edas despu\u00e9s, aquel crecimiento cancer\u00edgeno desapareci\u00f3, y con \u00e9l el dolor y la incomodad.<\/p>\n<p>Tras dar las gracias a Dios, Friday Igbaifua aconsej\u00f3 a quienes lo escuchaban que tuvieran fe en que Jes\u00fas sana, independientemente de la magnitud de la enfermedad, y su madre se postr\u00f3 en el suelo para expresar la gratitud que sent\u00eda hacia Dios por haber salvado a su hijo de un padecimiento que a punto hab\u00eda estado de segar su vida.<\/p>\n<p><strong>LIBERADO DE UNA MANIPULACI\u00d3N DEMON\u00cdACA<\/strong><\/p>\n<p>Era una espina clavada en la carne de sus padres, pero su naturaleza testaruda le empujaba a enfrentarse a ellos cada vez que intentaban corregirlo o reprenderlo por algo que hubiera hecho mal. Su adicci\u00f3n a la pornograf\u00eda amenazaba incluso la buena marcha de sus estudios, para desilusi\u00f3n de sus padres. Seg\u00fan Samuel, sus problemas eran numerosos, y entre ellos se contaban tener una esposa espiritual y frecuentar malas compa\u00f1\u00edas. En un momento dado, la tensi\u00f3n entre su padre y \u00e9l creci\u00f3 porque su padre se neg\u00f3 a seguir pagando sus gastos. Por culpa de sus fechor\u00edas, su padre incluso lleg\u00f3 a amenazar con divorciarse de su madre. Pero la crisis entre ambos lleg\u00f3 a su punto \u00e1lgido cuando lo ech\u00f3 de casa y tuvo que irse con un amigo.<\/p>\n<div id=\"image-gallery\" class=\"col-4\">\n<figure class=\"gallery-thumbnail\"><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/master-samuel-and-family.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-thumbnail \" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/master-samuel-and-family-150x150.jpg\" alt=\"\" width=\"203\" height=\"203\" \/><\/a><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/master-samuel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-thumbnail \" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/master-samuel-150x150.jpg\" alt=\"\" width=\"202\" height=\"202\" \/><\/a><a href=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/samuel1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-thumbnail \" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/05\/samuel1-150x150.jpg\" alt=\"\" width=\"201\" height=\"201\" \/><\/a><\/figure>\n<\/div>\n<p>La vida con ese amigo era toda libertad, ya que su compa\u00f1ero era un tipo que no se tomaba nada en serio y al que le encantaba ir a clubs, beber y fumar. Pero su padre decidi\u00f3 llamarlo del \u201cexilio\u201d despu\u00e9s de o\u00edr las ense\u00f1anzas del Profeta T.B. Joshua sobre no guardar ofensas. Samuel volvi\u00f3 a su casa y se disculp\u00f3, aunque no de coraz\u00f3n. En aquel momento, esperaba esperando los resultados de sus ex\u00e1menes finales de Secundaria. Cuando los resultados se publicaron, los suyos quedaron retenidos y, al final, sus ex\u00e1menes resultaron invalidados.<\/p>\n<p>Todo aquello le afecto mucho psicol\u00f3gicamente, y su madre se llev\u00f3 una tremenda desilusi\u00f3n, ya que hab\u00edan invertido mucho en su educaci\u00f3n. Fue en aquel momento cuando su padre lleg\u00f3 a la conclusi\u00f3n de que lo que su hijo necesitaba era ser liberado, y lo organiz\u00f3 todo para visitar La SCOAN. Cuando se lo comunic\u00f3 a Samuel, el joven protest\u00f3 por lo repentino de aquel viaje a Lagos, pero no pudo resistirse a la obra del Esp\u00edritu Santo, que era quien estaba detr\u00e1s de todo el proceso que condujo a su liberaci\u00f3n.<\/p>\n<p>Samuel fue liberado a trav\u00e9s del Profeta T.B. Joshua del demonio que lo hab\u00eda venido atormentando, no sin antes confesar todo el mal que le hab\u00eda hecho y que le hab\u00eda obligado a ser grosero, airado y terco. Incluso su adicci\u00f3n a la pornograf\u00eda hab\u00eda sido obra del demonio.<\/p>\n<p>El \u00faltimo domingo estuvo en La SCOAN para compartir su testimonio, en compa\u00f1\u00eda de sus padres y sus hermanos. Sus padres dieron las gracias a Dios por su liberaci\u00f3n, y narraron la pesadilla que hab\u00edan vivido mientras intentaban hacer de su hijo una mejor persona. Por su parte Samuel se disculp\u00f3 con sus padres por su mal comportamiento instigado por el demonio. Ahora era una persona nueva, y ya hab\u00eda dejado de so\u00f1ar que practicaba el sexo con mujeres. Los padres dijeron que ahora se le pod\u00eda describir como un joven respetuoso, y dejaron este consejo: <strong><em>\u00abDebemos aconsejar a nuestros hijos cuando se equivocan y no amarlos por encima de Dios\u00bb.<\/em><\/strong><\/p>\n<\/div>\n<p><code><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gloriosa atm\u00f3sfera del auditorio recibi\u00f3 un poderoso impulso con el mensaje del hombre de Dios titulado ACTUANDO EN LA PALABRA. El Profeta T.B. Joshua inst\u00f3\u00a0 a los Cristianos a pasar tiempo de calidad con la Palabra de Dios, a fin de que pueda calar en sus corazones, de manera que puedan empoderarse y ser [&hellip;]<\/p>\n","protected":false},"author":103,"featured_media":14950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[1436],"tags":[1090,994,1444,1480,1464,1107,4,1242,1279,1305,1762,825,1747,17,19,1067,1068,1070,5,1203],"class_list":["post-14949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emmanuel-tv-2","tag-adicciones","tag-agua-de-la-manana","tag-brazalete-de-la-fe","tag-cristo","tag-dificultad-para-caminar","tag-drogas","tag-emmanuel-tv","tag-evangelista","tag-exito","tag-fe","tag-iglesia-de-todas-las-naciones","tag-jesus","tag-la-sinagoga","tag-lagos","tag-nigeria","tag-profeta-t-b-joshua","tag-progreso","tag-sanidad","tag-scoan","tag-testimonios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ACTUANDO EN LA PALABRA - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACTUANDO EN LA PALABRA\" \/>\n<meta property=\"og:description\" content=\"La gloriosa atm\u00f3sfera del auditorio recibi\u00f3 un poderoso impulso con el mensaje del hombre de Dios titulado ACTUANDO EN LA PALABRA. El Profeta T.B. Joshua inst\u00f3\u00a0 a los Cristianos a pasar tiempo de calidad con la Palabra de Dios, a fin de que pueda calar en sus corazones, de manera que puedan empoderarse y ser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/\" \/>\n<meta property=\"og:site_name\" content=\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tbjministries\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-16T17:24:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-16T17:30:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/06\/1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"713\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Johana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:site\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/\"},\"author\":{\"name\":\"Johana\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/15d5d70121df962845c5d2ba3a5faf33\"},\"headline\":\"ACTUANDO EN LA PALABRA\",\"datePublished\":\"2017-06-16T17:24:40+00:00\",\"dateModified\":\"2017-06-16T17:30:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/\"},\"wordCount\":3635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/06\\\/1-2.jpg\",\"keywords\":[\"ADICCIONES\",\"AGUA DE LA MA\u00d1ANA\",\"brazalete de la fe\",\"cristo\",\"dificultad para caminar\",\"DROGAS\",\"Emmanuel TV\",\"evangelista\",\"\u00e9xito\",\"fe\",\"Iglesia de Todas las Naciones\",\"Jesus\",\"LA SINAGOGA\",\"Lagos\",\"Nigeria\",\"PROFETA T.B. JOSHUA\",\"progreso\",\"sanidad\",\"SCOAN\",\"testimonios\"],\"articleSection\":[\"EMMANUEL TV\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/\",\"name\":\"ACTUANDO EN LA PALABRA - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/06\\\/1-2.jpg\",\"datePublished\":\"2017-06-16T17:24:40+00:00\",\"dateModified\":\"2017-06-16T17:30:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/06\\\/1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2017\\\/06\\\/1-2.jpg\",\"width\":713,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/actuando-en-la-palabra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACTUANDO EN LA PALABRA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"description\":\"Founded by Prophet TB Joshua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"width\":186,\"height\":85,\"caption\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tbjministries\",\"https:\\\/\\\/x.com\\\/SCOANTBJoshua\",\"https:\\\/\\\/www.instagram.com\\\/tbjoshua\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/15d5d70121df962845c5d2ba3a5faf33\",\"name\":\"Johana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g\",\"caption\":\"Johana\"},\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/author\\\/johanamyegn-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ACTUANDO EN LA PALABRA - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/","og_locale":"es_ES","og_type":"article","og_title":"ACTUANDO EN LA PALABRA","og_description":"La gloriosa atm\u00f3sfera del auditorio recibi\u00f3 un poderoso impulso con el mensaje del hombre de Dios titulado ACTUANDO EN LA PALABRA. El Profeta T.B. Joshua inst\u00f3\u00a0 a los Cristianos a pasar tiempo de calidad con la Palabra de Dios, a fin de que pueda calar en sus corazones, de manera que puedan empoderarse y ser [&hellip;]","og_url":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/","og_site_name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","article_publisher":"https:\/\/www.facebook.com\/tbjministries","article_published_time":"2017-06-16T17:24:40+00:00","article_modified_time":"2017-06-16T17:30:32+00:00","og_image":[{"width":713,"height":422,"url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/06\/1-2.jpg","type":"image\/jpeg"}],"author":"Johana","twitter_card":"summary_large_image","twitter_creator":"@SCOANTBJoshua","twitter_site":"@SCOANTBJoshua","twitter_misc":{"Escrito por":"Johana","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#article","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/"},"author":{"name":"Johana","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/15d5d70121df962845c5d2ba3a5faf33"},"headline":"ACTUANDO EN LA PALABRA","datePublished":"2017-06-16T17:24:40+00:00","dateModified":"2017-06-16T17:30:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/"},"wordCount":3635,"commentCount":0,"publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"image":{"@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/06\/1-2.jpg","keywords":["ADICCIONES","AGUA DE LA MA\u00d1ANA","brazalete de la fe","cristo","dificultad para caminar","DROGAS","Emmanuel TV","evangelista","\u00e9xito","fe","Iglesia de Todas las Naciones","Jesus","LA SINAGOGA","Lagos","Nigeria","PROFETA T.B. JOSHUA","progreso","sanidad","SCOAN","testimonios"],"articleSection":["EMMANUEL TV"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/","url":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/","name":"ACTUANDO EN LA PALABRA - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#primaryimage"},"image":{"@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/06\/1-2.jpg","datePublished":"2017-06-16T17:24:40+00:00","dateModified":"2017-06-16T17:30:32+00:00","breadcrumb":{"@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#primaryimage","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/06\/1-2.jpg","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2017\/06\/1-2.jpg","width":713,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/www.scoan.org\/es\/actuando-en-la-palabra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scoan.org\/es\/"},{"@type":"ListItem","position":2,"name":"ACTUANDO EN LA PALABRA"}]},{"@type":"WebSite","@id":"https:\/\/www.scoan.org\/es\/#website","url":"https:\/\/www.scoan.org\/es\/","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"Founded by Prophet TB Joshua","publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scoan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scoan.org\/es\/#organization","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","url":"https:\/\/www.scoan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","width":186,"height":85,"caption":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua"},"image":{"@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tbjministries","https:\/\/x.com\/SCOANTBJoshua","https:\/\/www.instagram.com\/tbjoshua"]},{"@type":"Person","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/15d5d70121df962845c5d2ba3a5faf33","name":"Johana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3483dd83e4d31ad32896f8730ecde5cb4f55bde475ed18c2b3be7ff8639b6af1?s=96&d=mm&r=g","caption":"Johana"},"url":"https:\/\/www.scoan.org\/es\/author\/johanamyegn-org\/"}]}},"_links":{"self":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/14949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/comments?post=14949"}],"version-history":[{"count":6,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/14949\/revisions"}],"predecessor-version":[{"id":14958,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/14949\/revisions\/14958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media\/14950"}],"wp:attachment":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media?parent=14949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/categories?post=14949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/tags?post=14949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}