{"id":103656,"date":"2024-12-31T17:04:07","date_gmt":"2024-12-31T17:04:07","guid":{"rendered":"https:\/\/www.scoan.org\/examinate\/"},"modified":"2025-02-19T17:05:34","modified_gmt":"2025-02-19T17:05:34","slug":"examinate","status":"publish","type":"post","link":"https:\/\/www.scoan.org\/es\/examinate\/","title":{"rendered":"EXAM\u00cdNATE"},"content":{"rendered":"\n<p>A medida que el a\u00f1o se acaba, \u00bfte das cuenta de que es crucial que te revises a ti mismo? Para los presentes en La SCOAN durante el \u00faltimo servicio dominical de 2024, fue el momento de revisar su posici\u00f3n ante Dios y ante sus semejantes. Este examen de conciencia comenz\u00f3 con una sesi\u00f3n de adoraci\u00f3n, durante la cual el pueblo glorific\u00f3 a Dios con muchos cantos por su misericordia y gracia duraderas. \u00abTe damos gloria y honor, T\u00fa eres el Se\u00f1or, que Tu nombre sea glorificado\u00bb, proclamaron. Reconociendo el dominio de Dios, los congregantes aclamaron a Yahweh de muchas maneras y consiguieron preparar el ambiente para el Esp\u00edritu Santo.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-683x1024.jpg\" alt=\"El coro de La SCOAN cantando alabanzas y adoraci&#xF3;n en el servicio dominical de La SCOAN el 29 de diciembre del 2024. \" class=\"wp-image-100576\" style=\"width:678px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-683x1024.jpg 683w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-200x300.jpg 200w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-768x1152.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-1024x1536.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-500x750.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3-800x1200.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-2-3.jpg 1080w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-736x1024.jpg\" alt=\"El coro de La SCOAN cantando alabanzas y adoraci&#xF3;n en el servicio dominical de La SCOAN el 29 de diciembre del 2024. \" class=\"wp-image-100580\" style=\"width:677px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-736x1024.jpg 736w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-216x300.jpg 216w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-768x1068.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-500x695.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3-800x1113.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-6-3.jpg 1080w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"418\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-1024x418.jpg\" alt=\"El coro de La SCOAN cantando alabanzas y adoraci&#xF3;n en el servicio dominical de La SCOAN el 29 de diciembre del 2024. \" class=\"wp-image-100584\" style=\"width:680px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-1024x418.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-300x123.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-768x314.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-500x204.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4-800x327.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHOIR-7-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-an-unexamined-life-is-an-unkempt-life\">Una vida ignorada es una vida descuidada<\/h3>\n\n<p>El Evangelista Ope bas\u00f3 su serm\u00f3n principalmente en 1 Timoteo 4:16 y en parte en 2 Corintios 13:5 y 1 Corintios 11:28. Titulado \u00ab Exam\u00ednate\u00bb, el mensaje se dirigi\u00f3 sin rodeos a un p\u00fablico bastante receptivo. Bas\u00e1ndose en 2 Corintios 10:2, el predicador explic\u00f3 que su objetivo no era que el pueblo se comparara con los dem\u00e1s o se midiera por s\u00ed mismo. En lugar de eso, dijo, deb\u00edan examinar sus acciones a la luz de la Palabra de Dios, tal como se exhorta en 2 Timoteo 3:16-17 y Hebreos 4:12. \u00abExaminarse a uno mismo cada d\u00eda es algo bueno\u00bb, afirm\u00f3.  <\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"745\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-745x1024.jpg\" alt=\"El Evangelista predicando el serm&#xF3;n en el altar en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100588\" style=\"width:691px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-745x1024.jpg 745w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-218x300.jpg 218w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-768x1056.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-500x688.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1-800x1100.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-2-1.jpg 1080w\" sizes=\"auto, (max-width: 745px) 100vw, 745px\" \/><\/figure>\n\n<p>El ministro tambi\u00e9n se\u00f1al\u00f3 que la mayor\u00eda de los fracasos suelen ser el resultado de la inacci\u00f3n, especialmente de no controlarse a uno mismo, una situaci\u00f3n que a menudo conduce al arrepentimiento. \u00abUna vida sin control es una vida descuidada\u00bb, observ\u00f3, al tiempo que a\u00f1ad\u00eda que algunas personas se deleitan causando dolor a los dem\u00e1s y sembrando la discordia entre el pueblo. Por ello, inst\u00f3 a los congregantes a darse cuenta de que, de hecho, pueden ser la fuente de sus propios problemas. Una forma de ser mejor persona, dijo, es estar siempre agradecido, ser generoso y practicar el perd\u00f3n, evitando la mentalidad de tener derechos.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"714\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-1024x714.jpg\" alt=\"El Evangelista predicando el serm&#xF3;n en el altar en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100592\" style=\"width:700px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-1024x714.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-300x209.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-768x535.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-500x349.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2-800x558.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-4-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-697x1024.jpg\" alt=\"El Evangelista predicando el serm&#xF3;n en el altar en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100596\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-697x1024.jpg 697w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-204x300.jpg 204w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-768x1128.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-1046x1536.jpg 1046w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-500x734.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1-800x1175.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-5-1.jpg 1080w\" sizes=\"auto, (max-width: 697px) 100vw, 697px\" \/><\/figure>\n\n<p>Al concluir el serm\u00f3n, el Evangelista Ope cit\u00f3 1 Corintios 10:12 y G\u00e1latas 6:3 y dijo al pueblo: \u00abDios Todopoderoso nos llama a cambiar. Nos pide que miremos en nuestro interior y corrijamos nuestros caminos. Examin\u00e9monos a nosotros mismos para cambiar, \u00a1porque si no cambias nada cambiar\u00e1!\u00bb.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-735x1024.jpg\" alt=\"El Evangelista predicando el serm&#xF3;n en el altar en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100600\" style=\"width:663px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-735x1024.jpg 735w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-215x300.jpg 215w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-768x1070.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-500x697.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1-800x1115.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-3-1.jpg 1080w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"777\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-777x1024.jpg\" alt=\"El Evangelista predicando el serm&#xF3;n en el altar en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100608\" style=\"width:621px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-777x1024.jpg 777w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-228x300.jpg 228w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-768x1012.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-500x659.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1-800x1054.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SERMON-7-1.jpg 1080w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-go-where-you-are-welcome\">\u00abVe donde seas bienvenido\u00bb<\/h3>\n\n<p>\u00abEs otro d\u00eda glorioso en Su presencia y hemos venido a dar las gracias\u00bb, dijo la Pastora Evelyn Joshua al unirse al pueblo para orar.<\/p>\n\n<p>Siguiendo con el serm\u00f3n, la Pastora Evelyn Joshua habl\u00f3 al pueblo sobre el lugar de la fe y la naturaleza del Esp\u00edritu Santo. Les asegur\u00f3: \u00abEl que est\u00e1 dentro de vosotros es m\u00e1s grande que el que hay en el mundo\u00bb. Tambi\u00e9n record\u00f3 a los congregantes lo siguiente: \u00abSi el Esp\u00edritu Santo se establece en tu interior, ir\u00e1s a un lugar donde \u00c9l sea honrado, bienvenido y apreciado, no s\u00f3lo donde se Le necesite\u00bb.<\/p>\n\n<p>Citando Lucas 9:1-5 y el Salmo 40:2, la mujer de Dios observ\u00f3: \u00abHoy muchos de nosotros nos encontramos donde se nos necesita pero no somos bienvenidos\u00bb. Por eso alent\u00f3 al pueblo a tomar la decisi\u00f3n correcta abrazando a Jesucristo, que nos ense\u00f1a el camino a seguir.<\/p>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-touched-in-a-special-way\">Tocado de una manera especial<\/h3>\n\n<p>En la l\u00ednea de oraci\u00f3n, la Pastora Evelyn Joshua mir\u00f3 hacia el cielo: \u00abPadre Se\u00f1or, bendecimos Tu Santo nombre. Jesucristo, te honramos. Esp\u00edritu Santo, te damos la bienvenida. Padre, hemos venido declarando Tu soberan\u00eda. Confesamos que T\u00fa eres nuestro Dios, que T\u00fa eres nuestro Creador. Hemos venido sabiendo que T\u00fa eres el Juez, confiando en Tu gracia y en Tu amor que no somos dejados de lado. T\u00fa eres nuestra paz; en Ti encontramos la alegr\u00eda y en Ti la vida eterna.<\/p>\n\n<p>Se\u00f1or Dios Todopoderoso, te pedimos que nos toques hoy de una manera diferente, de una manera especial. Toca a tus hijos para que los que est\u00e1n enfermos digan que est\u00e1n curados, los que son pobres digan que est\u00e1n bendecidos, los que son d\u00e9biles digan que tienen fuerza y los que est\u00e1n perdidos declaren que han sido encontrados, en el nombre de Jesucristo\u00bb.<\/p>\n\n<p>Con fe en sus corazones, el pueblo vino con diversos problemas como dificultad para caminar, asma, vientre hinchado, hernia, adicci\u00f3n al alcohol, enfermedad de la piel, derrame cerebral parcial, artritis reumatoide y hemorragia nasal. Y el poder del Dios vivo los san\u00f3 a todos.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-1024x543.jpg\" alt=\"La Pastora Evelyn Joshua orando por el pueblo en el poder del Esp&#xED;ritu Santo durante la Secci&#xF3;n de L&#xED;nea de Oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100612\" style=\"width:668px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-1024x543.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-300x159.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-768x407.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-500x265.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3-800x424.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-1-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"851\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-1024x851.jpg\" alt=\"La Pastora Evelyn Joshua orando por el pueblo en el poder del Esp&#xED;ritu Santo durante la Secci&#xF3;n de L&#xED;nea de Oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100616\" style=\"width:675px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-1024x851.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-300x249.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-768x639.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-500x416.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2-800x665.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"483\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-1024x483.jpg\" alt=\"La Pastora Evelyn Joshua orando por el pueblo en el poder del Esp&#xED;ritu Santo durante la Secci&#xF3;n de L&#xED;nea de Oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100620\" style=\"width:675px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-1024x483.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-300x141.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-768x362.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-500x236.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2-800x377.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-3-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"609\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-1024x609.jpg\" alt=\"La Pastora Evelyn Joshua orando por el pueblo en el poder del Esp&#xED;ritu Santo durante la Secci&#xF3;n de L&#xED;nea de Oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100624\" style=\"width:668px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-1024x609.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-300x178.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-768x457.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-500x297.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1-800x476.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-4-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"631\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-1024x631.jpg\" alt=\"La Pastora Evelyn Joshua orando por el pueblo en el poder del Esp&#xED;ritu Santo durante la Secci&#xF3;n de L&#xED;nea de Oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100632\" style=\"width:671px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-1024x631.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-300x185.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-768x473.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-500x308.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2-800x493.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-5-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Otros casos que recibieron atenci\u00f3n fueron lesiones de tobillo, drogadicci\u00f3n, fractura de hombro, pr\u00f3stata agrandada, trastorno mental, \u00falceras de pierna, quemaduras de fuego, p\u00e9rdida de memoria, almorranas, hipertensi\u00f3n, dificultad para respirar y convulsiones. A medida que el pueblo recib\u00eda del Trono de Gracia, exclamaba \u00ab\u00a1Gracias, Jes\u00fas!\u00bb\u00bb.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"544\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-1024x544.jpg\" alt=\"La Pastora Evelyn Joshua orando por el pueblo en el poder del Esp&#xED;ritu Santo durante la Secci&#xF3;n de L&#xED;nea de Oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100636\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-1024x544.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-300x159.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-768x408.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-500x266.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1-800x425.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-PRAYERLINE-6-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"496\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-1024x496.jpg\" alt=\"El Evangelista orando por el pueblo durante la Secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100640\" style=\"width:754px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-1024x496.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-300x145.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-768x372.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-500x242.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2-800x387.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"466\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-1024x466.jpg\" alt=\"El Evangelista orando por el pueblo durante la Secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100644\" style=\"width:751px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-1024x466.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-300x136.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-768x349.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-500x227.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2-800x364.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"602\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-1024x602.jpg\" alt=\"El Evangelista orando por el pueblo durante la Secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100648\" style=\"width:747px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-1024x602.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-300x176.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-768x452.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-500x294.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2-800x470.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"501\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-1024x501.jpg\" alt=\"El Evangelista orando por el pueblo durante la Secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100652\" style=\"width:738px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-1024x501.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-300x147.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-768x375.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-500x244.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2-800x391.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"787\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-1024x787.jpg\" alt=\"El Evangelista orando por el pueblo durante la Secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100656\" style=\"width:730px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-1024x787.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-300x231.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-768x590.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-500x384.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2-800x615.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"602\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-1024x602.jpg\" alt=\"El Evangelista orando por el pueblo durante la Secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100660\" style=\"width:733px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-1024x602.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-300x176.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-768x452.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-500x294.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2-800x470.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-PRAYERLINE-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-1024x570.jpg\" alt=\"El Evangelista orando por el pueblo durante la Secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100664\" style=\"width:731px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-1024x570.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-300x167.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-768x427.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-500x278.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3-800x445.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-1-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"922\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-1024x922.jpg\" alt=\" \" class=\"wp-image-100668\" style=\"width:731px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-1024x922.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-300x270.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-768x691.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-500x450.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4-800x720.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-PRAYERLINE-2-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Las mujeres embarazadas tambi\u00e9n se cubrieron con la Sangre de Jesucristo.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"571\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-1024x571.jpg\" alt=\"La pastora Evelyn Joshua or&#xF3; por las mujeres para que dieran a luz durante la secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el servicio dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100672\" style=\"width:751px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-1024x571.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-300x167.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-768x428.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-500x279.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2-800x446.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-1-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-1024x529.jpg\" alt=\"La pastora Evelyn Joshua or&#xF3; por las mujeres para que dieran a luz durante la secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el servicio dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100676\" style=\"width:758px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-1024x529.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-300x155.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-768x397.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-500x258.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2-800x413.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-2-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-1024x612.jpg\" alt=\"La pastora Evelyn Joshua or&#xF3; por las mujeres para que dieran a luz durante la secci&#xF3;n de la l&#xED;nea de oraci&#xF3;n en el servicio dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100680\" style=\"width:761px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-1024x612.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-300x179.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-768x459.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-500x299.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3-800x478.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/SAFE-DELIVERY-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Para el resto de los congregantes en el auditorio, la secci\u00f3n de desbordamiento, la Escuela Dominical y la secci\u00f3n de madres lactantes, fue un toque especial de fin de a\u00f1o respaldado por el Cielo mientras los siervos de Dios ministraban con una unci\u00f3n poco com\u00fan.<\/p>\n\n<p>En efecto, por el fuego del Esp\u00edritu Santo, \u00a1todo demonio obstinado fue expulsado!<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-1024x574.jpg\" alt=\"La Pastora Evelyn Joshua imponiendo las manos y orando por al pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100684\" style=\"width:773px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-1024x574.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-300x168.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-768x430.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-500x280.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3-800x448.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-1-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-790x1024.jpg\" alt=\"La Pastora Evelyn Joshua imponiendo las manos y orando por al pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100688\" style=\"width:774px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-790x1024.jpg 790w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-231x300.jpg 231w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-768x996.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-500x648.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3-800x1037.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-2-3.jpg 1080w\" sizes=\"auto, (max-width: 790px) 100vw, 790px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-799x1024.jpg\" alt=\" La Pastora Evelyn Joshua imponiendo las manos y orando por al pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100692\" style=\"width:781px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-799x1024.jpg 799w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-234x300.jpg 234w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-768x984.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-500x641.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3-800x1025.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-LAYING-OF-HAND-3-3.jpg 1080w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"862\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-862x1024.jpg\" alt=\"El Evangelista imponiendo las manos y orando por el pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100696\" style=\"width:785px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-862x1024.jpg 862w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-253x300.jpg 253w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-768x912.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-500x594.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2-800x950.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-3-2.jpg 1080w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-822x1024.jpg\" alt=\"El Evangelista imponiendo las manos y orando por el pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100700\" style=\"width:776px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-822x1024.jpg 822w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-241x300.jpg 241w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-768x956.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-500x623.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1-800x996.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-LAYING-OF-HANDS-3-1.jpg 1080w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-778x1024.jpg\" alt=\"El Evangelista imponiendo las manos y orando por el pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100704\" style=\"width:781px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-778x1024.jpg 778w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-228x300.jpg 228w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-768x1010.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-500x658.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2-800x1053.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-3-2.jpg 1080w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"806\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-806x1024.jpg\" alt=\"El Evangelista imponiendo las manos y orando por el pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100708\" style=\"width:777px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-806x1024.jpg 806w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-236x300.jpg 236w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-768x976.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-500x635.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2-800x1016.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-3-2.jpg 1080w\" sizes=\"auto, (max-width: 806px) 100vw, 806px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"867\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-867x1024.jpg\" alt=\"El Evangelista imponiendo las manos y orando por el pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100802\" style=\"width:776px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-867x1024.jpg 867w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-254x300.jpg 254w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-768x907.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-500x590.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4-800x944.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-LAYING-OF-HANDS-4.jpg 1080w\" sizes=\"auto, (max-width: 867px) 100vw, 867px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-1024x592.jpg\" alt=\"El Evangelista imponiendo las manos y orando por el pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100806\" style=\"width:780px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-1024x592.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-300x173.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-768x444.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-500x289.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4-800x462.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-LAYING-OF-HANDS-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-1024x512.jpg\" alt=\"El Evangelista imponiendo las manos y orando por el pueblo durante la ministraci&#xF3;n en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024.\" class=\"wp-image-100811\" style=\"width:780px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-1024x512.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-300x150.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-768x384.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-500x250.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4-800x400.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-LAYING-OF-HANDS-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-and-their-fear-became-faith\">Y su miedo se convirti\u00f3 en fe.<\/h3>\n\n<p>\u00abQue la paz de Dios nunca se aparte de tu hogar\u00bb, or\u00f3 la Pastora Evelyn Joshua al final de la sesi\u00f3n de alabanza. \u00abDa gracias a Dios\u00bb, exhort\u00f3 al pueblo.<\/p>\n\n<p>Al comenzar la sesi\u00f3n de Oraci\u00f3n Masiva, or\u00f3: \u00abTe ordenamos que toda duda en ti se convierta en fe fuerte, en el nombre de Jes\u00fas. Te ordenamos que todo temor dentro y fuera de ti se convierta en confianza tranquila, en el nombre de Jes\u00fas. Cada problema que vino a tu vida a trav\u00e9s de la iniquidad de los padres &#8211; sea lavado, en el nombre de Jes\u00fas. Esp\u00edritu de maldad que ha enredado tu vida &#8211; \u00a1te ordenamos que sea lavado, en el nombre de Jes\u00fas! Que haya sanidad en tu cuerpo, esp\u00edritu, huesos, ri\u00f1ones, espina dorsal, h\u00edgado. \u00a1Que haya sanidad en cada \u00f3rgano de tu cuerpo! S\u00e9 sanado de esa aflicci\u00f3n, enfermedad, dolencia, \u00a1en el nombre de Jes\u00fas!\u00bb<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"751\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-751x1024.jpg\" alt=\"La Pastora Evelyn Joshua orando por la congregaci&#xF3;n y los espectadores durante la Oraci&#xF3;n Masiva en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100712\" style=\"width:707px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-751x1024.jpg 751w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-220x300.jpg 220w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-768x1047.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-500x682.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3-800x1091.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-3.jpg 1080w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/figure>\n\n<p>La mujer de Dios continu\u00f3 orando: \u00abTodo lo que te causa verg\u00fcenza y desgracia &#8211; \u00a1le ordenamos que se vaya con el a\u00f1o, en el nombre de Jes\u00fas! Todo lo que te retiene en el estancamiento &#8211; \u00a1le ordenamos que se vaya, en el nombre de Jesucristo!\u00bb.<\/p>\n\n<p>Dirigi\u00e9ndose a los espectadores de todo el mundo, la Pastora Evelyn Joshua or\u00f3: \u00abCualquier cosa que se interponga entre t\u00fa y las promesas de Dios para tu vida &#8211; \u00a1Le ordenamos que ceda ahora mismo, en el nombre de Jes\u00fas! Todo velo maligno de destrucci\u00f3n, odio, estancamiento que se interponga entre t\u00fa y las promesas de Dios para tu vida &#8211; \u00a1ordenamos que se rompa, en el nombre de Jesucristo! Victoria en nuestras vidas, en nuestras carreras, en nuestro matrimonio, \u00a1en el nombre de Jes\u00fas! \u00a1Progreso en tus finanzas! Libertad de todo grillete, de toda atadura, de toda limitaci\u00f3n\u00bb.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"871\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-871x1024.jpg\" alt=\"La Pastora Evelyn Joshua orando por la congregaci&#xF3;n y los espectadores durante la Oraci&#xF3;n Masiva en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100716\" style=\"width:710px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-871x1024.jpg 871w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-255x300.jpg 255w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-768x903.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-500x588.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2-800x941.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/MUMMY-MASSPRAYER-2.jpg 1080w\" sizes=\"auto, (max-width: 871px) 100vw, 871px\" \/><\/figure>\n\n<p>El Evangelista James inst\u00f3 al pueblo a orar: \u00abDemonio, dondequiera que est\u00e9s en mi vida, en mi familia &#8211; \u00a1Fuera, en el nombre de Jes\u00fas! Esp\u00edritu familiar, esp\u00edritu ancestral &#8211; \u00a1Fuera, en el nombre de Jes\u00fas!\u00bb.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-886x1024.jpg\" alt=\"Evangelista orando por la congregaci&#xF3;n y los espectadores durante la Oraci&#xF3;n Masiva en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100720\" style=\"width:765px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-886x1024.jpg 886w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-260x300.jpg 260w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-768x887.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-500x578.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER-800x924.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JAMES-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/figure>\n\n<p>A continuaci\u00f3n, el Evangelista Ope or\u00f3: \u00abCada \u00eddolo familiar que opera en tu vida &#8211; \u00a1Fuera!\u00bb<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"923\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-923x1024.jpg\" alt=\"Evangelista orando por la congregaci&#xF3;n y los espectadores durante la Oraci&#xF3;n Masiva en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100724\" style=\"width:753px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-923x1024.jpg 923w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-270x300.jpg 270w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-768x852.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-500x555.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER-800x887.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/OPE-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 923px) 100vw, 923px\" \/><\/figure>\n\n<p>Tomando el mando, el Evangelista Joseph or\u00f3: \u00abEsos esp\u00edritus que te causan aflicci\u00f3n, que te causan dolor, que te causan enfermedad en tus \u00f3rganos &#8211; \u00a1Fuera, en el nombre de Jes\u00fas! Veneno en mi coraz\u00f3n, pulmones, ri\u00f1ones, huesos &#8211; dondequiera que est\u00e9is, o\u00edd la voz de Dios: \u00a1Te ordeno que salgas!\u00bb<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-820x1024.jpg\" alt=\"Evangelista orando por la congregaci&#xF3;n y los espectadores durante la Oraci&#xF3;n Masiva en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100728\" style=\"width:763px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-820x1024.jpg 820w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-240x300.jpg 240w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-768x959.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-500x624.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER-800x999.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/JOSEPH-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n<p>El Evangelista Chisom or\u00f3: \u00abDemonio, no tienes elecci\u00f3n; \u00a1debes someterte! Dondequiera que est\u00e9s, sujet\u00e1ndome en esclavitud, limitaci\u00f3n, desilusi\u00f3n &#8211; te lo ordeno en el nombre de Jes\u00fas: \u00a1Fuera!\u00bb<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"867\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-867x1024.jpg\" alt=\"Evangelista orando por la congregaci&#xF3;n y los espectadores durante la Oraci&#xF3;n Masiva en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100732\" style=\"width:761px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-867x1024.jpg 867w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-254x300.jpg 254w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-768x907.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-500x590.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER-800x944.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/CHISOM-MASSPRAYER.jpg 1080w\" sizes=\"auto, (max-width: 867px) 100vw, 867px\" \/><\/figure>\n\n<p>En un v\u00eddeo de Oraci\u00f3n Masiva, el Profeta T.B. Joshua declar\u00f3: \u00ab\u00a1Vengo contra todo esp\u00edritu que se te oponga! Cada esp\u00edritu que cuestiona tu negocio, carrera, visi\u00f3n, destino &#8211; \u00a1empieza a ceder, en el nombre de Jes\u00fas! A todo esp\u00edritu familiar &#8211; le ordenamos su existencia: \u00a1Fuera! T\u00fa aflicci\u00f3n en la sangre, fluidos, ri\u00f1ones, h\u00edgado, huesos &#8211; \u00a1debes irte, en el nombre de Jes\u00fas!\u00bb El hombre de Dios inst\u00f3 al pueblo a decretar: \u00ab\u00a1Mis finanzas, mis negocios, mi carrera &#8211; sean liberados, en el nombre de Jes\u00fas!\u00bb<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-1024x683.jpg\" alt=\"Profeta T.B. Joshua orando por la congregaci&#xF3;n y los espectadores durante la Oraci&#xF3;n Masiva en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024. \" class=\"wp-image-100736\" style=\"width:726px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-1024x683.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-300x200.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-768x512.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-500x333.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1-800x533.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-MASSPRAYER-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-normal-font-size\" id=\"h-testimonies\"><strong>Testimonios<\/strong><\/h3>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-healed-from-a-paralysing-stroke\">\u00a1SANA DE UNA PAR\u00c1LISIS CEREBRAL!<\/h3>\n\n<p>En 2002, Blessing sufri\u00f3 un ataque espiritual que le provoc\u00f3 un derrame cerebral. Fue trasladada a varios lugares en busca de ayuda. \u00abEn un momento dado, me trasladaron al estado de Ondo\u00bb, declar\u00f3 Blessing el 29 de diciembre de 2024. Al no registrarse mucho progreso, Blessing regres\u00f3 a Lagos. \u00abEl 23 de octubre de 2022, mi marido me llev\u00f3 a La SCOAN para recibir oraci\u00f3n\u00bb, record\u00f3. Esa misma noche, Blessing tuvo un encuentro en sue\u00f1os en el que se le apareci\u00f3 una imagen del Profeta T.B. Joshua. \u00abEl hombre de Dios levant\u00f3 mi mano enferma y me declar\u00f3 sana\u00bb, dijo. Hoy, Blessing ya no tiene la boca torcida por el derrame ni la mano paralizada. \u00abRecurran a Dios para que les d\u00e9 sanidad y liberaci\u00f3n\u00bb, aconseja a las dem\u00e1s personas.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"596\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-1024x596.jpg\" alt=\"Testimonio 1 Compartido en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024\" class=\"wp-image-100780\" style=\"width:764px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-1024x596.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-300x175.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-768x447.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-500x291.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2-800x466.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-4-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-no-longer-a-slave-to-demonic-pain\">\u00a1YA NO ES ESCLAVA DEL DOLOR DEMON\u00cdACO!<\/h3>\n\n<p>Una ma\u00f1ana de hace cinco a\u00f1os, Helen se despert\u00f3 con un dolor insoportable en todo el cuerpo. \u00abDerram\u00e9 l\u00e1grimas y el dolor desapareci\u00f3 misteriosamente\u00bb, dijo el 29 de diciembre de 2024. Dos a\u00f1os despu\u00e9s, sin embargo, el dolor volvi\u00f3. \u00abFui a diferentes hospitales\u00bb, continu\u00f3, \u00aby recib\u00ed sesiones de fisioterapia\u00bb. M\u00e1s tarde tambi\u00e9n le pusieron un cors\u00e9 lumbar. Sin embargo, todas estas ayudas no pudieron ayudarla. <\/p>\n\n<p>\u00abTodos los d\u00edas me despertaba a las cuatro de la ma\u00f1ana a causa del dolor\u00bb, explic\u00f3 Helen. Pero el problema ten\u00eda una dimensi\u00f3n espiritual. \u00abSol\u00eda ver a un hombre que se me acercaba en sue\u00f1os y sufr\u00eda abortos espont\u00e1neos\u00bb, relat\u00f3. Al recibir la oraci\u00f3n el 22 de diciembre, Helen fue testigo de c\u00f3mo el poder del Dios vivo surg\u00eda a trav\u00e9s de ella. \u00abAhora puedo hacer todo lo que antes no pod\u00eda\u00bb, dijo mientras demostraba su libertad. Aconsej\u00f3 a las dem\u00e1s personas que buscaran la ayuda de Dios.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"586\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-1024x586.jpg\" alt=\"Testimonio 2 Compartido en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024\" class=\"wp-image-100776\" style=\"width:734px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-1024x586.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-300x172.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-768x439.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-500x286.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5-800x458.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-1-5.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-an-artisan-regains-his-strength\">\u00a1UN ARTESANO RECUPERA SUS FUERZAS!<\/h3>\n\n<p>Joseph, un alicatador ghan\u00e9s afincado en Nigeria, sinti\u00f3 de repente un fuerte dolor en la espalda. \u00abQued\u00e9 incapacitado y uno de mis trabajadores tuvo que buscar un autob\u00fas para trasladarme\u00bb, relat\u00f3 el 29 de diciembre de 2024. Con su trabajo en suspenso, Joseph no tuvo m\u00e1s remedio que acudir a La SCOAN para recibir oraci\u00f3n. Mientras tanto, se hab\u00eda ministrado a s\u00ed mismo el Agua de Unci\u00f3n. Tras un toque de uno de los Evangelistas, el dolor de espalda de Joseph desapareci\u00f3 al instante. Ahora ha vuelto al trabajo. \u00abSi tan solo pudieras creer, Dios lo har\u00eda por ti\u00bb, aconsej\u00f3.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"541\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-1024x541.jpg\" alt=\"Testimonio 3 Compartido en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024\" class=\"wp-image-100748\" style=\"width:765px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-1024x541.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-300x159.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-768x406.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-500x264.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4-800x423.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-2-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-i-feel-a-sense-of-joy-says-man-delivered-from-evil-spirits\">\u00abSIENTO UN GRAN GOZO\u00bb, DICE UN HOMBRE LIBERADO DE ESP\u00cdRITUS MALIGNOS<\/h3>\n\n<p>Knowledge, zimbabuense, hab\u00eda nacido en una familia que adoraba \u00eddolos. \u00abMis padres heredaron los \u00eddolos de sus propios padres y dec\u00edan que los \u00eddolos estaban destinados a protegernos\u00bb, dijo Knowledge el 29 de diciembre de 2024. Sin embargo, los \u00eddolos no trajeron m\u00e1s que desgracias a la familia, con retrasos en todos los \u00e1mbitos de la vida. Al descubrir Emmanuel TV, Knowledge decidi\u00f3 que ten\u00eda que ir a La SCOAN el 15 de diciembre de 2024. \u00abDespu\u00e9s de un toque, supe que hab\u00eda sido liberado y ahora siento un gran gozo\u00bb, dijo Knowledge. Como consejo, dijo a los congregantes: \u00abJesucristo es la \u00fanica soluci\u00f3n a nuestros problemas\u00bb.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"646\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-1024x646.jpg\" alt=\"Testimonio 4 Compartido en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024\" class=\"wp-image-100752\" style=\"width:740px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-1024x646.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-300x189.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-768x484.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-500x315.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2-800x504.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-3-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-elisa-breaks-free-from-pain\">\u00a1ELISA ES LIBRE DEL DOLOR!<\/h3>\n\n<p>El 22 de diciembre de 2024, Elisa, de Angola, estaba en La SCOAN para recibir oraci\u00f3n. En el instante en que recibi\u00f3 la oraci\u00f3n durante la ministraci\u00f3n de la Pastora Evelyn Joshua, el cuerpo de Elisa comenz\u00f3 a vibrar incontrolablemente, haci\u00e9ndola terminar en el suelo. \u00abDurante 15 a\u00f1os sufr\u00ed fuertes dolores de osteoporosis\u00bb, dijo, \u00aby acud\u00ed a distintos m\u00e9dicos en busca de ayuda\u00bb. Como la enfermedad afectaba su capacidad de caminar, Elisa casi hab\u00eda aceptado el veredicto de los m\u00e9dicos de que no podr\u00eda recibir una sanidad permanente. Sin embargo, dio un paso de fe y pidi\u00f3 ayuda divina. \u00abTras la oraci\u00f3n, recib\u00ed la sanidad y pude moverme libremente y dormir tranquila\u00bb, afirm\u00f3. \u00abBusquen la ayuda de Dios\u00bb, aconsej\u00f3 a las dem\u00e1s personas.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"927\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-1024x927.jpg\" alt=\"Testimonio 5 Compartido en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024\" class=\"wp-image-100756\" style=\"width:770px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-1024x927.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-300x272.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-768x695.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-500x453.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1-800x724.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-5-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-an-end-to-16-years-of-bed-wetting\">\u00a1FIN A 16 A\u00d1OS DE MOJAR LA CAMA!<\/h3>\n\n<p>\u00abMoj\u00e9 la cama hasta los 16 a\u00f1os\u00bb, comenz\u00f3 Gifty, de 18 a\u00f1os, el 29 de diciembre de 2024. Debido a este problema, Gifty no pudo asistir a un internado ni relacionarse con sus compa\u00f1eros en sus d\u00edas de escuela primaria. Cuando finalmente fue descubierta en secundaria, Gifty se convirti\u00f3 en el blanco de las bromas. \u00abIncluso en casa, mis hermanos se burlaban de m\u00ed\u00bb, relat\u00f3. Como soluci\u00f3n, Gifty comenz\u00f3 a usar pa\u00f1ales para adultos. \u00abMe escond\u00eda de mis compa\u00f1eros de la escuela secundaria cuando usaba o tiraba los pa\u00f1ales\u00bb.<\/p>\n\n<p>Para la gloria de Dios, la madre de Gifty visit\u00f3 La SCOAN y le regalaron el adhesivo y el Agua de Unci\u00f3n. \u00abMe ministr\u00e9 el agua antes de acostarme y descubr\u00ed que no hab\u00eda mojado la cama en toda la noche\u00bb, declar\u00f3. Gifty repiti\u00f3 la acci\u00f3n y llam\u00f3 a su madre cuando confirm\u00f3 que Dios la hab\u00eda liberado. Eso ocurri\u00f3 hace dos a\u00f1os, \u00a1y las s\u00e1banas de Gifty han permanecido secas! Ella y su madre glorificaron al Se\u00f1or por su sanidad y animaron a las dem\u00e1s personas a confiar en el Todopoderoso.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"773\" height=\"1024\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-773x1024.jpg\" alt=\"Testimonio 6 Compartido en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024\" class=\"wp-image-100768\" style=\"width:738px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-773x1024.jpg 773w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-227x300.jpg 227w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-768x1017.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-500x662.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6-800x1059.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-6.jpg 1090w\" sizes=\"auto, (max-width: 773px) 100vw, 773px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading has-small-font-size\" id=\"h-addiction-to-hair-pulling-ends-in-praise\">\u00a1LA ADICCI\u00d3N A TIRARSE DEL PELO ACABA EN ALABANZA!<\/h3>\n\n<p>El 28 de julio de 2023, Hope estaba en el Servicio de Agua Viva de La SCOAN. Hab\u00eda estado sufriendo la adicci\u00f3n de tirarse el pelo de la nuca. \u00abNo pod\u00eda dejar de hacerlo, y las personas pod\u00edan identificarme f\u00e1cilmente por ello\u00bb, dijo Hope el 29 de diciembre de 2024. Sus padres hab\u00edan intentado muchas cosas para impedir que Hope continuara con el h\u00e1bito, pero hab\u00edan fracasado rotundamente. En el Servicio de Agua Viva, sin embargo, Hope hab\u00eda orado con ferviente fe en su coraz\u00f3n, y el Se\u00f1or hab\u00eda escuchado su clamor.<\/p>\n\n<p>\u00abDos semanas despu\u00e9s de orar en el altar de La SCOAN, me di cuenta de que hab\u00eda dejado de tirarme el pelo\u00bb, record\u00f3 Hope, con una sonrisa de oreja a oreja. Aconsej\u00f3 a las dem\u00e1s personas que buscaran la ayuda del Se\u00f1or de toda carne. \u00abSea lo que sea lo que busquen hoy, el Se\u00f1or lo har\u00e1 por ustedes\u00bb, asegur\u00f3. Su madre, Stella, a\u00f1adi\u00f3: \u00abOro para que el milagro sea permanente en su vida, en el nombre de Jes\u00fas\u00bb.<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-1024x826.jpg\" alt=\"Testimonio 7 Compartido en el Servicio Dominical de La SCOAN el 29 de diciembre de 2024\" class=\"wp-image-100764\" style=\"width:728px;height:auto\" srcset=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-1024x826.jpg 1024w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-300x242.jpg 300w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-768x619.jpg 768w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-500x403.jpg 500w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1-800x645.jpg 800w, https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/TESTIMONY-7-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A medida que el a\u00f1o se acaba, \u00bfte das cuenta de que es crucial que te revises a ti mismo? Para los presentes en La SCOAN durante el \u00faltimo servicio dominical de 2024, fue el momento de revisar su posici\u00f3n ante Dios y ante sus semejantes. Este examen de conciencia comenz\u00f3 con una sesi\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":100801,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[1952],"tags":[2001,1991,1062,1995,1992,1070,2085,1998,2087,1158,2086,1072,1999],"class_list":["post-103656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicio-dominical-de-la-scoan","tag-coro","tag-emmanuel-tv-es","tag-liberacion","tag-liberacion-es","tag-pastora-evelyn-joshua-es","tag-sanidad","tag-scoan-es","tag-sermon-es","tag-sinagoga-iglesia-de-todas-las-naciones-es","tag-sinagoga-iglesia-de-todas-las-naciones","tag-t-b-joshua-es","tag-testimonio","tag-testimonio-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXAM\u00cdNATE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua<\/title>\n<meta name=\"description\" content=\"EXAM\u00cdNATE A lo largo de los a\u00f1os invitamos a los miembros de nuestra familia de la iglesia a reflexionar sobre temas como lo que Dios est\u00e1 ense\u00f1ando...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scoan.org\/es\/examinate\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXAM\u00cdNATE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"og:description\" content=\"EXAM\u00cdNATE A lo largo de los a\u00f1os invitamos a los miembros de nuestra familia de la iglesia a reflexionar sobre temas como lo que Dios est\u00e1 ense\u00f1ando...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scoan.org\/es\/examinate\/\" \/>\n<meta property=\"og:site_name\" content=\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tbjministries\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-31T17:04:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T17:05:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"v3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:site\" content=\"@SCOANTBJoshua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"v3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/\"},\"author\":{\"name\":\"v3\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/9407e2a1d1e2a15ac63326fe09b7d3b6\"},\"headline\":\"EXAM\u00cdNATE\",\"datePublished\":\"2024-12-31T17:04:07+00:00\",\"dateModified\":\"2025-02-19T17:05:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/\"},\"wordCount\":2533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"keywords\":[\"Coro\",\"Emmanuel TV\",\"liberaci\u00f3n\",\"Liberaci\u00f3n\",\"Pastora Evelyn Joshua\",\"sanidad\",\"SCOAN\",\"Serm\u00f3n\",\"sinagoga iglesia de todas las naciones\",\"Sinagoga Iglesia de Todas las Naciones\",\"T.B. Joshua\",\"testimonio\",\"Testimonio\"],\"articleSection\":[\"Servicio Dominical de La SCOAN\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/\",\"name\":\"EXAM\u00cdNATE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"datePublished\":\"2024-12-31T17:04:07+00:00\",\"dateModified\":\"2025-02-19T17:05:34+00:00\",\"description\":\"EXAM\u00cdNATE A lo largo de los a\u00f1os invitamos a los miembros de nuestra familia de la iglesia a reflexionar sobre temas como lo que Dios est\u00e1 ense\u00f1ando...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2024\\\/12\\\/DADDY-1-1.jpg\",\"width\":1080,\"height\":704,\"caption\":\"Prophet TB Joshua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/examinate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXAM\u00cdNATE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"description\":\"Founded by Prophet TB Joshua\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#organization\",\"name\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"contentUrl\":\"https:\\\/\\\/www.scoan.org\\\/wp-content\\\/blogs.dir\\\/12\\\/files\\\/2016\\\/08\\\/logo-e1711044614299.png\",\"width\":186,\"height\":85,\"caption\":\"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tbjministries\",\"https:\\\/\\\/x.com\\\/SCOANTBJoshua\",\"https:\\\/\\\/www.instagram.com\\\/tbjoshua\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/#\\\/schema\\\/person\\\/9407e2a1d1e2a15ac63326fe09b7d3b6\",\"name\":\"v3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g\",\"caption\":\"v3\"},\"url\":\"https:\\\/\\\/www.scoan.org\\\/es\\\/author\\\/v3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXAM\u00cdNATE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"EXAM\u00cdNATE A lo largo de los a\u00f1os invitamos a los miembros de nuestra familia de la iglesia a reflexionar sobre temas como lo que Dios est\u00e1 ense\u00f1ando...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scoan.org\/es\/examinate\/","og_locale":"es_ES","og_type":"article","og_title":"EXAM\u00cdNATE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","og_description":"EXAM\u00cdNATE A lo largo de los a\u00f1os invitamos a los miembros de nuestra familia de la iglesia a reflexionar sobre temas como lo que Dios est\u00e1 ense\u00f1ando...","og_url":"https:\/\/www.scoan.org\/es\/examinate\/","og_site_name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","article_publisher":"https:\/\/www.facebook.com\/tbjministries","article_published_time":"2024-12-31T17:04:07+00:00","article_modified_time":"2025-02-19T17:05:34+00:00","og_image":[{"width":1080,"height":704,"url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","type":"image\/jpeg"}],"author":"v3","twitter_card":"summary_large_image","twitter_creator":"@SCOANTBJoshua","twitter_site":"@SCOANTBJoshua","twitter_misc":{"Escrito por":"v3","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scoan.org\/es\/examinate\/#article","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/examinate\/"},"author":{"name":"v3","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/9407e2a1d1e2a15ac63326fe09b7d3b6"},"headline":"EXAM\u00cdNATE","datePublished":"2024-12-31T17:04:07+00:00","dateModified":"2025-02-19T17:05:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scoan.org\/es\/examinate\/"},"wordCount":2533,"commentCount":0,"publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"image":{"@id":"https:\/\/www.scoan.org\/es\/examinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","keywords":["Coro","Emmanuel TV","liberaci\u00f3n","Liberaci\u00f3n","Pastora Evelyn Joshua","sanidad","SCOAN","Serm\u00f3n","sinagoga iglesia de todas las naciones","Sinagoga Iglesia de Todas las Naciones","T.B. Joshua","testimonio","Testimonio"],"articleSection":["Servicio Dominical de La SCOAN"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scoan.org\/es\/examinate\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scoan.org\/es\/examinate\/","url":"https:\/\/www.scoan.org\/es\/examinate\/","name":"EXAM\u00cdNATE - The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","isPartOf":{"@id":"https:\/\/www.scoan.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scoan.org\/es\/examinate\/#primaryimage"},"image":{"@id":"https:\/\/www.scoan.org\/es\/examinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","datePublished":"2024-12-31T17:04:07+00:00","dateModified":"2025-02-19T17:05:34+00:00","description":"EXAM\u00cdNATE A lo largo de los a\u00f1os invitamos a los miembros de nuestra familia de la iglesia a reflexionar sobre temas como lo que Dios est\u00e1 ense\u00f1ando...","breadcrumb":{"@id":"https:\/\/www.scoan.org\/es\/examinate\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scoan.org\/es\/examinate\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/examinate\/#primaryimage","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2024\/12\/DADDY-1-1.jpg","width":1080,"height":704,"caption":"Prophet TB Joshua"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scoan.org\/es\/examinate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scoan.org\/es\/"},{"@type":"ListItem","position":2,"name":"EXAM\u00cdNATE"}]},{"@type":"WebSite","@id":"https:\/\/www.scoan.org\/es\/#website","url":"https:\/\/www.scoan.org\/es\/","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","description":"Founded by Prophet TB Joshua","publisher":{"@id":"https:\/\/www.scoan.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scoan.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scoan.org\/es\/#organization","name":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua","url":"https:\/\/www.scoan.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","contentUrl":"https:\/\/www.scoan.org\/wp-content\/blogs.dir\/12\/files\/2016\/08\/logo-e1711044614299.png","width":186,"height":85,"caption":"The Synagogue, Church Of All Nations - SCOAN - Prophet T.B. Joshua"},"image":{"@id":"https:\/\/www.scoan.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tbjministries","https:\/\/x.com\/SCOANTBJoshua","https:\/\/www.instagram.com\/tbjoshua"]},{"@type":"Person","@id":"https:\/\/www.scoan.org\/es\/#\/schema\/person\/9407e2a1d1e2a15ac63326fe09b7d3b6","name":"v3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3cde603877c2fdfd674408ddea061b7f9a11636efd9a4b2b28829dd498f526c4?s=96&d=mm&r=g","caption":"v3"},"url":"https:\/\/www.scoan.org\/es\/author\/v3\/"}]}},"_links":{"self":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/103656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/comments?post=103656"}],"version-history":[{"count":1,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/103656\/revisions"}],"predecessor-version":[{"id":103657,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/posts\/103656\/revisions\/103657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media\/100801"}],"wp:attachment":[{"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/media?parent=103656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/categories?post=103656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scoan.org\/es\/wp-json\/wp\/v2\/tags?post=103656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}